{"id":13284,"date":"2020-04-22T09:48:01","date_gmt":"2020-04-22T13:48:01","guid":{"rendered":"https:\/\/cpa.ca\/cpa-ccppp-acpro-statements-regarding-covid-19\/"},"modified":"2020-06-09T11:03:05","modified_gmt":"2020-06-09T15:03:05","slug":"cpa-ccppp-acpro-statements-regarding-covid-19","status":"publish","type":"post","link":"https:\/\/cpa.ca\/fr\/cpa-ccppp-acpro-statements-regarding-covid-19\/","title":{"rendered":"D\u00e9clarations CPA-CCPPP-ACPRO concernant COVID-19"},"content":{"rendered":"\n<p>Au nom de l\u2019Association des organisations canadiennes de r\u00e9glementation en psychologie (AOCRP), du Conseil canadien des programmes de psychologie professionnelle (CCPPP) et du jury d\u2019agr\u00e9ment de la Soci\u00e9t\u00e9 canadienne de psychologie (SCP) :<\/p>\n<p>La pand\u00e9mie mondiale de la COVID-19 a des effets sans pr\u00e9c\u00e9dent sur les individus, les collectivit\u00e9s, les syst\u00e8mes de sant\u00e9 et les professionnels de la sant\u00e9. Nous \u2013 l\u2019AOCRP, le CCPPP et le jury d\u2019agr\u00e9ment de la SCP \u2013 savons aussi que la pand\u00e9mie a eu et continue d\u2019avoir des effets consid\u00e9rables sur le fonctionnement des programmes de formation de psychologie professionnelle et sur leurs enseignants, leur personnel et leurs \u00e9tudiants. <\/p>\n<p>Vous trouverez ci-joint une d\u00e9claration de l\u2019AOCRP exprimant sa r\u00e9ponse aux inqui\u00e9tudes associ\u00e9es \u00e0 l\u2019autorisation d\u2019exercer la profession de psychologue dans le contexte de la pand\u00e9mie, ainsi qu\u2019une d\u00e9claration du CCPPP et du jury d\u2019agr\u00e9ment de la SCP concernant les inqui\u00e9tudes suscit\u00e9es en mati\u00e8re d\u2019agr\u00e9ment et de formation. Nos organismes \u2013 et c\u2019est ce que nous voulons communiquer par ces d\u00e9clarations \u2013 ont la volont\u00e9 d\u2019att\u00e9nuer, dans toute la mesure du possible, les perturbations que la pand\u00e9mie entra\u00eene pour la formation des \u00e9tudiants, pour le fonctionnement des programmes, et en fin de compte, pour la disponibilit\u00e9 de professionnels comp\u00e9tents r\u00e9pondant aux besoins du public en mati\u00e8re de services de sant\u00e9 mentale dans la conjoncture actuelle; en m\u00eame temps, nous devons maintenir l\u2019int\u00e9grit\u00e9 absolue de nos d\u00e9marches en mati\u00e8re de formation, d\u2019autorisation d\u2019exercer la profession, et d\u2019agr\u00e9ment. Nous voulons \u00e9galement faire savoir \u00e0 nos parties prenantes que nous nous engageons \u00e0 garder le dialogue ouvert entre nos organismes tant que la situation continuera d\u2019\u00e9voluer. Soyez certains que nous continuerons d\u2019\u00eatre \u00e0 l\u2019\u00e9coute de vos besoins.<\/p> \n<p>Si vous avez des questions sur le contenu de ces d\u00e9clarations, n\u2019h\u00e9sitez pas \u00e0 communiquer avec nous aux adresses ci-dessous.<\/p>\n\n<p>Bonne sant\u00e9 \u00e0 tous,<br>\n<p>Sara Hagstrom, pr\u00e9sidente, CCPPP, <a href=\"mailto:hagstros@tbh.net\">hagstros@tbh.net<\/a><br>\n\tCatherine Costigan, CCPPP, <a href=\"mailto:costigan@uvic.ca\">costigan@uvic.ca<\/a><br>\n\tKaren Messer-Engel, pr\u00e9sidente, ACPRO, <a href=\"mailto:registrar.skcp@sasktel.net\">registrar.skcp@sasktel.net<\/a><br>\n\tStewart Madon, registraire \u00e0 l\u2019agr\u00e9ment, CPA, <a href=\"mailto:smadon@cpa.ca\">smadon@cpa.ca<\/a><\/p>\n\n\n<h4><a target=\"_blank\" href=\"https:\/\/cpa.ca\/docs\/File\/Accreditation\/CCPPP%20CPA%20ACPRO%20Declarations%20COVID-19.pdf\" rel=\"noopener noreferrer\">CCPPP CPA ACPRO D\u00e9clarations COVID-19.pdf<\/a><\/h4>\n","protected":false},"excerpt":{"rendered":"<p>We, ACPRO, CCPPP, and the CPA Accreditation Panel recognize that this pandemic has had, and continues to have, a significant impact on the operation of professional psychology training programmes, and on their faculty, staff, and students&#8230;<\/p>\n<p style=\"font-weight:bold; font-style:italic\"><a target=\"_blank\" href=\"\/docs\/File\/Accreditation\/CCPPP CPA ACPRO Statements COVID-19.pdf\" rel=\"noopener noreferrer\">CCPPP CPA ACPRO Statements COVID-19.pdf<\/a><\/p>\n<hr \/>\n","protected":false},"author":2,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[160,118,134],"tags":[],"class_list":["post-13284","post","type-post","status-publish","format-standard","hentry","category-accreditation-covidfr","category-covid19membersfr","category-statements-fr"],"acf":[],"aioseo_notices":[],"publishpress_future_action":{"enabled":false,"date":"2026-06-24 09:53:39","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/cpa.ca\/fr\/wp-json\/wp\/v2\/posts\/13284","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cpa.ca\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/cpa.ca\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/cpa.ca\/fr\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/cpa.ca\/fr\/wp-json\/wp\/v2\/comments?post=13284"}],"version-history":[{"count":5,"href":"https:\/\/cpa.ca\/fr\/wp-json\/wp\/v2\/posts\/13284\/revisions"}],"predecessor-version":[{"id":14661,"href":"https:\/\/cpa.ca\/fr\/wp-json\/wp\/v2\/posts\/13284\/revisions\/14661"}],"wp:attachment":[{"href":"https:\/\/cpa.ca\/fr\/wp-json\/wp\/v2\/media?parent=13284"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/cpa.ca\/fr\/wp-json\/wp\/v2\/categories?post=13284"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/cpa.ca\/fr\/wp-json\/wp\/v2\/tags?post=13284"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}