{"id":28033,"date":"2022-02-25T00:01:59","date_gmt":"2022-02-25T05:01:59","guid":{"rendered":"https:\/\/cpa.ca\/?p=28033"},"modified":"2022-05-05T13:54:48","modified_gmt":"2022-05-05T17:54:48","slug":"psychology-month-profile-dr-lindsay-mccunn-and-dr-john-zelenski-environmental-psychology","status":"publish","type":"post","link":"https:\/\/cpa.ca\/fr\/psychology-month-profile-dr-lindsay-mccunn-and-dr-john-zelenski-environmental-psychology\/","title":{"rendered":"Profils du Mois de la psychologie : Dre Lindsay McCunn et Dr John Zelenski, <em>Environmental Psychology<\/em>"},"content":{"rendered":"<div style=\"text-align: left;\">\n<p><a id=\"Environmental\" class=\"anchor\" name=\"Environmental\"><\/a><\/p>\n<div style=\"min-height: 130px;\">\n<div class=\"textwrapleft\"><img decoding=\"async\" class=\"textwrapleft\" style=\"max-height: 150px;\" src=\"https:\/\/cpa.ca\/docs\/File\/Psychology Month\/Lindsay McCunn.jpg\" alt=\"Dre Lindsay McCunn\" \/><br \/>\n<span style=\"color: gray; font-size: 12px; line-height: 9px;\"><em>Dre Lindsay McCunn<\/em><\/span><\/div>\n<div class=\"textwrapright\"><img decoding=\"async\" class=\"textwrapleft\" style=\"max-height: 150px;\" src=\"https:\/\/cpa.ca\/docs\/File\/Psychology Month\/John Zelenski.jpg\" alt=\"Dr John Zelenski\" \/><br \/>\n<span style=\"color: gray; font-size: 12px; line-height: 9px;\"><em>Dr. John Zelenski<\/em><\/span><\/div>\n<p><strong>Dre Lindsay McCunn et Dr John Zelenski, <em>Environmental Psychology<\/em><\/strong><br \/>\nLa psychologie de l\u2019environnement compte deux branches principales. Nous avons parl\u00e9 \u00e0 la Dre Lindsay McCunn de la branche de la psychologie de l\u2019architecture (la conception de b\u00e2timents et de pi\u00e8ces pour le bien-\u00eatre des occupants) et au Dr John Zelenski, de la psychologie \u00e9cologique (qui s\u2019int\u00e9resse aux comportements \u00e9cologiquement durables par l\u2019interm\u00e9diaire de la connexion des gens \u00e0 la nature).<\/p>\n<\/div>\n<div id=\"accordions-28025\" class=\"accordions-28025 accordions\" data-accordions={&quot;lazyLoad&quot;:true,&quot;id&quot;:&quot;28025&quot;,&quot;event&quot;:&quot;click&quot;,&quot;collapsible&quot;:&quot;true&quot;,&quot;heightStyle&quot;:&quot;content&quot;,&quot;animateStyle&quot;:&quot;swing&quot;,&quot;animateDelay&quot;:1000,&quot;navigation&quot;:true,&quot;active&quot;:999,&quot;expandedOther&quot;:&quot;no&quot;}>\r\n                <div id=\"accordions-lazy-28025\" class=\"accordions-lazy\" accordionsId=\"28025\">\r\n                    <\/div>\r\n\r\n    <div class=\"items\"  style=\"display:none\" >\r\n    \r\n            <div post_id=\"28025\" itemcount=\"0\"  header_id=\"header-1580324481504\" id=\"header-1580324481504\" style=\"\" class=\"accordions-head head1580324481504 border-none\" toggle-text=\"\" main-text=\"\u00c0 propos de  Dre Lindsay McCunn et Dr John Zelenski\">\r\n                                    <span id=\"accordion-icons-1580324481504\" class=\"accordion-icons\">\r\n                        <span class=\"accordion-icon-active accordion-plus\"><i class=\"fa fas fa-chevron-up\"><\/i><\/span>\r\n                        <span class=\"accordion-icon-inactive accordion-minus\"><i class=\"fa fas fa-chevron-down\"><\/i><\/span>\r\n                    <\/span>\r\n                    <span id=\"header-text-1580324481504\" class=\"accordions-head-title\">\u00c0 propos de  Dre Lindsay McCunn et Dr John Zelenski<\/span>\r\n                            <\/div>\r\n            <div class=\"accordion-content content1580324481504 \">\r\n                <p><strong><a href=\"https:\/\/cpa.ca\/fr\/sections\/environmentalpsychology\/\">Psychologie de l\u2019environnement <\/a><\/strong><\/p>\n<p>\u00ab\u00a0Quand je dis que je ne vous juge pas, je pense que je veux vraiment dire \u201cpas plus que les autres.\u201d\u00a0\u00bb.<\/p>\n<p>Je suis un peu nerveux \u00e0 l\u2019id\u00e9e que, pendant notre r\u00e9union Zoom, la Dre\u00a0Lindsay McCunn et le Dr\u00a0John Zelenski puissent juger mon arri\u00e8re-plan, d\u00e9cid\u00e9ment tr\u00e8s encombr\u00e9. Tous mes appareils \u00e9lectrom\u00e9nagers sont plac\u00e9s sur une tablette derri\u00e8re moi, ce qui donne l\u2019impression (exacte, il se trouve) que mon bureau \u00e0 domicile est un coin exigu pr\u00e8s de la cuisine. La Dre\u00a0McCunn et le Dr\u00a0Zelenski sont des psychologues de l\u2019environnement, c\u2019est-\u00e0-dire des sp\u00e9cialistes des espaces que nous occupons et de la mani\u00e8re dont nous interagissons avec eux. Le Dr\u00a0Zelenski est plut\u00f4t gentil et honn\u00eate \u2013 en tant qu\u2019\u00eatres humains, nous percevons des indices subtils, \u00e0 partir des espaces de chacun, mais cela n\u2019est probablement pas propre aux psychologues de l\u2019environnement. Nous jugeons tous les arri\u00e8re-plans Zoom, ne serait-ce qu\u2019un peu.<\/p>\n<p>La Dre\u00a0Lindsay McCunn est professeure de psychologie \u00e0 l\u2019Universit\u00e9 Vancouver Island. Elle est la pr\u00e9sidente de la Section de psychologie de l\u2019environnement de la SCP et la r\u00e9dactrice en chef adjointe du Journal of Environmental Psychology. Selon elle, les arri\u00e8re-plans Zoom des gens ou la fa\u00e7on dont ils am\u00e9nagent leurs jardins ou leurs espaces de vie sont sources de curiosit\u00e9 pour chacun d\u2019entre nous.<\/p>\n<p>\u00ab\u00a0La fa\u00e7on dont les gens s\u2019expriment, organisent leur domicile et placent des objets importants est vraiment int\u00e9ressante. Sam Gosling a \u00e9crit un livre intitul\u00e9 Snoopologie; il s\u2019agit d\u2019une \u00e9tude portant sur la fa\u00e7on dont on peut d\u00e9duire la personnalit\u00e9 et la fa\u00e7on de penser des gens en fonction de la mani\u00e8re dont ils rangent leurs bibelots et leurs affaires dans leur maison et leur bureau.\u00a0\u00bb<\/p>\n<p>La Dre\u00a0McCunn se sp\u00e9cialise en psychologie de l\u2019environnement et d\u00e9crit ainsi sa sp\u00e9cialit\u00e9.<\/p>\n<p>\u00ab\u00a0La psychologie de l\u2019environnement, c\u2019est l\u2019\u00e9tude des transactions entre les personnes et les lieux. Et j\u2019entends par l\u00e0 beaucoup de types d\u2019endroits \u2013 un caf\u00e9, un bureau, une \u00e9cole, un parc, un oc\u00e9an, une montagne. Nous \u00e9tudions les diff\u00e9rentes fa\u00e7ons dont les gens interagissent avec leur environnement. De la m\u00eame mani\u00e8re qu\u2019un psychologue social \u00e9tudie et analyse les relations et les interactions entre les individus et les autres, les psychologues de l\u2019environnement \u00e9tudient et analysent les relations entre les personnes et les lieux. Dans mes recherches, je m\u2019int\u00e9resse \u00e0 la fa\u00e7on dont les gens interagissent dans les collectivit\u00e9s et les milieux de travail, en particulier dans les h\u00f4pitaux, les \u00e9coles et les bureaux. \u00c0 ce titre, je me penche sur le personnel, principalement, et sur les personnes qui utilisent les environnements d\u2019une mani\u00e8re diff\u00e9rente de celle \u00e0 laquelle on pourrait s\u2019attendre, comme les \u00e9tudiants et les patients, les enseignants, etc.\u00a0\u00bb.<\/p>\n<p>Le Dr\u00a0John Zelenski est professeur au d\u00e9partement de psychologie de l\u2019Universit\u00e9 Carleton. Il est \u00e9galement un psychologue de l\u2019environnement, mais il se sp\u00e9cialise dans un domaine bien diff\u00e9rent de celui de la Dre\u00a0McCunn. On pourrait dire que l\u2019un et l\u2019autre repr\u00e9sentent les deux principales branches de la psychologie de l\u2019environnement \u2013 la psychologie de l\u2019architecture (Dre\u00a0McCunn) et la psychologie de l\u2019\u00e9cologie (Dr\u00a0Zelenski).<\/p>\n<p>\u00ab\u00a0En plus d\u2019\u00eatre un psychologue de l\u2019environnement, je me consid\u00e8re aussi comme un psychologue de la personnalit\u00e9 qui se r\u00e9clame de la psychologie positive. Je me suis beaucoup int\u00e9ress\u00e9 \u00e0 ce que nous appelons le rapport \u00e0 la nature, ou ce que d\u2019autres appellent \u201cla connexion avec la nature\u201d. Je parle ici des impressions subjectives des gens\u00a0: font-ils partie de la nature ou la nature est-elle distincte d\u2019eux et n\u2019a pas grand-chose \u00e0 voir avec leur perception d\u2019eux-m\u00eames? Je me suis aussi beaucoup int\u00e9ress\u00e9 de fa\u00e7on g\u00e9n\u00e9rale par ce que j\u2019appelle un \u201cchemin heureux vers la durabilit\u00e9\u201d. C\u2019est l\u2019id\u00e9e que nous savons que la nature est capable de rendre les gens de bonne humeur. La nature est associ\u00e9e au bonheur, tant sur de longues p\u00e9riodes que sur le moment. Nous savons que les gens qui passent beaucoup de temps dans la nature et qui se sentent tr\u00e8s li\u00e9s \u00e0 la nature adoptent des comportements proenvironnement et \u00e9cologiquement durables. Au cours des derni\u00e8res ann\u00e9es, nous avons commenc\u00e9 \u00e0 penser que l\u2019inverse est peut-\u00eatre vrai aussi. Si l\u2019on peut amener les gens \u00e0 faire quelques petits gestes pour la nature, en adoptant des comportements \u00e9cologiquement durables, il serait possible de se servir de cela pour qu\u2019ils se sentent plus proches de la nature et plus heureux de pratiquer ces activit\u00e9s. Nous pensons que les actions en faveur de l\u2019environnement ne doivent pas n\u00e9cessairement \u00eatre on\u00e9reuses et que nous pouvons les associer \u00e0 des \u00e9motions positives.\u00a0\u00bb<\/p>\n<p>Ce que \u00ab\u00a0consacrer du temps dans la nature\u00a0\u00bb signifie pour chaque personne est subjectif. Il s\u2019agit peut-\u00eatre de prendre un week-end pour faire de la randonn\u00e9e dans les collines, de passer une journ\u00e9e \u00e0 p\u00eacher sur la glace ou simplement d\u2019aller dans son jardin et s\u2019occuper de son potager de radis. Pour la Dre\u00a0McCunn, cela a entra\u00een\u00e9 de grands changements depuis le d\u00e9but de la pand\u00e9mie de COVID-19. Elle nous parle par Zoom dans ce qui semble \u00eatre un chalet dans les bois. Depuis quelques ann\u00e9es, elle et sa famille vivaient dans le centre-ville de Nanaimo, en Colombie-Britannique, en face du service d\u2019ambulance, du service de police et de la caserne de pompiers. Les sir\u00e8nes ont augment\u00e9 consid\u00e9rablement lorsque la pand\u00e9mie a commenc\u00e9, leurs habitudes de sommeil ont commenc\u00e9 \u00e0 en \u00eatre affect\u00e9es et ils ont d\u00e9cid\u00e9 de louer un endroit \u00e0 la campagne.<\/p>\n<p>\u00ab\u00a0Ce fut en quelque sorte une bonne \u00e9tude de cas en psychologie de l\u2019environnement, dans la mesure o\u00f9 nous pouvions r\u00e9aliser ce qui nous stimulait dans notre environnement familial, puis d\u00e9cider comment le modifier pour notre sant\u00e9 mentale. Nous avons donc pens\u00e9 \u00e0 d\u00e9m\u00e9nager dans un cadre naturel plus vaste o\u00f9 nous pourrions avoir un peu plus de contr\u00f4le sur les choses qui nous stimulent. Nous avons \u00e9t\u00e9 tr\u00e8s chanceux de pouvoir louer quelque chose \u00e0 la campagne. C\u2019\u00e9tait int\u00e9ressant, parce que j\u2019\u00e9tais tr\u00e8s attach\u00e9e \u00e0 la maison que nous poss\u00e9dions. L\u2019une des choses que nous \u00e9tudions, comme psychologues de l\u2019environnement, est le \u201csentiment d\u2019appartenance\u201d ou un sentiment d\u2019appartenance \u00e0 un lieu, un sentiment identitaire ou un sentiment de d\u00e9pendance. Au d\u00e9but de la pand\u00e9mie, j\u2019ai entendu beaucoup de questions sur la fa\u00e7on dont les gens faisaient face au sentiment de perte qu\u2019ils ressentaient depuis qu\u2019ils travaillaient \u00e0 domicile. Pas seulement un sentiment de perte en rapport avec des \u00e9l\u00e9ments sociaux, mais aussi une perte des moyens habituels par lesquels ils se rendaient \u00e0 leur lieu de travail. Peut-\u00eatre prenaient-ils le m\u00eame autobus tous les jours ou arr\u00eataient-ils au m\u00eame caf\u00e9 lorsqu\u2019ils se rendaient \u00e0 l\u2019\u00e9cole ou au travail. M\u00eame le caract\u00e8re physique de l\u2019environnement de bureau ou de la salle de classe elle-m\u00eame \u2013 cet environnement leur manquait. Je me suis donc demand\u00e9 comment je r\u00e9agirais lorsque je m\u2019\u00e9loignerais de mon environnement familier auquel je m\u2019\u00e9tais vraiment attach\u00e9. Je ne voulais pas me mettre dans une position o\u00f9 je perdrais mon lien avec mon cadre habituel, mais je me suis rapidement attach\u00e9e \u00e0 cet endroit et aux caract\u00e9ristiques naturelles qui l\u2019entourent. Ce fut une belle aventure d\u2019explorer la psychologie de l\u2019environnement de l\u2019int\u00e9rieur et dans ce contexte.\u00a0\u00bb<\/p>\n<p>Se sentir proche de la nature, ce peut \u00eatre aussi simple que de pouvoir sortir et toucher \u00e0 un arbre, ou regarder par la fen\u00eatre une montagne ou une vari\u00e9t\u00e9 d\u2019esp\u00e8ces d\u2019oiseaux. Alors, comment cela peut-il se traduire par des comportements plus respectueux de l\u2019environnement, au moment o\u00f9 le changement climatique est devenu le probl\u00e8me le plus urgent de notre \u00e9poque? Le Dr\u00a0Zelenski donne l\u2019exemple que voici.<\/p>\n<p>\u00ab\u00a0Nous avons beaucoup de bonnes preuves circonstancielles et d\u2019\u00e9tudes de laboratoire, et nous essayons de les assembler. Quelques programmes ont \u00e9t\u00e9 prometteurs! Mon ancienne \u00e9tudiante, amie et collaboratrice, Lisa Nisbet, a collabor\u00e9 avec la Fondation David Suzuki pour relever le D\u00e9fi nature\u00a030\u00d730. Ce d\u00e9fi consiste \u00e0 consacrer 30\u00a0minutes dans la nature chaque jour pendant 30\u00a0jours. Les personnes qui s\u2019inscrivent \u00e0 ce d\u00e9fi ont tendance \u00e0 \u00eatre plut\u00f4t \u00e9cologistes et d\u00e9j\u00e0 tr\u00e8s proches de la nature. Mais au cours de ce mois, cette connexion semble se d\u00e9velopper. Ce n\u2019est pas un essai contr\u00f4l\u00e9 randomis\u00e9, mais il semble que le fait de passer du temps dans la nature donne \u00e0 ces personnes le sentiment d\u2019\u00eatre plus proches, ce qui les incite \u00e0 adopter des comportements \u00e9cologiquement durables.\u00a0\u00bb<\/p>\n<p>L\u2019\u00e9cologie est une division de la psychologie de l\u2019environnement (relativement) nouvelle, et elle a sans aucun doute pris beaucoup d\u2019ampleur au cours des 20\u00a0derni\u00e8res ann\u00e9es, les changements climatiques \u00e9tant rapidement devenus un sujet de premier plan pour beaucoup d\u2019entre nous. Le Dr\u00a0Zelenski n\u2019est pas le seul \u00e0 avoir \u00e9volu\u00e9 dans cette direction.<\/p>\n<p>\u00ab\u00a0L\u2019attention et l\u2019importance accord\u00e9es \u00e0 l\u2019aspect \u00e9cologique de la psychologie de l\u2019environnement semblent s\u2019\u00eatre accrues au cours des 10\u00a0ou 15\u00a0derni\u00e8res ann\u00e9es. Je suis venu \u00e0 la psychologie \u00e9cologique apr\u00e8s mon doctorat, par simple int\u00e9r\u00eat personnel, et j\u2019ai l\u2019impression d\u2019\u00eatre l\u2019un des millions de personnes qui ont suivi le mouvement, et ce, pour plusieurs raisons. Les gens semblent de plus en plus manifester des sympt\u00f4mes de d\u00e9pression, d\u2019anxi\u00e9t\u00e9, etc., et la nature semble offrir un r\u00e9pit agr\u00e9able. De plus, la prise de conscience relative aux changements climatiques ne cesse de cro\u00eetre, car nous en voyons de plus en plus les effets. Et les d\u00e9cideurs politiques souhaitent savoir ce que les sciences sociales peuvent apporter pour r\u00e9soudre ces probl\u00e8mes.\u00a0\u00bb<\/p>\n<p>La dimension \u00e9cologique de la discipline a \u00e9man\u00e9 naturellement de la branche traditionnelle de la psychologie de l\u2019architecture, qui existe depuis les ann\u00e9es\u00a01960. Selon la Dre\u00a0McCunn, il existe quelques programmes d\u2019\u00e9tudes sup\u00e9rieures officiels en \u00ab\u00a0psychologie de l\u2019environnement\u00a0\u00bb au Canada, mais il y en a plus en Angleterre et aux \u00c9tats-Unis, aux Pays-Bas et en Am\u00e9rique du Sud. Donc, lorsqu\u2019elle dit aux gens qu\u2019elle est une \u00ab\u00a0psychologue de l\u2019environnement\u00a0\u00bb, ceux-ci savent souvent ce qu\u2019elle veut dire.<\/p>\n<p>\u00ab\u00a0Certaines personnes, \u00e0 juste titre, divisent la dimension de la psychologie de l\u2019architecture et la dimension de la psychologie de l\u2019\u00e9cologie. Je le fais aussi si je veux expliquer aux gens ce que j\u2019\u00e9tudie, parce que je suis plut\u00f4t du c\u00f4t\u00e9 de l\u2019architecture. Je travaille avec des ing\u00e9nieurs, des gestionnaires d\u2019installations et des urbanistes, mais j\u2019ai aussi des coll\u00e8gues, comme John, qui s\u2019int\u00e9ressent au lien avec la nature et travaillent avec des personnes qui \u00e9tudient les attitudes et les comportements proenvironnement. L\u2019id\u00e9e de conservation de la nature est devenue tr\u00e8s populaire dans le domaine de la psychologie de l\u2019environnement, sans pour autant prendre le pas sur la dimension architecturale, qui s\u2019int\u00e9resse \u00e0 l\u2019infrastructure des immeubles, etc. En fait, la psychologie de l\u2019environnement a d\u00e9but\u00e9 dans le contexte de l\u2019architecture, mais elle s\u2019est largement \u00e9tendue \u00e0 son autre volet, qui consiste \u00e0 poser aux gens des questions sur leur conscience \u00e9cologique et leur rapport \u00e0 la nature.\u00a0\u00bb<\/p>\n<p>Les deux branches vont de pair. Pensez \u00e0 la tendance \u00e0 construire des b\u00e2timents \u00ab\u00a0verts\u00a0\u00bb, avec du chauffage \u00e0 faible consommation d\u2019\u00e9nergie, des panneaux solaires, voire un jardin sur le toit.<\/p>\n<p>Selon la Dre\u00a0McCunn, \u00ab\u00a0Quand un ing\u00e9nieur me demande\u00a0: \u201cdevrions-nous concevoir ce b\u00e2timent en tenant compte de la durabilit\u00e9\u201d, il veut en r\u00e9alit\u00e9 savoir \u2013 \u201cles gens vont-ils le remarquer? S\u2019en soucient-ils? Vont-ils apporter des changements \u00e0 leurs comportements \u00e0 l\u2019int\u00e9rieur (et \u00e0 l\u2019ext\u00e9rieur) de l\u2019immeuble pour cette raison?\u201d Je peux les aider \u00e0 \u00e9tudier la mani\u00e8re dont les gens se comportent, travaillent et fonctionnent dans des b\u00e2timents plus (ou moins) durables. J\u2019ai fait une \u00e9tude dans une \u00e9cole d\u2019\u00e9tudes sup\u00e9rieures qui a montr\u00e9 que le fait qu\u2019un immeuble de bureaux soit \u201cvert\u201d ou durable ne signifie pas n\u00e9cessairement que cela permettra de pr\u00e9dire une forte productivit\u00e9 ou une forte satisfaction. Il est important de garder un \u0153il critique sur ce que l\u2019on attend d\u2019une conception durable et sur ce que l\u2019on n\u2019attend pas.\u00a0\u00bb<\/p>\n<p>Pensez \u00e0 des espaces dans lesquels vous vous \u00eates sentis imm\u00e9diatement \u00e0 l\u2019aise avec les personnes qui vous entouraient \u2013 et d\u2019autres o\u00f9 ce n\u2019\u00e9tait pas le cas. Il est possible que ce ne soit pas les personnes pr\u00e9sentes qui en soient la cause, mais la conception de l\u2019espace qui a rendu les interactions plus embarrassantes, ou qui a rendu cette pi\u00e8ce, ce b\u00e2timent ou ce wagon plus confortable. La Dre McClunn pr\u00e9cise.<\/p>\n<p>\u00ab\u00a0Si l\u2019on veut qu\u2019un certain espace soit accueillant et confortable, on peut le concevoir pour qu\u2019un certain nombre de personnes puissent s\u2019y asseoir \u00e0 une certaine distance. Je pense \u00e0 la conception d\u2019un caf\u00e9, ou un restaurant ou m\u00eame une salle de classe o\u00f9 l\u2019on veut que les gens s\u2019assoient d\u2019une certaine fa\u00e7on et cohabitent d\u2019une certaine mani\u00e8re.<\/p>\n<p>Je pense qu\u2019il est important d\u2019utiliser diff\u00e9rentes m\u00e9thodes, tout comme les autres psychologues le font. Nous sommes capables d\u2019int\u00e9grer une vari\u00e9t\u00e9 de m\u00e9thodes combin\u00e9es dans notre travail. Nous utilisons l\u2019observation naturaliste pour observer et voir comment les gens se d\u00e9placent et se comportent dans un espace afin de prendre des d\u00e9cisions de conception \u00e0 partir de nos observations. Nous effectuons beaucoup de sondages et d\u2019entrevues et, \u00e0 partir de ceux-ci, nous pouvons aider les architectes et les concepteurs \u00e0 rendre les b\u00e2timents les plus humains possible. Si l\u2019objet du travail clinique et d\u2019autres types d\u2019intervention psychologique est d\u2019aider les gens \u00e0 se sentir bien, alors la psychologie de l\u2019environnement est tout \u00e0 fait en phase avec cela. Nous voulons que les b\u00e2timents soient con\u00e7us de mani\u00e8re \u00e0 aider les gens \u00e0 se sentir aussi bien, motiv\u00e9s, enthousiastes et en forme que possible.\u00a0\u00bb<\/p>\n<p>Le Dr\u00a0Zelenski jette \u00e9galement un pont entre les deux c\u00f4t\u00e9s de la psychologie de l\u2019environnement, et ce, de diff\u00e9rentes mani\u00e8res. La collaboration avec des groupes qui font d\u00e9j\u00e0 un travail environnemental lui permet de recueillir plus facilement des donn\u00e9es, et l\u2019analyse de ces donn\u00e9es permet \u00e0 ces groupes de fonctionner de mani\u00e8re plus efficace et efficiente.<\/p>\n<p>\u00ab\u00a0J\u2019ai collabor\u00e9 avec un architecte, faisant ainsi le pont entre ces deux composantes de la psychologie de l\u2019environnement. Il \u00e9tait tr\u00e8s int\u00e9ress\u00e9 par la construction de b\u00e2timents qui donneraient envie aux gens de se comporter de mani\u00e8re \u00e9cologique. De m\u00eame, il ne s\u2019agit peut-\u00eatre pas seulement de l\u2019int\u00e9rieur du b\u00e2timent, mais aussi des espaces naturels proches du b\u00e2timent qui pourraient encourager ces comportements. Il s\u2019agit de poser une question plus nuanc\u00e9e sur les types de milieux naturels \u00e0 proximit\u00e9 qui pourraient aider les gens \u00e0 se sentir mieux, \u00e0 \u00eatre plus heureux et plus productifs.<\/p>\n<p>Il y a un petit organisme sans but lucratif qui fournit des trousses d\u2019analyse de l\u2019eau. Il les distribue aux gens, qui les utilisent pour tester la qualit\u00e9 de l\u2019eau \u00e0 proximit\u00e9; les gens t\u00e9l\u00e9chargent ensuite leurs donn\u00e9es dans un genre de base de donn\u00e9es participative qui permet de voir si le lac ou la rivi\u00e8re pr\u00e8s de chez eux est en bon ou en mauvais \u00e9tat, et comment cela \u00e9volue au fil du temps. Il serait difficile pour moi de monter une exp\u00e9rience dans laquelle je distribuerais des tas de trousses d\u2019analyse de l\u2019eau, mais je peux essayer de suivre les personnes qui le font d\u00e9j\u00e0 pour voir si cela change leur sentiment de connexion avec la nature, si cela les rend heureux et si cela leur donne envie de faire d\u2019autres choses bonnes pour l\u2019environnement que de simplement tester l\u2019eau.\u00a0\u00bb<\/p>\n<p>Depuis la mise en place de mesures de confinement en raison de la pand\u00e9mie, nous entendons beaucoup de personnes dire qu\u2019elles appr\u00e9cient davantage la nature. C\u2019est un moyen s\u00fbr de sortir de chez soi. Si on ne peut pas aller dans un centre commercial bond\u00e9 ou \u00e0 un concert, on peut toujours aller dans un parc et se promener. Les gens voient la nature comme une source de bien-\u00eatre et un bon moyen de s\u2019adapter, et certaines \u00e9tudes indiquent que la nature est l\u2019une des choses les plus positives que les gens ont ressenties au cours des deux derni\u00e8res ann\u00e9es, o\u00f9 la distanciation physique \u00e9tait impos\u00e9e. Mais ce lien avec la nature, ainsi que la prise de conscience de la grave menace que repr\u00e9sente le changement climatique, cr\u00e9e \u00e0 certains \u00e9gards de nouveaux probl\u00e8mes.<\/p>\n<p>Selon le Dr\u00a0Zelenski, \u00ab\u00a0Beaucoup de gens parlent d\u2019\u00e9coanxi\u00e9t\u00e9 et le fait que les gens soient de plus en plus conscients des changements climatiques pourrait \u00eatre une arme \u00e0 double tranchant. Cela peut donc \u00eatre motivant \u2013 ce qui est un r\u00e9sultat positif, les gens voulant se comporter d\u2019une mani\u00e8re plus \u00e9cologique \u2013 mais certaines personnes pourraient \u00eatre boulevers\u00e9es ou inqui\u00e8tes \u00e0 tel point que cela cr\u00e9era de nouvelles formes de stress et d\u2019inqui\u00e9tude qui, chez elles, peuvent \u00eatre inadapt\u00e9es.\u00a0\u00bb<\/p>\n<p>L\u2019un des moyens de lutter contre l\u2019\u00e9coanxi\u00e9t\u00e9, un nouveau mot \u00e0 la mode dans le domaine de la pr\u00e9servation de l\u2019environnement, consiste \u00e0 faire conna\u00eetre les psychologues de l\u2019environnement et \u00e0 solliciter leurs conseils. Cette sensibilisation accrue se ressent \u00e9galement dans la dimension architecturale, car les contributions des experts de ce domaine sont maintenant per\u00e7ues par beaucoup comme \u00e9tant inestimables. La Dre\u00a0McCunn dit qu\u2019elle a vu ce changement directement.<\/p>\n<p>\u00ab\u00a0Lorsque je rencontre des ing\u00e9nieurs, des architectes et des urbanistes, je constate qu\u2019ils sont davantage sensibili\u00e9s \u00e0 la psychologie de l\u2019environnement et qu\u2019ils sont tout \u00e0 fait dispos\u00e9s \u00e0 travailler avec nous. Lorsque je faisais ma ma\u00eetrise, j\u2019ai remarqu\u00e9 que tr\u00e8s peu de personnes occupant ces postes voulaient travailler avec un sp\u00e9cialiste en sciences sociales. Plusieurs d\u2019entre eux disaient qu\u2019ils faisaient ce genre de recherche accessoirement, et qu\u2019ils \u201csavaient d\u00e9j\u00e0 comment \u00e9tudier les gens\u201d. Aujourd\u2019hui, ils font appel \u00e0 moi car ils veulent int\u00e9grer cette dimension professionnelle \u00e0 leur activit\u00e9 ou \u00e0 leurs processus.<\/p>\n<p>La cognition spatiale, par exemple, est un sujet tr\u00e8s habituel en psychologie de l\u2019environnement. Je pense qu\u2019il est important de le mentionner car la population vieillit. Les psychologues de l\u2019environnement consultent souvent les concepteurs pour savoir comment aider les personnes atteintes de d\u00e9mence \u00e0 s\u2019orienter dans une maison de soins, par exemple. Nous pouvons les observer et les aider avec des pancartes et des symboles, et des moyens d\u2019int\u00e9grer leur psychologie dans la conception pour leur faciliter la vie.\u00a0\u00bb<\/p>\n<p>\u00cates-vous d\u00e9j\u00e0 all\u00e9 dans un magasin o\u00f9 il y a, sur le sol, un motif tr\u00e8s simple qui se transforme un peu \u00e0 l\u2019approche des toilettes, et un peu plus pr\u00e8s de la caisse? Peut-\u00eatre y a-t-il des rampes d\u2019escalier de couleur vive le long des murs, et le si\u00e8ge des toilettes est-il d\u2019une couleur nettement diff\u00e9rente du reste des toilettes. Le magasin est bien \u00e9clair\u00e9, mais pas trop, car il y a peu de surfaces r\u00e9fl\u00e9chissantes et pas de miroirs. Un magasin qui ressemble \u00e0 \u00e7a a probablement \u00e9t\u00e9 con\u00e7u pour \u00eatre accessible aux personnes atteintes de d\u00e9mence, avec l\u2019aide de psychologues de l\u2019environnement.<\/p>\n<p>Les personnes atteintes de la maladie d\u2019Alzheimer et de diff\u00e9rents types de d\u00e9mence sont g\u00e9n\u00e9ralement suivies par une \u00e9quipe de soins, notamment par un neuroscientifique (voir le portrait de la neuropsychologie clinique pr\u00e9sent\u00e9 plus t\u00f4t ce mois-ci). De plus en plus, les psychologues de l\u2019environnement travaillent au sein d\u2019\u00e9quipes interdisciplinaires plus larges, et les neurosciences elles-m\u00eames prennent une place plus importante dans la discipline. La Dre\u00a0McCunn dit qu\u2019elle le constate gr\u00e2ce aux articles propos\u00e9s au Journal of Environmental Psychology.<\/p>\n<p>\u00ab\u00a0Il y a beaucoup d\u2019articles qui fusionnent les neurosciences et la psychologie de l\u2019environnement. Je fais aussi cela dans mon propre travail \u2013 j\u2019ai presque termin\u00e9 une deuxi\u00e8me ma\u00eetrise en neurosciences appliqu\u00e9es, simplement pour approfondir mes recherches dans le domaine des neurosciences environnementales. J\u2019aime chercher \u00e0 comprendre des concepts tels que \u201cque se passe-t-il dans le cerveau lorsque nous ressentons un attachement \u00e0 un lieu? Est-ce diff\u00e9rent de l\u2019attachement que l\u2019on ressent face \u00e0 une personne? Que se passe-t-il dans le cerveau lorsque nous rencontrons diff\u00e9rents contextes?\u201d Ce sont des questions importantes qui, je pense, sont de plus en plus populaires.\u00a0\u00bb<\/p>\n<p>La psychologie de l\u2019environnement devenant une discipline de plus en plus demand\u00e9e, l\u2019expertise des personnes travaillant dans ce domaine est appliqu\u00e9e \u00e0 une vari\u00e9t\u00e9 de sujets sans cesse croissante. La Dre\u00a0McCunn esp\u00e8re que cette tendance se poursuivra, afin que l\u2019ensemble des comp\u00e9tences de ses coll\u00e8gues puisse \u00eatre utilis\u00e9 pour aider \u00e0 r\u00e9soudre des probl\u00e8mes importants.<\/p>\n<p>\u00ab\u00a0Je souhaite que la psychologie de l\u2019environnement fasse partie d\u2019un grand nombre d\u2019\u00e9quipes tr\u00e8s diverses. Bien s\u00fbr, les architectes et les urbanistes, mais aussi les cliniciens, les m\u00e9decins, les neuroscientifiques, etc. Je crois que nous sommes de bons partenaires et nous pouvons ajouter des facettes aux questions de recherche qui peuvent enrichir une r\u00e9ponse et la rendre plus compl\u00e8te. Il est tr\u00e8s difficile de tirer des conclusions \u00e0 partir de quelques variables seulement. La mobilisation des donn\u00e9es et de la mod\u00e9lisation dans le domaine de la psychologie de l\u2019environnement peut nous aider \u00e0 aider les autres \u00e0 obtenir des r\u00e9ponses plus fiables \u00e0 de vastes questions de soci\u00e9t\u00e9 sur ce qui pousse les gens \u00e0 agir et \u00e0 penser de telle ou telle mani\u00e8re. J\u2019aimerais voir la psychologie de l\u2019environnement mettre \u00e0 contribution son expertise dans toutes sortes de contextes et dans toutes sortes d\u2019\u00e9quipes.\u00a0\u00bb<\/p>\n<p>Mais soyez rassur\u00e9 \u2013 si un psychologue de l\u2019environnement se retrouve chez vous, il ne jugera pas la disposition de votre argenterie ni l\u2019endroit o\u00f9 vous avez plac\u00e9 votre sauci\u00e8re, \u00e0 c\u00f4t\u00e9 du pot de Nutella. Du moins, pas plus que n\u2019importe qui d\u2019autre.<\/p>\n            <\/div>\r\n    <\/div>\r\n\r\n\r\n\r\n            <\/div><\/div>\n<hr \/>\n","protected":false},"excerpt":{"rendered":"<div style=\"text-align: left;\">\n<p><a id=\"Environmental\" class=\"anchor\" name=\"Environmental\"><\/a><\/p>\n<div style=\"min-height: 130px;\">\n<div class=\"textwrapleft\"><img decoding=\"async\" class=\"textwrapleft\" style=\"max-height: 150px;\" src=\"https:\/\/cpa.ca\/docs\/File\/Psychology Month\/Lindsay McCunn.jpg\" alt=\"Dre Lindsay McCunn\" \/><br \/>\n<span style=\"color: gray; font-size: 12px; line-height: 9px;\"><em>Dre Lindsay McCunn<\/em><\/span><\/div>\n<div class=\"textwrapright\"><img decoding=\"async\" class=\"textwrapleft\" style=\"max-height: 150px;\" src=\"https:\/\/cpa.ca\/docs\/File\/Psychology Month\/John Zelenski.jpg\" alt=\"Dr John Zelenski\" \/><br \/>\n<span style=\"color: gray; font-size: 12px; line-height: 9px;\"><em>Dr. John Zelenski<\/em><\/span><\/div>\n<p><strong>Dre Lindsay McCunn et Dr John Zelenski, <em>Environmental Psychology<\/em><\/strong><br \/>\nLa psychologie de l\u2019environnement compte deux branches principales. Nous avons parl\u00e9 \u00e0 la Dre Lindsay McCunn de la branche de la psychologie de l\u2019architecture (la conception de b\u00e2timents et de pi\u00e8ces pour le bien-\u00eatre des occupants) et au Dr John Zelenski, de la psychologie \u00e9cologique (qui s\u2019int\u00e9resse aux comportements \u00e9cologiquement durables par l\u2019interm\u00e9diaire de la connexion des gens \u00e0 la nature).<\/p>\n<\/div>\n<div id=\"accordions-28025\" class=\"accordions-28025 accordions\" data-accordions={&quot;lazyLoad&quot;:true,&quot;id&quot;:&quot;28025&quot;,&quot;event&quot;:&quot;click&quot;,&quot;collapsible&quot;:&quot;true&quot;,&quot;heightStyle&quot;:&quot;content&quot;,&quot;animateStyle&quot;:&quot;swing&quot;,&quot;animateDelay&quot;:1000,&quot;navigation&quot;:true,&quot;active&quot;:999,&quot;expandedOther&quot;:&quot;no&quot;}>\r\n                <div id=\"accordions-lazy-28025\" class=\"accordions-lazy\" accordionsId=\"28025\">\r\n                    <\/div>\r\n\r\n    <div class=\"items\"  style=\"display:none\" >\r\n    \r\n            <div post_id=\"28025\" itemcount=\"0\"  header_id=\"header-1580324481504\" id=\"header-1580324481504\" style=\"\" class=\"accordions-head head1580324481504 border-none\" toggle-text=\"\" main-text=\"\u00c0 propos de  Dre Lindsay McCunn et Dr John Zelenski\">\r\n                                    <span id=\"accordion-icons-1580324481504\" class=\"accordion-icons\">\r\n                        <span class=\"accordion-icon-active accordion-plus\"><i class=\"fa fas fa-chevron-up\"><\/i><\/span>\r\n                        <span class=\"accordion-icon-inactive accordion-minus\"><i class=\"fa fas fa-chevron-down\"><\/i><\/span>\r\n                    <\/span>\r\n                    <span id=\"header-text-1580324481504\" class=\"accordions-head-title\">\u00c0 propos de  Dre Lindsay McCunn et Dr John Zelenski<\/span>\r\n                            <\/div>\r\n            <div class=\"accordion-content content1580324481504 \">\r\n                <p><strong><a href=\"https:\/\/cpa.ca\/fr\/sections\/environmentalpsychology\/\">Psychologie de l\u2019environnement <\/a><\/strong><\/p>\n<p>\u00ab\u00a0Quand je dis que je ne vous juge pas, je pense que je veux vraiment dire \u201cpas plus que les autres.\u201d\u00a0\u00bb.<\/p>\n<p>Je suis un peu nerveux \u00e0 l\u2019id\u00e9e que, pendant notre r\u00e9union Zoom, la Dre\u00a0Lindsay McCunn et le Dr\u00a0John Zelenski puissent juger mon arri\u00e8re-plan, d\u00e9cid\u00e9ment tr\u00e8s encombr\u00e9. Tous mes appareils \u00e9lectrom\u00e9nagers sont plac\u00e9s sur une tablette derri\u00e8re moi, ce qui donne l\u2019impression (exacte, il se trouve) que mon bureau \u00e0 domicile est un coin exigu pr\u00e8s de la cuisine. La Dre\u00a0McCunn et le Dr\u00a0Zelenski sont des psychologues de l\u2019environnement, c\u2019est-\u00e0-dire des sp\u00e9cialistes des espaces que nous occupons et de la mani\u00e8re dont nous interagissons avec eux. Le Dr\u00a0Zelenski est plut\u00f4t gentil et honn\u00eate \u2013 en tant qu\u2019\u00eatres humains, nous percevons des indices subtils, \u00e0 partir des espaces de chacun, mais cela n\u2019est probablement pas propre aux psychologues de l\u2019environnement. Nous jugeons tous les arri\u00e8re-plans Zoom, ne serait-ce qu\u2019un peu.<\/p>\n<p>La Dre\u00a0Lindsay McCunn est professeure de psychologie \u00e0 l\u2019Universit\u00e9 Vancouver Island. Elle est la pr\u00e9sidente de la Section de psychologie de l\u2019environnement de la SCP et la r\u00e9dactrice en chef adjointe du Journal of Environmental Psychology. Selon elle, les arri\u00e8re-plans Zoom des gens ou la fa\u00e7on dont ils am\u00e9nagent leurs jardins ou leurs espaces de vie sont sources de curiosit\u00e9 pour chacun d\u2019entre nous.<\/p>\n<p>\u00ab\u00a0La fa\u00e7on dont les gens s\u2019expriment, organisent leur domicile et placent des objets importants est vraiment int\u00e9ressante. Sam Gosling a \u00e9crit un livre intitul\u00e9 Snoopologie; il s\u2019agit d\u2019une \u00e9tude portant sur la fa\u00e7on dont on peut d\u00e9duire la personnalit\u00e9 et la fa\u00e7on de penser des gens en fonction de la mani\u00e8re dont ils rangent leurs bibelots et leurs affaires dans leur maison et leur bureau.\u00a0\u00bb<\/p>\n<p>La Dre\u00a0McCunn se sp\u00e9cialise en psychologie de l\u2019environnement et d\u00e9crit ainsi sa sp\u00e9cialit\u00e9.<\/p>\n<p>\u00ab\u00a0La psychologie de l\u2019environnement, c\u2019est l\u2019\u00e9tude des transactions entre les personnes et les lieux. Et j\u2019entends par l\u00e0 beaucoup de types d\u2019endroits \u2013 un caf\u00e9, un bureau, une \u00e9cole, un parc, un oc\u00e9an, une montagne. Nous \u00e9tudions les diff\u00e9rentes fa\u00e7ons dont les gens interagissent avec leur environnement. De la m\u00eame mani\u00e8re qu\u2019un psychologue social \u00e9tudie et analyse les relations et les interactions entre les individus et les autres, les psychologues de l\u2019environnement \u00e9tudient et analysent les relations entre les personnes et les lieux. Dans mes recherches, je m\u2019int\u00e9resse \u00e0 la fa\u00e7on dont les gens interagissent dans les collectivit\u00e9s et les milieux de travail, en particulier dans les h\u00f4pitaux, les \u00e9coles et les bureaux. \u00c0 ce titre, je me penche sur le personnel, principalement, et sur les personnes qui utilisent les environnements d\u2019une mani\u00e8re diff\u00e9rente de celle \u00e0 laquelle on pourrait s\u2019attendre, comme les \u00e9tudiants et les patients, les enseignants, etc.\u00a0\u00bb.<\/p>\n<p>Le Dr\u00a0John Zelenski est professeur au d\u00e9partement de psychologie de l\u2019Universit\u00e9 Carleton. Il est \u00e9galement un psychologue de l\u2019environnement, mais il se sp\u00e9cialise dans un domaine bien diff\u00e9rent de celui de la Dre\u00a0McCunn. On pourrait dire que l\u2019un et l\u2019autre repr\u00e9sentent les deux principales branches de la psychologie de l\u2019environnement \u2013 la psychologie de l\u2019architecture (Dre\u00a0McCunn) et la psychologie de l\u2019\u00e9cologie (Dr\u00a0Zelenski).<\/p>\n<p>\u00ab\u00a0En plus d\u2019\u00eatre un psychologue de l\u2019environnement, je me consid\u00e8re aussi comme un psychologue de la personnalit\u00e9 qui se r\u00e9clame de la psychologie positive. Je me suis beaucoup int\u00e9ress\u00e9 \u00e0 ce que nous appelons le rapport \u00e0 la nature, ou ce que d\u2019autres appellent \u201cla connexion avec la nature\u201d. Je parle ici des impressions subjectives des gens\u00a0: font-ils partie de la nature ou la nature est-elle distincte d\u2019eux et n\u2019a pas grand-chose \u00e0 voir avec leur perception d\u2019eux-m\u00eames? Je me suis aussi beaucoup int\u00e9ress\u00e9 de fa\u00e7on g\u00e9n\u00e9rale par ce que j\u2019appelle un \u201cchemin heureux vers la durabilit\u00e9\u201d. C\u2019est l\u2019id\u00e9e que nous savons que la nature est capable de rendre les gens de bonne humeur. La nature est associ\u00e9e au bonheur, tant sur de longues p\u00e9riodes que sur le moment. Nous savons que les gens qui passent beaucoup de temps dans la nature et qui se sentent tr\u00e8s li\u00e9s \u00e0 la nature adoptent des comportements proenvironnement et \u00e9cologiquement durables. Au cours des derni\u00e8res ann\u00e9es, nous avons commenc\u00e9 \u00e0 penser que l\u2019inverse est peut-\u00eatre vrai aussi. Si l\u2019on peut amener les gens \u00e0 faire quelques petits gestes pour la nature, en adoptant des comportements \u00e9cologiquement durables, il serait possible de se servir de cela pour qu\u2019ils se sentent plus proches de la nature et plus heureux de pratiquer ces activit\u00e9s. Nous pensons que les actions en faveur de l\u2019environnement ne doivent pas n\u00e9cessairement \u00eatre on\u00e9reuses et que nous pouvons les associer \u00e0 des \u00e9motions positives.\u00a0\u00bb<\/p>\n<p>Ce que \u00ab\u00a0consacrer du temps dans la nature\u00a0\u00bb signifie pour chaque personne est subjectif. Il s\u2019agit peut-\u00eatre de prendre un week-end pour faire de la randonn\u00e9e dans les collines, de passer une journ\u00e9e \u00e0 p\u00eacher sur la glace ou simplement d\u2019aller dans son jardin et s\u2019occuper de son potager de radis. Pour la Dre\u00a0McCunn, cela a entra\u00een\u00e9 de grands changements depuis le d\u00e9but de la pand\u00e9mie de COVID-19. Elle nous parle par Zoom dans ce qui semble \u00eatre un chalet dans les bois. Depuis quelques ann\u00e9es, elle et sa famille vivaient dans le centre-ville de Nanaimo, en Colombie-Britannique, en face du service d\u2019ambulance, du service de police et de la caserne de pompiers. Les sir\u00e8nes ont augment\u00e9 consid\u00e9rablement lorsque la pand\u00e9mie a commenc\u00e9, leurs habitudes de sommeil ont commenc\u00e9 \u00e0 en \u00eatre affect\u00e9es et ils ont d\u00e9cid\u00e9 de louer un endroit \u00e0 la campagne.<\/p>\n<p>\u00ab\u00a0Ce fut en quelque sorte une bonne \u00e9tude de cas en psychologie de l\u2019environnement, dans la mesure o\u00f9 nous pouvions r\u00e9aliser ce qui nous stimulait dans notre environnement familial, puis d\u00e9cider comment le modifier pour notre sant\u00e9 mentale. Nous avons donc pens\u00e9 \u00e0 d\u00e9m\u00e9nager dans un cadre naturel plus vaste o\u00f9 nous pourrions avoir un peu plus de contr\u00f4le sur les choses qui nous stimulent. Nous avons \u00e9t\u00e9 tr\u00e8s chanceux de pouvoir louer quelque chose \u00e0 la campagne. C\u2019\u00e9tait int\u00e9ressant, parce que j\u2019\u00e9tais tr\u00e8s attach\u00e9e \u00e0 la maison que nous poss\u00e9dions. L\u2019une des choses que nous \u00e9tudions, comme psychologues de l\u2019environnement, est le \u201csentiment d\u2019appartenance\u201d ou un sentiment d\u2019appartenance \u00e0 un lieu, un sentiment identitaire ou un sentiment de d\u00e9pendance. Au d\u00e9but de la pand\u00e9mie, j\u2019ai entendu beaucoup de questions sur la fa\u00e7on dont les gens faisaient face au sentiment de perte qu\u2019ils ressentaient depuis qu\u2019ils travaillaient \u00e0 domicile. Pas seulement un sentiment de perte en rapport avec des \u00e9l\u00e9ments sociaux, mais aussi une perte des moyens habituels par lesquels ils se rendaient \u00e0 leur lieu de travail. Peut-\u00eatre prenaient-ils le m\u00eame autobus tous les jours ou arr\u00eataient-ils au m\u00eame caf\u00e9 lorsqu\u2019ils se rendaient \u00e0 l\u2019\u00e9cole ou au travail. M\u00eame le caract\u00e8re physique de l\u2019environnement de bureau ou de la salle de classe elle-m\u00eame \u2013 cet environnement leur manquait. Je me suis donc demand\u00e9 comment je r\u00e9agirais lorsque je m\u2019\u00e9loignerais de mon environnement familier auquel je m\u2019\u00e9tais vraiment attach\u00e9. Je ne voulais pas me mettre dans une position o\u00f9 je perdrais mon lien avec mon cadre habituel, mais je me suis rapidement attach\u00e9e \u00e0 cet endroit et aux caract\u00e9ristiques naturelles qui l\u2019entourent. Ce fut une belle aventure d\u2019explorer la psychologie de l\u2019environnement de l\u2019int\u00e9rieur et dans ce contexte.\u00a0\u00bb<\/p>\n<p>Se sentir proche de la nature, ce peut \u00eatre aussi simple que de pouvoir sortir et toucher \u00e0 un arbre, ou regarder par la fen\u00eatre une montagne ou une vari\u00e9t\u00e9 d\u2019esp\u00e8ces d\u2019oiseaux. Alors, comment cela peut-il se traduire par des comportements plus respectueux de l\u2019environnement, au moment o\u00f9 le changement climatique est devenu le probl\u00e8me le plus urgent de notre \u00e9poque? Le Dr\u00a0Zelenski donne l\u2019exemple que voici.<\/p>\n<p>\u00ab\u00a0Nous avons beaucoup de bonnes preuves circonstancielles et d\u2019\u00e9tudes de laboratoire, et nous essayons de les assembler. Quelques programmes ont \u00e9t\u00e9 prometteurs! Mon ancienne \u00e9tudiante, amie et collaboratrice, Lisa Nisbet, a collabor\u00e9 avec la Fondation David Suzuki pour relever le D\u00e9fi nature\u00a030\u00d730. Ce d\u00e9fi consiste \u00e0 consacrer 30\u00a0minutes dans la nature chaque jour pendant 30\u00a0jours. Les personnes qui s\u2019inscrivent \u00e0 ce d\u00e9fi ont tendance \u00e0 \u00eatre plut\u00f4t \u00e9cologistes et d\u00e9j\u00e0 tr\u00e8s proches de la nature. Mais au cours de ce mois, cette connexion semble se d\u00e9velopper. Ce n\u2019est pas un essai contr\u00f4l\u00e9 randomis\u00e9, mais il semble que le fait de passer du temps dans la nature donne \u00e0 ces personnes le sentiment d\u2019\u00eatre plus proches, ce qui les incite \u00e0 adopter des comportements \u00e9cologiquement durables.\u00a0\u00bb<\/p>\n<p>L\u2019\u00e9cologie est une division de la psychologie de l\u2019environnement (relativement) nouvelle, et elle a sans aucun doute pris beaucoup d\u2019ampleur au cours des 20\u00a0derni\u00e8res ann\u00e9es, les changements climatiques \u00e9tant rapidement devenus un sujet de premier plan pour beaucoup d\u2019entre nous. Le Dr\u00a0Zelenski n\u2019est pas le seul \u00e0 avoir \u00e9volu\u00e9 dans cette direction.<\/p>\n<p>\u00ab\u00a0L\u2019attention et l\u2019importance accord\u00e9es \u00e0 l\u2019aspect \u00e9cologique de la psychologie de l\u2019environnement semblent s\u2019\u00eatre accrues au cours des 10\u00a0ou 15\u00a0derni\u00e8res ann\u00e9es. Je suis venu \u00e0 la psychologie \u00e9cologique apr\u00e8s mon doctorat, par simple int\u00e9r\u00eat personnel, et j\u2019ai l\u2019impression d\u2019\u00eatre l\u2019un des millions de personnes qui ont suivi le mouvement, et ce, pour plusieurs raisons. Les gens semblent de plus en plus manifester des sympt\u00f4mes de d\u00e9pression, d\u2019anxi\u00e9t\u00e9, etc., et la nature semble offrir un r\u00e9pit agr\u00e9able. De plus, la prise de conscience relative aux changements climatiques ne cesse de cro\u00eetre, car nous en voyons de plus en plus les effets. Et les d\u00e9cideurs politiques souhaitent savoir ce que les sciences sociales peuvent apporter pour r\u00e9soudre ces probl\u00e8mes.\u00a0\u00bb<\/p>\n<p>La dimension \u00e9cologique de la discipline a \u00e9man\u00e9 naturellement de la branche traditionnelle de la psychologie de l\u2019architecture, qui existe depuis les ann\u00e9es\u00a01960. Selon la Dre\u00a0McCunn, il existe quelques programmes d\u2019\u00e9tudes sup\u00e9rieures officiels en \u00ab\u00a0psychologie de l\u2019environnement\u00a0\u00bb au Canada, mais il y en a plus en Angleterre et aux \u00c9tats-Unis, aux Pays-Bas et en Am\u00e9rique du Sud. Donc, lorsqu\u2019elle dit aux gens qu\u2019elle est une \u00ab\u00a0psychologue de l\u2019environnement\u00a0\u00bb, ceux-ci savent souvent ce qu\u2019elle veut dire.<\/p>\n<p>\u00ab\u00a0Certaines personnes, \u00e0 juste titre, divisent la dimension de la psychologie de l\u2019architecture et la dimension de la psychologie de l\u2019\u00e9cologie. Je le fais aussi si je veux expliquer aux gens ce que j\u2019\u00e9tudie, parce que je suis plut\u00f4t du c\u00f4t\u00e9 de l\u2019architecture. Je travaille avec des ing\u00e9nieurs, des gestionnaires d\u2019installations et des urbanistes, mais j\u2019ai aussi des coll\u00e8gues, comme John, qui s\u2019int\u00e9ressent au lien avec la nature et travaillent avec des personnes qui \u00e9tudient les attitudes et les comportements proenvironnement. L\u2019id\u00e9e de conservation de la nature est devenue tr\u00e8s populaire dans le domaine de la psychologie de l\u2019environnement, sans pour autant prendre le pas sur la dimension architecturale, qui s\u2019int\u00e9resse \u00e0 l\u2019infrastructure des immeubles, etc. En fait, la psychologie de l\u2019environnement a d\u00e9but\u00e9 dans le contexte de l\u2019architecture, mais elle s\u2019est largement \u00e9tendue \u00e0 son autre volet, qui consiste \u00e0 poser aux gens des questions sur leur conscience \u00e9cologique et leur rapport \u00e0 la nature.\u00a0\u00bb<\/p>\n<p>Les deux branches vont de pair. Pensez \u00e0 la tendance \u00e0 construire des b\u00e2timents \u00ab\u00a0verts\u00a0\u00bb, avec du chauffage \u00e0 faible consommation d\u2019\u00e9nergie, des panneaux solaires, voire un jardin sur le toit.<\/p>\n<p>Selon la Dre\u00a0McCunn, \u00ab\u00a0Quand un ing\u00e9nieur me demande\u00a0: \u201cdevrions-nous concevoir ce b\u00e2timent en tenant compte de la durabilit\u00e9\u201d, il veut en r\u00e9alit\u00e9 savoir \u2013 \u201cles gens vont-ils le remarquer? S\u2019en soucient-ils? Vont-ils apporter des changements \u00e0 leurs comportements \u00e0 l\u2019int\u00e9rieur (et \u00e0 l\u2019ext\u00e9rieur) de l\u2019immeuble pour cette raison?\u201d Je peux les aider \u00e0 \u00e9tudier la mani\u00e8re dont les gens se comportent, travaillent et fonctionnent dans des b\u00e2timents plus (ou moins) durables. J\u2019ai fait une \u00e9tude dans une \u00e9cole d\u2019\u00e9tudes sup\u00e9rieures qui a montr\u00e9 que le fait qu\u2019un immeuble de bureaux soit \u201cvert\u201d ou durable ne signifie pas n\u00e9cessairement que cela permettra de pr\u00e9dire une forte productivit\u00e9 ou une forte satisfaction. Il est important de garder un \u0153il critique sur ce que l\u2019on attend d\u2019une conception durable et sur ce que l\u2019on n\u2019attend pas.\u00a0\u00bb<\/p>\n<p>Pensez \u00e0 des espaces dans lesquels vous vous \u00eates sentis imm\u00e9diatement \u00e0 l\u2019aise avec les personnes qui vous entouraient \u2013 et d\u2019autres o\u00f9 ce n\u2019\u00e9tait pas le cas. Il est possible que ce ne soit pas les personnes pr\u00e9sentes qui en soient la cause, mais la conception de l\u2019espace qui a rendu les interactions plus embarrassantes, ou qui a rendu cette pi\u00e8ce, ce b\u00e2timent ou ce wagon plus confortable. La Dre McClunn pr\u00e9cise.<\/p>\n<p>\u00ab\u00a0Si l\u2019on veut qu\u2019un certain espace soit accueillant et confortable, on peut le concevoir pour qu\u2019un certain nombre de personnes puissent s\u2019y asseoir \u00e0 une certaine distance. Je pense \u00e0 la conception d\u2019un caf\u00e9, ou un restaurant ou m\u00eame une salle de classe o\u00f9 l\u2019on veut que les gens s\u2019assoient d\u2019une certaine fa\u00e7on et cohabitent d\u2019une certaine mani\u00e8re.<\/p>\n<p>Je pense qu\u2019il est important d\u2019utiliser diff\u00e9rentes m\u00e9thodes, tout comme les autres psychologues le font. Nous sommes capables d\u2019int\u00e9grer une vari\u00e9t\u00e9 de m\u00e9thodes combin\u00e9es dans notre travail. Nous utilisons l\u2019observation naturaliste pour observer et voir comment les gens se d\u00e9placent et se comportent dans un espace afin de prendre des d\u00e9cisions de conception \u00e0 partir de nos observations. Nous effectuons beaucoup de sondages et d\u2019entrevues et, \u00e0 partir de ceux-ci, nous pouvons aider les architectes et les concepteurs \u00e0 rendre les b\u00e2timents les plus humains possible. Si l\u2019objet du travail clinique et d\u2019autres types d\u2019intervention psychologique est d\u2019aider les gens \u00e0 se sentir bien, alors la psychologie de l\u2019environnement est tout \u00e0 fait en phase avec cela. Nous voulons que les b\u00e2timents soient con\u00e7us de mani\u00e8re \u00e0 aider les gens \u00e0 se sentir aussi bien, motiv\u00e9s, enthousiastes et en forme que possible.\u00a0\u00bb<\/p>\n<p>Le Dr\u00a0Zelenski jette \u00e9galement un pont entre les deux c\u00f4t\u00e9s de la psychologie de l\u2019environnement, et ce, de diff\u00e9rentes mani\u00e8res. La collaboration avec des groupes qui font d\u00e9j\u00e0 un travail environnemental lui permet de recueillir plus facilement des donn\u00e9es, et l\u2019analyse de ces donn\u00e9es permet \u00e0 ces groupes de fonctionner de mani\u00e8re plus efficace et efficiente.<\/p>\n<p>\u00ab\u00a0J\u2019ai collabor\u00e9 avec un architecte, faisant ainsi le pont entre ces deux composantes de la psychologie de l\u2019environnement. Il \u00e9tait tr\u00e8s int\u00e9ress\u00e9 par la construction de b\u00e2timents qui donneraient envie aux gens de se comporter de mani\u00e8re \u00e9cologique. De m\u00eame, il ne s\u2019agit peut-\u00eatre pas seulement de l\u2019int\u00e9rieur du b\u00e2timent, mais aussi des espaces naturels proches du b\u00e2timent qui pourraient encourager ces comportements. Il s\u2019agit de poser une question plus nuanc\u00e9e sur les types de milieux naturels \u00e0 proximit\u00e9 qui pourraient aider les gens \u00e0 se sentir mieux, \u00e0 \u00eatre plus heureux et plus productifs.<\/p>\n<p>Il y a un petit organisme sans but lucratif qui fournit des trousses d\u2019analyse de l\u2019eau. Il les distribue aux gens, qui les utilisent pour tester la qualit\u00e9 de l\u2019eau \u00e0 proximit\u00e9; les gens t\u00e9l\u00e9chargent ensuite leurs donn\u00e9es dans un genre de base de donn\u00e9es participative qui permet de voir si le lac ou la rivi\u00e8re pr\u00e8s de chez eux est en bon ou en mauvais \u00e9tat, et comment cela \u00e9volue au fil du temps. Il serait difficile pour moi de monter une exp\u00e9rience dans laquelle je distribuerais des tas de trousses d\u2019analyse de l\u2019eau, mais je peux essayer de suivre les personnes qui le font d\u00e9j\u00e0 pour voir si cela change leur sentiment de connexion avec la nature, si cela les rend heureux et si cela leur donne envie de faire d\u2019autres choses bonnes pour l\u2019environnement que de simplement tester l\u2019eau.\u00a0\u00bb<\/p>\n<p>Depuis la mise en place de mesures de confinement en raison de la pand\u00e9mie, nous entendons beaucoup de personnes dire qu\u2019elles appr\u00e9cient davantage la nature. C\u2019est un moyen s\u00fbr de sortir de chez soi. Si on ne peut pas aller dans un centre commercial bond\u00e9 ou \u00e0 un concert, on peut toujours aller dans un parc et se promener. Les gens voient la nature comme une source de bien-\u00eatre et un bon moyen de s\u2019adapter, et certaines \u00e9tudes indiquent que la nature est l\u2019une des choses les plus positives que les gens ont ressenties au cours des deux derni\u00e8res ann\u00e9es, o\u00f9 la distanciation physique \u00e9tait impos\u00e9e. Mais ce lien avec la nature, ainsi que la prise de conscience de la grave menace que repr\u00e9sente le changement climatique, cr\u00e9e \u00e0 certains \u00e9gards de nouveaux probl\u00e8mes.<\/p>\n<p>Selon le Dr\u00a0Zelenski, \u00ab\u00a0Beaucoup de gens parlent d\u2019\u00e9coanxi\u00e9t\u00e9 et le fait que les gens soient de plus en plus conscients des changements climatiques pourrait \u00eatre une arme \u00e0 double tranchant. Cela peut donc \u00eatre motivant \u2013 ce qui est un r\u00e9sultat positif, les gens voulant se comporter d\u2019une mani\u00e8re plus \u00e9cologique \u2013 mais certaines personnes pourraient \u00eatre boulevers\u00e9es ou inqui\u00e8tes \u00e0 tel point que cela cr\u00e9era de nouvelles formes de stress et d\u2019inqui\u00e9tude qui, chez elles, peuvent \u00eatre inadapt\u00e9es.\u00a0\u00bb<\/p>\n<p>L\u2019un des moyens de lutter contre l\u2019\u00e9coanxi\u00e9t\u00e9, un nouveau mot \u00e0 la mode dans le domaine de la pr\u00e9servation de l\u2019environnement, consiste \u00e0 faire conna\u00eetre les psychologues de l\u2019environnement et \u00e0 solliciter leurs conseils. Cette sensibilisation accrue se ressent \u00e9galement dans la dimension architecturale, car les contributions des experts de ce domaine sont maintenant per\u00e7ues par beaucoup comme \u00e9tant inestimables. La Dre\u00a0McCunn dit qu\u2019elle a vu ce changement directement.<\/p>\n<p>\u00ab\u00a0Lorsque je rencontre des ing\u00e9nieurs, des architectes et des urbanistes, je constate qu\u2019ils sont davantage sensibili\u00e9s \u00e0 la psychologie de l\u2019environnement et qu\u2019ils sont tout \u00e0 fait dispos\u00e9s \u00e0 travailler avec nous. Lorsque je faisais ma ma\u00eetrise, j\u2019ai remarqu\u00e9 que tr\u00e8s peu de personnes occupant ces postes voulaient travailler avec un sp\u00e9cialiste en sciences sociales. Plusieurs d\u2019entre eux disaient qu\u2019ils faisaient ce genre de recherche accessoirement, et qu\u2019ils \u201csavaient d\u00e9j\u00e0 comment \u00e9tudier les gens\u201d. Aujourd\u2019hui, ils font appel \u00e0 moi car ils veulent int\u00e9grer cette dimension professionnelle \u00e0 leur activit\u00e9 ou \u00e0 leurs processus.<\/p>\n<p>La cognition spatiale, par exemple, est un sujet tr\u00e8s habituel en psychologie de l\u2019environnement. Je pense qu\u2019il est important de le mentionner car la population vieillit. Les psychologues de l\u2019environnement consultent souvent les concepteurs pour savoir comment aider les personnes atteintes de d\u00e9mence \u00e0 s\u2019orienter dans une maison de soins, par exemple. Nous pouvons les observer et les aider avec des pancartes et des symboles, et des moyens d\u2019int\u00e9grer leur psychologie dans la conception pour leur faciliter la vie.\u00a0\u00bb<\/p>\n<p>\u00cates-vous d\u00e9j\u00e0 all\u00e9 dans un magasin o\u00f9 il y a, sur le sol, un motif tr\u00e8s simple qui se transforme un peu \u00e0 l\u2019approche des toilettes, et un peu plus pr\u00e8s de la caisse? Peut-\u00eatre y a-t-il des rampes d\u2019escalier de couleur vive le long des murs, et le si\u00e8ge des toilettes est-il d\u2019une couleur nettement diff\u00e9rente du reste des toilettes. Le magasin est bien \u00e9clair\u00e9, mais pas trop, car il y a peu de surfaces r\u00e9fl\u00e9chissantes et pas de miroirs. Un magasin qui ressemble \u00e0 \u00e7a a probablement \u00e9t\u00e9 con\u00e7u pour \u00eatre accessible aux personnes atteintes de d\u00e9mence, avec l\u2019aide de psychologues de l\u2019environnement.<\/p>\n<p>Les personnes atteintes de la maladie d\u2019Alzheimer et de diff\u00e9rents types de d\u00e9mence sont g\u00e9n\u00e9ralement suivies par une \u00e9quipe de soins, notamment par un neuroscientifique (voir le portrait de la neuropsychologie clinique pr\u00e9sent\u00e9 plus t\u00f4t ce mois-ci). De plus en plus, les psychologues de l\u2019environnement travaillent au sein d\u2019\u00e9quipes interdisciplinaires plus larges, et les neurosciences elles-m\u00eames prennent une place plus importante dans la discipline. La Dre\u00a0McCunn dit qu\u2019elle le constate gr\u00e2ce aux articles propos\u00e9s au Journal of Environmental Psychology.<\/p>\n<p>\u00ab\u00a0Il y a beaucoup d\u2019articles qui fusionnent les neurosciences et la psychologie de l\u2019environnement. Je fais aussi cela dans mon propre travail \u2013 j\u2019ai presque termin\u00e9 une deuxi\u00e8me ma\u00eetrise en neurosciences appliqu\u00e9es, simplement pour approfondir mes recherches dans le domaine des neurosciences environnementales. J\u2019aime chercher \u00e0 comprendre des concepts tels que \u201cque se passe-t-il dans le cerveau lorsque nous ressentons un attachement \u00e0 un lieu? Est-ce diff\u00e9rent de l\u2019attachement que l\u2019on ressent face \u00e0 une personne? Que se passe-t-il dans le cerveau lorsque nous rencontrons diff\u00e9rents contextes?\u201d Ce sont des questions importantes qui, je pense, sont de plus en plus populaires.\u00a0\u00bb<\/p>\n<p>La psychologie de l\u2019environnement devenant une discipline de plus en plus demand\u00e9e, l\u2019expertise des personnes travaillant dans ce domaine est appliqu\u00e9e \u00e0 une vari\u00e9t\u00e9 de sujets sans cesse croissante. La Dre\u00a0McCunn esp\u00e8re que cette tendance se poursuivra, afin que l\u2019ensemble des comp\u00e9tences de ses coll\u00e8gues puisse \u00eatre utilis\u00e9 pour aider \u00e0 r\u00e9soudre des probl\u00e8mes importants.<\/p>\n<p>\u00ab\u00a0Je souhaite que la psychologie de l\u2019environnement fasse partie d\u2019un grand nombre d\u2019\u00e9quipes tr\u00e8s diverses. Bien s\u00fbr, les architectes et les urbanistes, mais aussi les cliniciens, les m\u00e9decins, les neuroscientifiques, etc. Je crois que nous sommes de bons partenaires et nous pouvons ajouter des facettes aux questions de recherche qui peuvent enrichir une r\u00e9ponse et la rendre plus compl\u00e8te. Il est tr\u00e8s difficile de tirer des conclusions \u00e0 partir de quelques variables seulement. La mobilisation des donn\u00e9es et de la mod\u00e9lisation dans le domaine de la psychologie de l\u2019environnement peut nous aider \u00e0 aider les autres \u00e0 obtenir des r\u00e9ponses plus fiables \u00e0 de vastes questions de soci\u00e9t\u00e9 sur ce qui pousse les gens \u00e0 agir et \u00e0 penser de telle ou telle mani\u00e8re. J\u2019aimerais voir la psychologie de l\u2019environnement mettre \u00e0 contribution son expertise dans toutes sortes de contextes et dans toutes sortes d\u2019\u00e9quipes.\u00a0\u00bb<\/p>\n<p>Mais soyez rassur\u00e9 \u2013 si un psychologue de l\u2019environnement se retrouve chez vous, il ne jugera pas la disposition de votre argenterie ni l\u2019endroit o\u00f9 vous avez plac\u00e9 votre sauci\u00e8re, \u00e0 c\u00f4t\u00e9 du pot de Nutella. Du moins, pas plus que n\u2019importe qui d\u2019autre.<\/p>\n            <\/div>\r\n    <\/div>\r\n\r\n\r\n\r\n            <\/div><\/div>\n<hr \/>\n","protected":false},"author":2,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[138,175],"tags":[],"class_list":["post-28033","post","type-post","status-publish","format-standard","hentry","category-psychprofilesfr","category-psychmonth2022fr"],"acf":[],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 4.9.9 - aioseo.com -->\n\t<meta name=\"description\" content=\"Dre Lindsay McCunn Dr. John Zelenski Dre Lindsay McCunn et Dr John Zelenski, Environmental Psychology La psychologie de l\u2019environnement compte deux branches principales. Nous avons parl\u00e9 \u00e0 la Dre Lindsay McCunn de la branche de la psychologie de l\u2019architecture (la conception de b\u00e2timents et de pi\u00e8ces pour le bien-\u00eatre des occupants) et au Dr John Zelenski, de la psychologie \u00e9cologique (qui s\u2019int\u00e9resse aux comportements \u00e9cologiquement durables par l\u2019interm\u00e9diaire de la connexion des gens \u00e0 la nature). \u00c0 propos de Dre Lindsay McCunn et Dr John Zelenski Psychologie de l\u2019environnement \u00ab Quand je dis que je ne vous juge pas, je pense que je veux vraiment dire \u201cpas plus que les autres.\u201d \u00bb. Je suis un peu nerveux \u00e0 l\u2019id\u00e9e que, pendant notre r\u00e9union Zoom, la Dre Lindsay McCunn et le Dr John Zelenski puissent juger mon arri\u00e8re-plan, d\u00e9cid\u00e9ment tr\u00e8s encombr\u00e9. Tous mes appareils \u00e9lectrom\u00e9nagers sont plac\u00e9s sur une tablette derri\u00e8re moi, ce qui donne l\u2019impression (exacte, il se trouve) que mon bureau \u00e0 domicile est un coin exigu pr\u00e8s de la cuisine. La Dre McCunn et le Dr Zelenski sont des psychologues de l\u2019environnement, c\u2019est-\u00e0-dire des sp\u00e9cialistes des espaces que nous occupons et de la mani\u00e8re dont nous interagissons avec eux. Le Dr Zelenski est plut\u00f4t gentil et honn\u00eate \u2013 en tant qu\u2019\u00eatres humains, nous percevons des indices subtils, \u00e0 partir des espaces de chacun, mais cela n\u2019est probablement pas propre aux psychologues de l\u2019environnement. Nous jugeons tous les arri\u00e8re-plans Zoom, ne serait-ce qu\u2019un peu. La Dre Lindsay McCunn est professeure de psychologie \u00e0 l\u2019Universit\u00e9 Vancouver Island. Elle est la pr\u00e9sidente de la Section de psychologie de l\u2019environnement de la SCP et la r\u00e9dactrice en chef adjointe du Journal of Environmental Psychology. Selon elle, les arri\u00e8re-plans Zoom des gens ou la fa\u00e7on dont ils am\u00e9nagent leurs jardins ou leurs espaces de vie sont sources de curiosit\u00e9 pour chacun d\u2019entre nous. \u00ab La fa\u00e7on dont les gens s\u2019expriment, organisent leur domicile et placent des objets importants est vraiment int\u00e9ressante. Sam Gosling a \u00e9crit un livre intitul\u00e9 Snoopologie; il s\u2019agit d\u2019une \u00e9tude portant sur la fa\u00e7on dont on peut d\u00e9duire la personnalit\u00e9 et la fa\u00e7on de penser des gens en fonction de la mani\u00e8re dont ils rangent leurs bibelots et leurs affaires dans leur maison et leur bureau. \u00bb La Dre McCunn se sp\u00e9cialise en psychologie de l\u2019environnement et d\u00e9crit ainsi sa sp\u00e9cialit\u00e9. \u00ab La psychologie de l\u2019environnement, c\u2019est l\u2019\u00e9tude des transactions entre les personnes et les lieux. Et j\u2019entends par l\u00e0 beaucoup de types d\u2019endroits \u2013 un caf\u00e9, un bureau, une \u00e9cole, un parc, un oc\u00e9an, une montagne. Nous \u00e9tudions les diff\u00e9rentes fa\u00e7ons dont les gens interagissent avec leur environnement. De la m\u00eame mani\u00e8re qu\u2019un psychologue social \u00e9tudie et analyse les relations et les interactions entre les individus et les autres, les psychologues de l\u2019environnement \u00e9tudient et analysent les relations entre les personnes et les lieux. Dans mes recherches, je m\u2019int\u00e9resse \u00e0 la fa\u00e7on dont les gens interagissent dans les collectivit\u00e9s et les milieux de travail, en particulier dans les h\u00f4pitaux, les \u00e9coles et les bureaux. \u00c0 ce titre, je me penche sur le personnel, principalement, et sur les personnes qui utilisent les environnements d\u2019une mani\u00e8re diff\u00e9rente de celle \u00e0 laquelle on pourrait s\u2019attendre, comme les \u00e9tudiants et les patients, les enseignants, etc. \u00bb. Le Dr John Zelenski est professeur au d\u00e9partement de psychologie de l\u2019Universit\u00e9 Carleton. Il est \u00e9galement un psychologue de l\u2019environnement, mais il se sp\u00e9cialise dans un domaine bien diff\u00e9rent de celui de la Dre McCunn. On pourrait dire que l\u2019un et l\u2019autre repr\u00e9sentent les deux principales branches de la psychologie de l\u2019environnement \u2013 la psychologie de l\u2019architecture (Dre McCunn) et la psychologie de l\u2019\u00e9cologie (Dr Zelenski). \u00ab En plus d\u2019\u00eatre un psychologue de l\u2019environnement, je me consid\u00e8re aussi comme un psychologue de la personnalit\u00e9 qui se r\u00e9clame de la psychologie positive. Je me suis beaucoup int\u00e9ress\u00e9 \u00e0 ce que nous appelons le rapport \u00e0 la nature, ou ce que d\u2019autres appellent \u201cla connexion avec la nature\u201d. Je parle ici des impressions subjectives des gens : font-ils partie de la nature ou la nature est-elle distincte d\u2019eux et n\u2019a pas grand-chose \u00e0 voir avec leur perception d\u2019eux-m\u00eames? Je me suis aussi beaucoup int\u00e9ress\u00e9 de fa\u00e7on g\u00e9n\u00e9rale par ce que j\u2019appelle un \u201cchemin heureux vers la durabilit\u00e9\u201d. C\u2019est l\u2019id\u00e9e que nous savons que la nature est capable de rendre les gens de bonne humeur. La nature est associ\u00e9e au bonheur, tant sur de longues p\u00e9riodes que sur le moment. Nous savons que les gens qui passent beaucoup de temps dans la nature et qui se sentent tr\u00e8s li\u00e9s \u00e0 la nature adoptent des comportements proenvironnement et \u00e9cologiquement durables. Au cours des derni\u00e8res ann\u00e9es, nous avons commenc\u00e9 \u00e0 penser que l\u2019inverse est peut-\u00eatre vrai aussi. Si l\u2019on peut amener les gens \u00e0 faire quelques petits gestes pour la nature, en adoptant des comportements \u00e9cologiquement durables, il serait possible de se servir de cela pour qu\u2019ils se sentent plus proches de la nature et plus heureux de pratiquer ces activit\u00e9s. Nous pensons que les actions en faveur de l\u2019environnement ne doivent pas n\u00e9cessairement \u00eatre on\u00e9reuses et que nous pouvons les associer \u00e0 des \u00e9motions positives. \u00bb Ce que \u00ab consacrer du temps dans la nature \u00bb signifie pour chaque personne est subjectif. Il s\u2019agit peut-\u00eatre de prendre un week-end pour faire de la randonn\u00e9e dans les collines, de passer une journ\u00e9e \u00e0 p\u00eacher sur la glace ou simplement d\u2019aller dans son jardin et s\u2019occuper de son potager de radis. Pour la Dre McCunn, cela a entra\u00een\u00e9 de grands changements depuis le d\u00e9but de la pand\u00e9mie de COVID-19. Elle nous parle par Zoom dans ce qui semble \u00eatre un chalet dans les bois. Depuis quelques ann\u00e9es, elle et sa famille vivaient dans le centre-ville de Nanaimo, en Colombie-Britannique, en face du service d\u2019ambulance, du service de police et de la caserne de pompiers. Les sir\u00e8nes ont augment\u00e9 consid\u00e9rablement lorsque la pand\u00e9mie a commenc\u00e9, leurs habitudes de sommeil ont commenc\u00e9 \u00e0 en \u00eatre affect\u00e9es et ils ont d\u00e9cid\u00e9 de louer un endroit \u00e0 la campagne. \u00ab Ce fut en quelque sorte une bonne \u00e9tude de cas en psychologie de l\u2019environnement, dans la mesure o\u00f9 nous pouvions r\u00e9aliser ce qui nous stimulait dans notre environnement familial, puis d\u00e9cider comment le modifier pour notre sant\u00e9 mentale. Nous avons donc pens\u00e9 \u00e0 d\u00e9m\u00e9nager dans un cadre naturel plus vaste o\u00f9 nous pourrions avoir un peu plus de contr\u00f4le sur les choses qui nous stimulent. Nous avons \u00e9t\u00e9 tr\u00e8s chanceux de pouvoir louer quelque chose \u00e0 la campagne. C\u2019\u00e9tait int\u00e9ressant, parce que j\u2019\u00e9tais tr\u00e8s attach\u00e9e \u00e0 la maison que nous poss\u00e9dions. L\u2019une des choses que nous \u00e9tudions, comme psychologues de l\u2019environnement, est le \u201csentiment d\u2019appartenance\u201d ou un sentiment d\u2019appartenance \u00e0 un lieu, un sentiment identitaire ou un sentiment de d\u00e9pendance. Au d\u00e9but de la pand\u00e9mie, j\u2019ai entendu beaucoup de questions sur la fa\u00e7on dont les gens faisaient face au sentiment de perte qu\u2019ils ressentaient depuis qu\u2019ils travaillaient \u00e0 domicile. Pas seulement un sentiment de perte en rapport avec des \u00e9l\u00e9ments sociaux, mais aussi une perte des moyens habituels par lesquels ils se rendaient \u00e0 leur lieu de travail. Peut-\u00eatre prenaient-ils le m\u00eame autobus tous les jours ou arr\u00eataient-ils au m\u00eame caf\u00e9 lorsqu\u2019ils se rendaient \u00e0 l\u2019\u00e9cole ou au travail. M\u00eame le caract\u00e8re physique de l\u2019environnement de bureau ou de la salle de classe elle-m\u00eame \u2013 cet environnement leur manquait. Je me suis donc demand\u00e9 comment je r\u00e9agirais lorsque je m\u2019\u00e9loignerais de mon environnement familier auquel je m\u2019\u00e9tais vraiment attach\u00e9. Je ne voulais pas me mettre dans une position o\u00f9 je perdrais mon lien avec mon cadre habituel, mais je me suis rapidement attach\u00e9e \u00e0 cet endroit et aux caract\u00e9ristiques naturelles qui l\u2019entourent. Ce fut une belle aventure d\u2019explorer la psychologie de l\u2019environnement de l\u2019int\u00e9rieur et dans ce contexte. \u00bb Se sentir proche de la nature, ce peut \u00eatre aussi simple que de pouvoir sortir et toucher \u00e0 un arbre, ou regarder par la fen\u00eatre une montagne ou une vari\u00e9t\u00e9 d\u2019esp\u00e8ces d\u2019oiseaux. Alors, comment cela peut-il se traduire par des comportements plus respectueux de l\u2019environnement, au moment o\u00f9 le changement climatique est devenu le probl\u00e8me le plus urgent de notre \u00e9poque? Le Dr Zelenski donne l\u2019exemple que voici. \u00ab Nous avons beaucoup de bonnes preuves circonstancielles et d\u2019\u00e9tudes de laboratoire, et nous essayons de les assembler. Quelques programmes ont \u00e9t\u00e9 prometteurs! Mon ancienne \u00e9tudiante, amie et collaboratrice, Lisa Nisbet, a collabor\u00e9 avec la Fondation David Suzuki pour relever le D\u00e9fi nature 30\u00d730. Ce d\u00e9fi consiste \u00e0 consacrer 30 minutes dans la nature chaque jour pendant 30 jours. Les personnes qui s\u2019inscrivent \u00e0 ce d\u00e9fi ont tendance \u00e0 \u00eatre plut\u00f4t \u00e9cologistes et d\u00e9j\u00e0 tr\u00e8s proches de la nature. Mais au cours de ce mois, cette connexion semble se d\u00e9velopper. Ce n\u2019est pas un essai contr\u00f4l\u00e9 randomis\u00e9, mais il semble que le fait de passer du temps dans la nature donne \u00e0 ces personnes le sentiment d\u2019\u00eatre plus proches, ce qui les incite \u00e0 adopter des comportements \u00e9cologiquement durables. \u00bb L\u2019\u00e9cologie est une division de la psychologie de l\u2019environnement (relativement) nouvelle, et elle a sans aucun doute pris beaucoup d\u2019ampleur au cours des 20 derni\u00e8res ann\u00e9es, les changements climatiques \u00e9tant rapidement devenus un sujet de premier plan pour beaucoup d\u2019entre nous. Le Dr Zelenski n\u2019est pas le seul \u00e0 avoir \u00e9volu\u00e9 dans cette direction. \u00ab L\u2019attention et l\u2019importance accord\u00e9es \u00e0 l\u2019aspect \u00e9cologique de la psychologie de l\u2019environnement semblent s\u2019\u00eatre accrues au cours des 10 ou 15 derni\u00e8res ann\u00e9es. Je suis venu \u00e0 la psychologie \u00e9cologique apr\u00e8s mon doctorat, par simple int\u00e9r\u00eat personnel, et j\u2019ai l\u2019impression d\u2019\u00eatre l\u2019un des millions de personnes qui ont suivi le mouvement, et ce, pour plusieurs raisons. Les gens semblent de plus en plus manifester des sympt\u00f4mes de d\u00e9pression, d\u2019anxi\u00e9t\u00e9, etc., et la nature semble offrir un r\u00e9pit agr\u00e9able. De plus, la prise de conscience relative aux changements climatiques ne cesse de cro\u00eetre, car nous en voyons de plus en plus les effets. Et les d\u00e9cideurs politiques souhaitent savoir ce que les sciences sociales peuvent apporter pour r\u00e9soudre ces probl\u00e8mes. \u00bb La dimension \u00e9cologique de la discipline a \u00e9man\u00e9 naturellement de la branche traditionnelle de la psychologie de l\u2019architecture, qui existe depuis les ann\u00e9es 1960. Selon la Dre McCunn, il existe quelques programmes d\u2019\u00e9tudes sup\u00e9rieures officiels en \u00ab psychologie de l\u2019environnement \u00bb au Canada, mais il y en a plus en Angleterre et aux \u00c9tats-Unis, aux Pays-Bas et en Am\u00e9rique du Sud. Donc, lorsqu\u2019elle dit aux gens qu\u2019elle est une \u00ab psychologue de l\u2019environnement \u00bb, ceux-ci savent souvent ce qu\u2019elle veut dire. \u00ab Certaines personnes, \u00e0 juste titre, divisent la dimension de la psychologie de l\u2019architecture et la dimension de la psychologie de l\u2019\u00e9cologie. Je le fais aussi si je veux expliquer aux gens ce que j\u2019\u00e9tudie, parce que je suis plut\u00f4t du c\u00f4t\u00e9 de l\u2019architecture. Je travaille avec des ing\u00e9nieurs, des gestionnaires d\u2019installations et des urbanistes, mais j\u2019ai aussi des coll\u00e8gues, comme John, qui s\u2019int\u00e9ressent au lien avec la nature et travaillent avec des personnes qui \u00e9tudient les attitudes et les comportements proenvironnement. L\u2019id\u00e9e de conservation de la nature est devenue tr\u00e8s populaire dans le domaine de la psychologie de l\u2019environnement, sans pour autant prendre le pas sur la dimension architecturale, qui s\u2019int\u00e9resse \u00e0 l\u2019infrastructure des immeubles, etc. En fait, la psychologie de l\u2019environnement a d\u00e9but\u00e9 dans le contexte de l\u2019architecture, mais elle s\u2019est largement \u00e9tendue \u00e0 son autre volet, qui consiste \u00e0 poser aux gens des questions sur leur conscience \u00e9cologique et leur rapport \u00e0 la nature. \u00bb Les deux branches vont de pair. Pensez \u00e0 la tendance \u00e0 construire des b\u00e2timents \u00ab verts \u00bb, avec du chauffage \u00e0 faible consommation d\u2019\u00e9nergie, des panneaux solaires, voire un jardin sur le toit. Selon la Dre McCunn, \u00ab Quand un ing\u00e9nieur me demande : \u201cdevrions-nous concevoir ce b\u00e2timent en tenant compte de la durabilit\u00e9\u201d, il veut en r\u00e9alit\u00e9 savoir \u2013 \u201cles gens vont-ils le remarquer? S\u2019en soucient-ils? Vont-ils apporter des changements \u00e0 leurs comportements \u00e0 l\u2019int\u00e9rieur (et \u00e0 l\u2019ext\u00e9rieur) de l\u2019immeuble pour cette raison?\u201d Je peux les aider \u00e0 \u00e9tudier la mani\u00e8re dont les gens se comportent, travaillent et fonctionnent dans des b\u00e2timents plus (ou moins) durables. J\u2019ai fait une \u00e9tude dans une \u00e9cole d\u2019\u00e9tudes sup\u00e9rieures qui a montr\u00e9 que le fait qu\u2019un immeuble de bureaux soit \u201cvert\u201d ou durable ne signifie pas n\u00e9cessairement que cela permettra de pr\u00e9dire une forte productivit\u00e9 ou une forte satisfaction. Il est important de garder un \u0153il critique sur ce que l\u2019on attend d\u2019une conception durable et sur ce que l\u2019on n\u2019attend pas. \u00bb Pensez \u00e0 des espaces dans lesquels vous vous \u00eates sentis imm\u00e9diatement \u00e0 l\u2019aise avec les personnes qui vous entouraient \u2013 et d\u2019autres o\u00f9 ce n\u2019\u00e9tait pas le cas. Il est possible que ce ne soit pas les personnes pr\u00e9sentes qui en soient la cause, mais la conception de l\u2019espace qui a rendu les interactions plus embarrassantes, ou qui a rendu cette pi\u00e8ce, ce b\u00e2timent ou ce wagon plus confortable. La Dre McClunn pr\u00e9cise. \u00ab Si l\u2019on veut qu\u2019un certain espace soit accueillant et confortable, on peut le concevoir pour qu\u2019un certain nombre de personnes puissent s\u2019y asseoir \u00e0 une certaine distance. Je pense \u00e0 la conception d\u2019un caf\u00e9, ou un restaurant ou m\u00eame une salle de classe o\u00f9 l\u2019on veut que les gens s\u2019assoient d\u2019une certaine fa\u00e7on et cohabitent d\u2019une certaine mani\u00e8re. Je pense qu\u2019il est important d\u2019utiliser diff\u00e9rentes m\u00e9thodes, tout comme les autres psychologues le font. Nous sommes capables d\u2019int\u00e9grer une vari\u00e9t\u00e9 de m\u00e9thodes combin\u00e9es dans notre travail. Nous utilisons l\u2019observation naturaliste pour observer et voir comment les gens se d\u00e9placent et se comportent dans un espace afin de prendre des d\u00e9cisions de conception \u00e0 partir de nos observations. Nous effectuons beaucoup de sondages et d\u2019entrevues et, \u00e0 partir de ceux-ci, nous pouvons aider les architectes et les concepteurs \u00e0 rendre les b\u00e2timents les plus humains possible. Si l\u2019objet du travail clinique et d\u2019autres types d\u2019intervention psychologique est d\u2019aider les gens \u00e0 se sentir bien, alors la psychologie de l\u2019environnement est tout \u00e0 fait en phase avec cela. Nous voulons que les b\u00e2timents soient con\u00e7us de mani\u00e8re \u00e0 aider les gens \u00e0 se sentir aussi bien, motiv\u00e9s, enthousiastes et en forme que possible. \u00bb Le Dr Zelenski jette \u00e9galement un pont entre les deux c\u00f4t\u00e9s de la psychologie de l\u2019environnement, et ce, de diff\u00e9rentes mani\u00e8res. La collaboration avec des groupes qui font d\u00e9j\u00e0 un travail environnemental lui permet de recueillir plus facilement des donn\u00e9es, et l\u2019analyse de ces donn\u00e9es permet \u00e0 ces groupes de fonctionner de mani\u00e8re plus efficace et efficiente. \u00ab J\u2019ai collabor\u00e9 avec un architecte, faisant ainsi le pont entre ces deux composantes de la psychologie de l\u2019environnement. Il \u00e9tait tr\u00e8s int\u00e9ress\u00e9 par la construction de b\u00e2timents qui donneraient envie aux gens de se comporter de mani\u00e8re \u00e9cologique. De m\u00eame, il ne s\u2019agit peut-\u00eatre pas seulement de l\u2019int\u00e9rieur du b\u00e2timent, mais aussi des espaces naturels proches du b\u00e2timent qui pourraient encourager ces comportements. Il s\u2019agit de poser une question plus nuanc\u00e9e sur les types de milieux naturels \u00e0 proximit\u00e9 qui pourraient aider les gens \u00e0 se sentir mieux, \u00e0 \u00eatre plus heureux et plus productifs. Il y a un petit organisme sans but lucratif qui fournit des trousses d\u2019analyse de l\u2019eau. Il les distribue aux gens, qui les utilisent pour tester la qualit\u00e9 de l\u2019eau \u00e0 proximit\u00e9; les gens t\u00e9l\u00e9chargent ensuite leurs donn\u00e9es dans un genre de base de donn\u00e9es participative qui permet de voir si le lac ou la rivi\u00e8re pr\u00e8s de chez eux est en bon ou en mauvais \u00e9tat, et comment cela \u00e9volue au fil du temps. Il serait difficile pour moi de monter une exp\u00e9rience dans laquelle je distribuerais des tas de trousses d\u2019analyse de l\u2019eau, mais je peux essayer de suivre les personnes qui le font d\u00e9j\u00e0 pour voir si cela change leur sentiment de connexion avec la nature, si cela les rend heureux et si cela leur donne envie de faire d\u2019autres choses bonnes pour l\u2019environnement que de simplement tester l\u2019eau. \u00bb Depuis la mise en place de mesures de confinement en raison de la pand\u00e9mie, nous entendons beaucoup de personnes dire qu\u2019elles appr\u00e9cient davantage la nature. C\u2019est un moyen s\u00fbr de sortir de chez soi. Si on ne peut pas aller dans un centre commercial bond\u00e9 ou \u00e0 un concert, on peut toujours aller dans un parc et se promener. Les gens voient la nature comme une source de bien-\u00eatre et un bon moyen de s\u2019adapter, et certaines \u00e9tudes indiquent que la nature est l\u2019une des choses les plus positives que les gens ont ressenties au cours des deux derni\u00e8res ann\u00e9es, o\u00f9 la distanciation physique \u00e9tait impos\u00e9e. Mais ce lien avec la nature, ainsi que la prise de conscience de la grave menace que repr\u00e9sente le changement climatique, cr\u00e9e \u00e0 certains \u00e9gards de nouveaux probl\u00e8mes. Selon le Dr Zelenski, \u00ab Beaucoup de gens parlent d\u2019\u00e9coanxi\u00e9t\u00e9 et le fait que les gens soient de plus en plus conscients des changements climatiques pourrait \u00eatre une arme \u00e0 double tranchant. Cela peut donc \u00eatre motivant \u2013 ce qui est un r\u00e9sultat positif, les gens voulant se comporter d\u2019une mani\u00e8re plus \u00e9cologique \u2013 mais certaines personnes pourraient \u00eatre boulevers\u00e9es ou inqui\u00e8tes \u00e0 tel point que cela cr\u00e9era de nouvelles formes de stress et d\u2019inqui\u00e9tude qui, chez elles, peuvent \u00eatre inadapt\u00e9es. \u00bb L\u2019un des moyens de lutter contre l\u2019\u00e9coanxi\u00e9t\u00e9, un nouveau mot \u00e0 la mode dans le domaine de la pr\u00e9servation de l\u2019environnement, consiste \u00e0 faire conna\u00eetre les psychologues de l\u2019environnement et \u00e0 solliciter leurs conseils. Cette sensibilisation accrue se ressent \u00e9galement dans la dimension architecturale, car les contributions des experts de ce domaine sont maintenant per\u00e7ues par beaucoup comme \u00e9tant inestimables. La Dre McCunn dit qu\u2019elle a vu ce changement directement. \u00ab Lorsque je rencontre des ing\u00e9nieurs, des architectes et des urbanistes, je constate qu\u2019ils sont davantage sensibili\u00e9s \u00e0 la psychologie de l\u2019environnement et qu\u2019ils sont tout \u00e0 fait dispos\u00e9s \u00e0 travailler avec nous. Lorsque je faisais ma ma\u00eetrise, j\u2019ai remarqu\u00e9 que tr\u00e8s peu de personnes occupant ces postes voulaient travailler avec un sp\u00e9cialiste en sciences sociales. Plusieurs d\u2019entre eux disaient qu\u2019ils faisaient ce genre de recherche accessoirement, et qu\u2019ils \u201csavaient d\u00e9j\u00e0 comment \u00e9tudier les gens\u201d. Aujourd\u2019hui, ils font appel \u00e0 moi car ils veulent int\u00e9grer cette dimension professionnelle \u00e0 leur activit\u00e9 ou \u00e0 leurs processus. La cognition spatiale, par exemple, est un sujet tr\u00e8s habituel en psychologie de l\u2019environnement. Je pense qu\u2019il est important de le mentionner car la population vieillit. Les psychologues de l\u2019environnement consultent souvent les concepteurs pour savoir comment aider les personnes atteintes de d\u00e9mence \u00e0 s\u2019orienter dans une maison de soins, par exemple. Nous pouvons les observer et les aider avec des pancartes et des symboles, et des moyens d\u2019int\u00e9grer leur psychologie dans la conception pour leur faciliter la vie. \u00bb \u00cates-vous d\u00e9j\u00e0 all\u00e9 dans un magasin o\u00f9 il y a, sur le sol, un motif tr\u00e8s simple qui se transforme un peu \u00e0 l\u2019approche des toilettes, et un peu plus pr\u00e8s de la caisse? Peut-\u00eatre y a-t-il des rampes d\u2019escalier de couleur vive le long des murs, et le si\u00e8ge des toilettes est-il d\u2019une couleur nettement diff\u00e9rente du reste des toilettes. Le magasin est bien \u00e9clair\u00e9, mais pas trop, car il y a peu de surfaces r\u00e9fl\u00e9chissantes et pas de miroirs. Un magasin qui ressemble \u00e0 \u00e7a a probablement \u00e9t\u00e9 con\u00e7u pour \u00eatre accessible aux personnes atteintes de d\u00e9mence, avec l\u2019aide de psychologues de l\u2019environnement. Les personnes atteintes de la maladie d\u2019Alzheimer et de diff\u00e9rents types de d\u00e9mence sont g\u00e9n\u00e9ralement suivies par une \u00e9quipe de soins, notamment par un neuroscientifique (voir le portrait de la neuropsychologie clinique pr\u00e9sent\u00e9 plus t\u00f4t ce mois-ci). De plus en plus, les psychologues de l\u2019environnement travaillent au sein d\u2019\u00e9quipes interdisciplinaires plus larges, et les neurosciences elles-m\u00eames prennent une place plus importante dans la discipline. La Dre McCunn dit qu\u2019elle le constate gr\u00e2ce aux articles propos\u00e9s au Journal of Environmental Psychology. \u00ab Il y a beaucoup d\u2019articles qui fusionnent les neurosciences et la psychologie de l\u2019environnement. Je fais aussi cela dans mon propre travail \u2013 j\u2019ai presque termin\u00e9 une deuxi\u00e8me ma\u00eetrise en neurosciences appliqu\u00e9es, simplement pour approfondir mes recherches dans le domaine des neurosciences environnementales. J\u2019aime chercher \u00e0 comprendre des concepts tels que \u201cque se passe-t-il dans le cerveau lorsque nous ressentons un attachement \u00e0 un lieu? Est-ce diff\u00e9rent de l\u2019attachement que l\u2019on ressent face \u00e0 une personne? Que se passe-t-il dans le cerveau lorsque nous rencontrons diff\u00e9rents contextes?\u201d Ce sont des questions importantes qui, je pense, sont de plus en plus populaires. \u00bb La psychologie de l\u2019environnement devenant une discipline de plus en plus demand\u00e9e, l\u2019expertise des personnes travaillant dans ce domaine est appliqu\u00e9e \u00e0 une vari\u00e9t\u00e9 de sujets sans cesse croissante. La Dre McCunn esp\u00e8re que cette tendance se poursuivra, afin que l\u2019ensemble des comp\u00e9tences de ses coll\u00e8gues puisse \u00eatre utilis\u00e9 pour aider \u00e0 r\u00e9soudre des probl\u00e8mes importants. \u00ab Je souhaite que la psychologie de l\u2019environnement fasse partie d\u2019un grand nombre d\u2019\u00e9quipes tr\u00e8s diverses. Bien s\u00fbr, les architectes et les urbanistes, mais aussi les cliniciens, les m\u00e9decins, les neuroscientifiques, etc. Je crois que nous sommes de bons partenaires et nous pouvons ajouter des facettes aux questions de recherche qui peuvent enrichir une r\u00e9ponse et la rendre plus compl\u00e8te. Il est tr\u00e8s difficile de tirer des conclusions \u00e0 partir de quelques variables seulement. La mobilisation des donn\u00e9es et de la mod\u00e9lisation dans le domaine de la psychologie de l\u2019environnement peut nous aider \u00e0 aider les autres \u00e0 obtenir des r\u00e9ponses plus fiables \u00e0 de vastes questions de soci\u00e9t\u00e9 sur ce qui pousse les gens \u00e0 agir et \u00e0 penser de telle ou telle mani\u00e8re. J\u2019aimerais voir la psychologie de l\u2019environnement mettre \u00e0 contribution son expertise dans toutes sortes de contextes et dans toutes sortes d\u2019\u00e9quipes. \u00bb Mais soyez rassur\u00e9 \u2013 si un psychologue de l\u2019environnement se retrouve chez vous, il ne jugera pas la disposition de votre argenterie ni l\u2019endroit o\u00f9 vous avez plac\u00e9 votre sauci\u00e8re, \u00e0 c\u00f4t\u00e9 du pot de Nutella. Du moins, pas plus que n\u2019importe qui d\u2019autre.\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"CPA Webmaster\"\/>\n\t<link rel=\"canonical\" href=\"https:\/\/cpa.ca\/fr\/psychology-month-profile-dr-lindsay-mccunn-and-dr-john-zelenski-environmental-psychology\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 4.9.9\" \/>\n\t\t<meta property=\"og:locale\" content=\"fr_FR\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Canadian Psychological Association - The national voice for psychology in Canada\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Profils du Mois de la psychologie : Dre Lindsay McCunn et Dr John Zelenski, Environmental Psychology - Canadian Psychological Association\" \/>\n\t\t<meta property=\"og:description\" content=\"Dre Lindsay McCunn Dr. John Zelenski Dre Lindsay McCunn et Dr John Zelenski, Environmental Psychology La psychologie de l\u2019environnement compte deux branches principales. Nous avons parl\u00e9 \u00e0 la Dre Lindsay McCunn de la branche de la psychologie de l\u2019architecture (la conception de b\u00e2timents et de pi\u00e8ces pour le bien-\u00eatre des occupants) et au Dr John Zelenski, de la psychologie \u00e9cologique (qui s\u2019int\u00e9resse aux comportements \u00e9cologiquement durables par l\u2019interm\u00e9diaire de la connexion des gens \u00e0 la nature). \u00c0 propos de Dre Lindsay McCunn et Dr John Zelenski Psychologie de l\u2019environnement \u00ab Quand je dis que je ne vous juge pas, je pense que je veux vraiment dire \u201cpas plus que les autres.\u201d \u00bb. Je suis un peu nerveux \u00e0 l\u2019id\u00e9e que, pendant notre r\u00e9union Zoom, la Dre Lindsay McCunn et le Dr John Zelenski puissent juger mon arri\u00e8re-plan, d\u00e9cid\u00e9ment tr\u00e8s encombr\u00e9. Tous mes appareils \u00e9lectrom\u00e9nagers sont plac\u00e9s sur une tablette derri\u00e8re moi, ce qui donne l\u2019impression (exacte, il se trouve) que mon bureau \u00e0 domicile est un coin exigu pr\u00e8s de la cuisine. La Dre McCunn et le Dr Zelenski sont des psychologues de l\u2019environnement, c\u2019est-\u00e0-dire des sp\u00e9cialistes des espaces que nous occupons et de la mani\u00e8re dont nous interagissons avec eux. Le Dr Zelenski est plut\u00f4t gentil et honn\u00eate \u2013 en tant qu\u2019\u00eatres humains, nous percevons des indices subtils, \u00e0 partir des espaces de chacun, mais cela n\u2019est probablement pas propre aux psychologues de l\u2019environnement. Nous jugeons tous les arri\u00e8re-plans Zoom, ne serait-ce qu\u2019un peu. La Dre Lindsay McCunn est professeure de psychologie \u00e0 l\u2019Universit\u00e9 Vancouver Island. Elle est la pr\u00e9sidente de la Section de psychologie de l\u2019environnement de la SCP et la r\u00e9dactrice en chef adjointe du Journal of Environmental Psychology. Selon elle, les arri\u00e8re-plans Zoom des gens ou la fa\u00e7on dont ils am\u00e9nagent leurs jardins ou leurs espaces de vie sont sources de curiosit\u00e9 pour chacun d\u2019entre nous. \u00ab La fa\u00e7on dont les gens s\u2019expriment, organisent leur domicile et placent des objets importants est vraiment int\u00e9ressante. Sam Gosling a \u00e9crit un livre intitul\u00e9 Snoopologie; il s\u2019agit d\u2019une \u00e9tude portant sur la fa\u00e7on dont on peut d\u00e9duire la personnalit\u00e9 et la fa\u00e7on de penser des gens en fonction de la mani\u00e8re dont ils rangent leurs bibelots et leurs affaires dans leur maison et leur bureau. \u00bb La Dre McCunn se sp\u00e9cialise en psychologie de l\u2019environnement et d\u00e9crit ainsi sa sp\u00e9cialit\u00e9. \u00ab La psychologie de l\u2019environnement, c\u2019est l\u2019\u00e9tude des transactions entre les personnes et les lieux. Et j\u2019entends par l\u00e0 beaucoup de types d\u2019endroits \u2013 un caf\u00e9, un bureau, une \u00e9cole, un parc, un oc\u00e9an, une montagne. Nous \u00e9tudions les diff\u00e9rentes fa\u00e7ons dont les gens interagissent avec leur environnement. De la m\u00eame mani\u00e8re qu\u2019un psychologue social \u00e9tudie et analyse les relations et les interactions entre les individus et les autres, les psychologues de l\u2019environnement \u00e9tudient et analysent les relations entre les personnes et les lieux. Dans mes recherches, je m\u2019int\u00e9resse \u00e0 la fa\u00e7on dont les gens interagissent dans les collectivit\u00e9s et les milieux de travail, en particulier dans les h\u00f4pitaux, les \u00e9coles et les bureaux. \u00c0 ce titre, je me penche sur le personnel, principalement, et sur les personnes qui utilisent les environnements d\u2019une mani\u00e8re diff\u00e9rente de celle \u00e0 laquelle on pourrait s\u2019attendre, comme les \u00e9tudiants et les patients, les enseignants, etc. \u00bb. Le Dr John Zelenski est professeur au d\u00e9partement de psychologie de l\u2019Universit\u00e9 Carleton. Il est \u00e9galement un psychologue de l\u2019environnement, mais il se sp\u00e9cialise dans un domaine bien diff\u00e9rent de celui de la Dre McCunn. On pourrait dire que l\u2019un et l\u2019autre repr\u00e9sentent les deux principales branches de la psychologie de l\u2019environnement \u2013 la psychologie de l\u2019architecture (Dre McCunn) et la psychologie de l\u2019\u00e9cologie (Dr Zelenski). \u00ab En plus d\u2019\u00eatre un psychologue de l\u2019environnement, je me consid\u00e8re aussi comme un psychologue de la personnalit\u00e9 qui se r\u00e9clame de la psychologie positive. Je me suis beaucoup int\u00e9ress\u00e9 \u00e0 ce que nous appelons le rapport \u00e0 la nature, ou ce que d\u2019autres appellent \u201cla connexion avec la nature\u201d. Je parle ici des impressions subjectives des gens : font-ils partie de la nature ou la nature est-elle distincte d\u2019eux et n\u2019a pas grand-chose \u00e0 voir avec leur perception d\u2019eux-m\u00eames? Je me suis aussi beaucoup int\u00e9ress\u00e9 de fa\u00e7on g\u00e9n\u00e9rale par ce que j\u2019appelle un \u201cchemin heureux vers la durabilit\u00e9\u201d. C\u2019est l\u2019id\u00e9e que nous savons que la nature est capable de rendre les gens de bonne humeur. La nature est associ\u00e9e au bonheur, tant sur de longues p\u00e9riodes que sur le moment. Nous savons que les gens qui passent beaucoup de temps dans la nature et qui se sentent tr\u00e8s li\u00e9s \u00e0 la nature adoptent des comportements proenvironnement et \u00e9cologiquement durables. Au cours des derni\u00e8res ann\u00e9es, nous avons commenc\u00e9 \u00e0 penser que l\u2019inverse est peut-\u00eatre vrai aussi. Si l\u2019on peut amener les gens \u00e0 faire quelques petits gestes pour la nature, en adoptant des comportements \u00e9cologiquement durables, il serait possible de se servir de cela pour qu\u2019ils se sentent plus proches de la nature et plus heureux de pratiquer ces activit\u00e9s. Nous pensons que les actions en faveur de l\u2019environnement ne doivent pas n\u00e9cessairement \u00eatre on\u00e9reuses et que nous pouvons les associer \u00e0 des \u00e9motions positives. \u00bb Ce que \u00ab consacrer du temps dans la nature \u00bb signifie pour chaque personne est subjectif. Il s\u2019agit peut-\u00eatre de prendre un week-end pour faire de la randonn\u00e9e dans les collines, de passer une journ\u00e9e \u00e0 p\u00eacher sur la glace ou simplement d\u2019aller dans son jardin et s\u2019occuper de son potager de radis. Pour la Dre McCunn, cela a entra\u00een\u00e9 de grands changements depuis le d\u00e9but de la pand\u00e9mie de COVID-19. Elle nous parle par Zoom dans ce qui semble \u00eatre un chalet dans les bois. Depuis quelques ann\u00e9es, elle et sa famille vivaient dans le centre-ville de Nanaimo, en Colombie-Britannique, en face du service d\u2019ambulance, du service de police et de la caserne de pompiers. Les sir\u00e8nes ont augment\u00e9 consid\u00e9rablement lorsque la pand\u00e9mie a commenc\u00e9, leurs habitudes de sommeil ont commenc\u00e9 \u00e0 en \u00eatre affect\u00e9es et ils ont d\u00e9cid\u00e9 de louer un endroit \u00e0 la campagne. \u00ab Ce fut en quelque sorte une bonne \u00e9tude de cas en psychologie de l\u2019environnement, dans la mesure o\u00f9 nous pouvions r\u00e9aliser ce qui nous stimulait dans notre environnement familial, puis d\u00e9cider comment le modifier pour notre sant\u00e9 mentale. Nous avons donc pens\u00e9 \u00e0 d\u00e9m\u00e9nager dans un cadre naturel plus vaste o\u00f9 nous pourrions avoir un peu plus de contr\u00f4le sur les choses qui nous stimulent. Nous avons \u00e9t\u00e9 tr\u00e8s chanceux de pouvoir louer quelque chose \u00e0 la campagne. C\u2019\u00e9tait int\u00e9ressant, parce que j\u2019\u00e9tais tr\u00e8s attach\u00e9e \u00e0 la maison que nous poss\u00e9dions. L\u2019une des choses que nous \u00e9tudions, comme psychologues de l\u2019environnement, est le \u201csentiment d\u2019appartenance\u201d ou un sentiment d\u2019appartenance \u00e0 un lieu, un sentiment identitaire ou un sentiment de d\u00e9pendance. Au d\u00e9but de la pand\u00e9mie, j\u2019ai entendu beaucoup de questions sur la fa\u00e7on dont les gens faisaient face au sentiment de perte qu\u2019ils ressentaient depuis qu\u2019ils travaillaient \u00e0 domicile. Pas seulement un sentiment de perte en rapport avec des \u00e9l\u00e9ments sociaux, mais aussi une perte des moyens habituels par lesquels ils se rendaient \u00e0 leur lieu de travail. Peut-\u00eatre prenaient-ils le m\u00eame autobus tous les jours ou arr\u00eataient-ils au m\u00eame caf\u00e9 lorsqu\u2019ils se rendaient \u00e0 l\u2019\u00e9cole ou au travail. M\u00eame le caract\u00e8re physique de l\u2019environnement de bureau ou de la salle de classe elle-m\u00eame \u2013 cet environnement leur manquait. Je me suis donc demand\u00e9 comment je r\u00e9agirais lorsque je m\u2019\u00e9loignerais de mon environnement familier auquel je m\u2019\u00e9tais vraiment attach\u00e9. Je ne voulais pas me mettre dans une position o\u00f9 je perdrais mon lien avec mon cadre habituel, mais je me suis rapidement attach\u00e9e \u00e0 cet endroit et aux caract\u00e9ristiques naturelles qui l\u2019entourent. Ce fut une belle aventure d\u2019explorer la psychologie de l\u2019environnement de l\u2019int\u00e9rieur et dans ce contexte. \u00bb Se sentir proche de la nature, ce peut \u00eatre aussi simple que de pouvoir sortir et toucher \u00e0 un arbre, ou regarder par la fen\u00eatre une montagne ou une vari\u00e9t\u00e9 d\u2019esp\u00e8ces d\u2019oiseaux. Alors, comment cela peut-il se traduire par des comportements plus respectueux de l\u2019environnement, au moment o\u00f9 le changement climatique est devenu le probl\u00e8me le plus urgent de notre \u00e9poque? Le Dr Zelenski donne l\u2019exemple que voici. \u00ab Nous avons beaucoup de bonnes preuves circonstancielles et d\u2019\u00e9tudes de laboratoire, et nous essayons de les assembler. Quelques programmes ont \u00e9t\u00e9 prometteurs! Mon ancienne \u00e9tudiante, amie et collaboratrice, Lisa Nisbet, a collabor\u00e9 avec la Fondation David Suzuki pour relever le D\u00e9fi nature 30\u00d730. Ce d\u00e9fi consiste \u00e0 consacrer 30 minutes dans la nature chaque jour pendant 30 jours. Les personnes qui s\u2019inscrivent \u00e0 ce d\u00e9fi ont tendance \u00e0 \u00eatre plut\u00f4t \u00e9cologistes et d\u00e9j\u00e0 tr\u00e8s proches de la nature. Mais au cours de ce mois, cette connexion semble se d\u00e9velopper. Ce n\u2019est pas un essai contr\u00f4l\u00e9 randomis\u00e9, mais il semble que le fait de passer du temps dans la nature donne \u00e0 ces personnes le sentiment d\u2019\u00eatre plus proches, ce qui les incite \u00e0 adopter des comportements \u00e9cologiquement durables. \u00bb L\u2019\u00e9cologie est une division de la psychologie de l\u2019environnement (relativement) nouvelle, et elle a sans aucun doute pris beaucoup d\u2019ampleur au cours des 20 derni\u00e8res ann\u00e9es, les changements climatiques \u00e9tant rapidement devenus un sujet de premier plan pour beaucoup d\u2019entre nous. Le Dr Zelenski n\u2019est pas le seul \u00e0 avoir \u00e9volu\u00e9 dans cette direction. \u00ab L\u2019attention et l\u2019importance accord\u00e9es \u00e0 l\u2019aspect \u00e9cologique de la psychologie de l\u2019environnement semblent s\u2019\u00eatre accrues au cours des 10 ou 15 derni\u00e8res ann\u00e9es. Je suis venu \u00e0 la psychologie \u00e9cologique apr\u00e8s mon doctorat, par simple int\u00e9r\u00eat personnel, et j\u2019ai l\u2019impression d\u2019\u00eatre l\u2019un des millions de personnes qui ont suivi le mouvement, et ce, pour plusieurs raisons. Les gens semblent de plus en plus manifester des sympt\u00f4mes de d\u00e9pression, d\u2019anxi\u00e9t\u00e9, etc., et la nature semble offrir un r\u00e9pit agr\u00e9able. De plus, la prise de conscience relative aux changements climatiques ne cesse de cro\u00eetre, car nous en voyons de plus en plus les effets. Et les d\u00e9cideurs politiques souhaitent savoir ce que les sciences sociales peuvent apporter pour r\u00e9soudre ces probl\u00e8mes. \u00bb La dimension \u00e9cologique de la discipline a \u00e9man\u00e9 naturellement de la branche traditionnelle de la psychologie de l\u2019architecture, qui existe depuis les ann\u00e9es 1960. Selon la Dre McCunn, il existe quelques programmes d\u2019\u00e9tudes sup\u00e9rieures officiels en \u00ab psychologie de l\u2019environnement \u00bb au Canada, mais il y en a plus en Angleterre et aux \u00c9tats-Unis, aux Pays-Bas et en Am\u00e9rique du Sud. Donc, lorsqu\u2019elle dit aux gens qu\u2019elle est une \u00ab psychologue de l\u2019environnement \u00bb, ceux-ci savent souvent ce qu\u2019elle veut dire. \u00ab Certaines personnes, \u00e0 juste titre, divisent la dimension de la psychologie de l\u2019architecture et la dimension de la psychologie de l\u2019\u00e9cologie. Je le fais aussi si je veux expliquer aux gens ce que j\u2019\u00e9tudie, parce que je suis plut\u00f4t du c\u00f4t\u00e9 de l\u2019architecture. Je travaille avec des ing\u00e9nieurs, des gestionnaires d\u2019installations et des urbanistes, mais j\u2019ai aussi des coll\u00e8gues, comme John, qui s\u2019int\u00e9ressent au lien avec la nature et travaillent avec des personnes qui \u00e9tudient les attitudes et les comportements proenvironnement. L\u2019id\u00e9e de conservation de la nature est devenue tr\u00e8s populaire dans le domaine de la psychologie de l\u2019environnement, sans pour autant prendre le pas sur la dimension architecturale, qui s\u2019int\u00e9resse \u00e0 l\u2019infrastructure des immeubles, etc. En fait, la psychologie de l\u2019environnement a d\u00e9but\u00e9 dans le contexte de l\u2019architecture, mais elle s\u2019est largement \u00e9tendue \u00e0 son autre volet, qui consiste \u00e0 poser aux gens des questions sur leur conscience \u00e9cologique et leur rapport \u00e0 la nature. \u00bb Les deux branches vont de pair. Pensez \u00e0 la tendance \u00e0 construire des b\u00e2timents \u00ab verts \u00bb, avec du chauffage \u00e0 faible consommation d\u2019\u00e9nergie, des panneaux solaires, voire un jardin sur le toit. Selon la Dre McCunn, \u00ab Quand un ing\u00e9nieur me demande : \u201cdevrions-nous concevoir ce b\u00e2timent en tenant compte de la durabilit\u00e9\u201d, il veut en r\u00e9alit\u00e9 savoir \u2013 \u201cles gens vont-ils le remarquer? S\u2019en soucient-ils? Vont-ils apporter des changements \u00e0 leurs comportements \u00e0 l\u2019int\u00e9rieur (et \u00e0 l\u2019ext\u00e9rieur) de l\u2019immeuble pour cette raison?\u201d Je peux les aider \u00e0 \u00e9tudier la mani\u00e8re dont les gens se comportent, travaillent et fonctionnent dans des b\u00e2timents plus (ou moins) durables. J\u2019ai fait une \u00e9tude dans une \u00e9cole d\u2019\u00e9tudes sup\u00e9rieures qui a montr\u00e9 que le fait qu\u2019un immeuble de bureaux soit \u201cvert\u201d ou durable ne signifie pas n\u00e9cessairement que cela permettra de pr\u00e9dire une forte productivit\u00e9 ou une forte satisfaction. Il est important de garder un \u0153il critique sur ce que l\u2019on attend d\u2019une conception durable et sur ce que l\u2019on n\u2019attend pas. \u00bb Pensez \u00e0 des espaces dans lesquels vous vous \u00eates sentis imm\u00e9diatement \u00e0 l\u2019aise avec les personnes qui vous entouraient \u2013 et d\u2019autres o\u00f9 ce n\u2019\u00e9tait pas le cas. Il est possible que ce ne soit pas les personnes pr\u00e9sentes qui en soient la cause, mais la conception de l\u2019espace qui a rendu les interactions plus embarrassantes, ou qui a rendu cette pi\u00e8ce, ce b\u00e2timent ou ce wagon plus confortable. La Dre McClunn pr\u00e9cise. \u00ab Si l\u2019on veut qu\u2019un certain espace soit accueillant et confortable, on peut le concevoir pour qu\u2019un certain nombre de personnes puissent s\u2019y asseoir \u00e0 une certaine distance. Je pense \u00e0 la conception d\u2019un caf\u00e9, ou un restaurant ou m\u00eame une salle de classe o\u00f9 l\u2019on veut que les gens s\u2019assoient d\u2019une certaine fa\u00e7on et cohabitent d\u2019une certaine mani\u00e8re. Je pense qu\u2019il est important d\u2019utiliser diff\u00e9rentes m\u00e9thodes, tout comme les autres psychologues le font. Nous sommes capables d\u2019int\u00e9grer une vari\u00e9t\u00e9 de m\u00e9thodes combin\u00e9es dans notre travail. Nous utilisons l\u2019observation naturaliste pour observer et voir comment les gens se d\u00e9placent et se comportent dans un espace afin de prendre des d\u00e9cisions de conception \u00e0 partir de nos observations. Nous effectuons beaucoup de sondages et d\u2019entrevues et, \u00e0 partir de ceux-ci, nous pouvons aider les architectes et les concepteurs \u00e0 rendre les b\u00e2timents les plus humains possible. Si l\u2019objet du travail clinique et d\u2019autres types d\u2019intervention psychologique est d\u2019aider les gens \u00e0 se sentir bien, alors la psychologie de l\u2019environnement est tout \u00e0 fait en phase avec cela. Nous voulons que les b\u00e2timents soient con\u00e7us de mani\u00e8re \u00e0 aider les gens \u00e0 se sentir aussi bien, motiv\u00e9s, enthousiastes et en forme que possible. \u00bb Le Dr Zelenski jette \u00e9galement un pont entre les deux c\u00f4t\u00e9s de la psychologie de l\u2019environnement, et ce, de diff\u00e9rentes mani\u00e8res. La collaboration avec des groupes qui font d\u00e9j\u00e0 un travail environnemental lui permet de recueillir plus facilement des donn\u00e9es, et l\u2019analyse de ces donn\u00e9es permet \u00e0 ces groupes de fonctionner de mani\u00e8re plus efficace et efficiente. \u00ab J\u2019ai collabor\u00e9 avec un architecte, faisant ainsi le pont entre ces deux composantes de la psychologie de l\u2019environnement. Il \u00e9tait tr\u00e8s int\u00e9ress\u00e9 par la construction de b\u00e2timents qui donneraient envie aux gens de se comporter de mani\u00e8re \u00e9cologique. De m\u00eame, il ne s\u2019agit peut-\u00eatre pas seulement de l\u2019int\u00e9rieur du b\u00e2timent, mais aussi des espaces naturels proches du b\u00e2timent qui pourraient encourager ces comportements. Il s\u2019agit de poser une question plus nuanc\u00e9e sur les types de milieux naturels \u00e0 proximit\u00e9 qui pourraient aider les gens \u00e0 se sentir mieux, \u00e0 \u00eatre plus heureux et plus productifs. Il y a un petit organisme sans but lucratif qui fournit des trousses d\u2019analyse de l\u2019eau. Il les distribue aux gens, qui les utilisent pour tester la qualit\u00e9 de l\u2019eau \u00e0 proximit\u00e9; les gens t\u00e9l\u00e9chargent ensuite leurs donn\u00e9es dans un genre de base de donn\u00e9es participative qui permet de voir si le lac ou la rivi\u00e8re pr\u00e8s de chez eux est en bon ou en mauvais \u00e9tat, et comment cela \u00e9volue au fil du temps. Il serait difficile pour moi de monter une exp\u00e9rience dans laquelle je distribuerais des tas de trousses d\u2019analyse de l\u2019eau, mais je peux essayer de suivre les personnes qui le font d\u00e9j\u00e0 pour voir si cela change leur sentiment de connexion avec la nature, si cela les rend heureux et si cela leur donne envie de faire d\u2019autres choses bonnes pour l\u2019environnement que de simplement tester l\u2019eau. \u00bb Depuis la mise en place de mesures de confinement en raison de la pand\u00e9mie, nous entendons beaucoup de personnes dire qu\u2019elles appr\u00e9cient davantage la nature. C\u2019est un moyen s\u00fbr de sortir de chez soi. Si on ne peut pas aller dans un centre commercial bond\u00e9 ou \u00e0 un concert, on peut toujours aller dans un parc et se promener. Les gens voient la nature comme une source de bien-\u00eatre et un bon moyen de s\u2019adapter, et certaines \u00e9tudes indiquent que la nature est l\u2019une des choses les plus positives que les gens ont ressenties au cours des deux derni\u00e8res ann\u00e9es, o\u00f9 la distanciation physique \u00e9tait impos\u00e9e. Mais ce lien avec la nature, ainsi que la prise de conscience de la grave menace que repr\u00e9sente le changement climatique, cr\u00e9e \u00e0 certains \u00e9gards de nouveaux probl\u00e8mes. Selon le Dr Zelenski, \u00ab Beaucoup de gens parlent d\u2019\u00e9coanxi\u00e9t\u00e9 et le fait que les gens soient de plus en plus conscients des changements climatiques pourrait \u00eatre une arme \u00e0 double tranchant. Cela peut donc \u00eatre motivant \u2013 ce qui est un r\u00e9sultat positif, les gens voulant se comporter d\u2019une mani\u00e8re plus \u00e9cologique \u2013 mais certaines personnes pourraient \u00eatre boulevers\u00e9es ou inqui\u00e8tes \u00e0 tel point que cela cr\u00e9era de nouvelles formes de stress et d\u2019inqui\u00e9tude qui, chez elles, peuvent \u00eatre inadapt\u00e9es. \u00bb L\u2019un des moyens de lutter contre l\u2019\u00e9coanxi\u00e9t\u00e9, un nouveau mot \u00e0 la mode dans le domaine de la pr\u00e9servation de l\u2019environnement, consiste \u00e0 faire conna\u00eetre les psychologues de l\u2019environnement et \u00e0 solliciter leurs conseils. Cette sensibilisation accrue se ressent \u00e9galement dans la dimension architecturale, car les contributions des experts de ce domaine sont maintenant per\u00e7ues par beaucoup comme \u00e9tant inestimables. La Dre McCunn dit qu\u2019elle a vu ce changement directement. \u00ab Lorsque je rencontre des ing\u00e9nieurs, des architectes et des urbanistes, je constate qu\u2019ils sont davantage sensibili\u00e9s \u00e0 la psychologie de l\u2019environnement et qu\u2019ils sont tout \u00e0 fait dispos\u00e9s \u00e0 travailler avec nous. Lorsque je faisais ma ma\u00eetrise, j\u2019ai remarqu\u00e9 que tr\u00e8s peu de personnes occupant ces postes voulaient travailler avec un sp\u00e9cialiste en sciences sociales. Plusieurs d\u2019entre eux disaient qu\u2019ils faisaient ce genre de recherche accessoirement, et qu\u2019ils \u201csavaient d\u00e9j\u00e0 comment \u00e9tudier les gens\u201d. Aujourd\u2019hui, ils font appel \u00e0 moi car ils veulent int\u00e9grer cette dimension professionnelle \u00e0 leur activit\u00e9 ou \u00e0 leurs processus. La cognition spatiale, par exemple, est un sujet tr\u00e8s habituel en psychologie de l\u2019environnement. Je pense qu\u2019il est important de le mentionner car la population vieillit. Les psychologues de l\u2019environnement consultent souvent les concepteurs pour savoir comment aider les personnes atteintes de d\u00e9mence \u00e0 s\u2019orienter dans une maison de soins, par exemple. Nous pouvons les observer et les aider avec des pancartes et des symboles, et des moyens d\u2019int\u00e9grer leur psychologie dans la conception pour leur faciliter la vie. \u00bb \u00cates-vous d\u00e9j\u00e0 all\u00e9 dans un magasin o\u00f9 il y a, sur le sol, un motif tr\u00e8s simple qui se transforme un peu \u00e0 l\u2019approche des toilettes, et un peu plus pr\u00e8s de la caisse? Peut-\u00eatre y a-t-il des rampes d\u2019escalier de couleur vive le long des murs, et le si\u00e8ge des toilettes est-il d\u2019une couleur nettement diff\u00e9rente du reste des toilettes. Le magasin est bien \u00e9clair\u00e9, mais pas trop, car il y a peu de surfaces r\u00e9fl\u00e9chissantes et pas de miroirs. Un magasin qui ressemble \u00e0 \u00e7a a probablement \u00e9t\u00e9 con\u00e7u pour \u00eatre accessible aux personnes atteintes de d\u00e9mence, avec l\u2019aide de psychologues de l\u2019environnement. Les personnes atteintes de la maladie d\u2019Alzheimer et de diff\u00e9rents types de d\u00e9mence sont g\u00e9n\u00e9ralement suivies par une \u00e9quipe de soins, notamment par un neuroscientifique (voir le portrait de la neuropsychologie clinique pr\u00e9sent\u00e9 plus t\u00f4t ce mois-ci). De plus en plus, les psychologues de l\u2019environnement travaillent au sein d\u2019\u00e9quipes interdisciplinaires plus larges, et les neurosciences elles-m\u00eames prennent une place plus importante dans la discipline. La Dre McCunn dit qu\u2019elle le constate gr\u00e2ce aux articles propos\u00e9s au Journal of Environmental Psychology. \u00ab Il y a beaucoup d\u2019articles qui fusionnent les neurosciences et la psychologie de l\u2019environnement. Je fais aussi cela dans mon propre travail \u2013 j\u2019ai presque termin\u00e9 une deuxi\u00e8me ma\u00eetrise en neurosciences appliqu\u00e9es, simplement pour approfondir mes recherches dans le domaine des neurosciences environnementales. J\u2019aime chercher \u00e0 comprendre des concepts tels que \u201cque se passe-t-il dans le cerveau lorsque nous ressentons un attachement \u00e0 un lieu? Est-ce diff\u00e9rent de l\u2019attachement que l\u2019on ressent face \u00e0 une personne? Que se passe-t-il dans le cerveau lorsque nous rencontrons diff\u00e9rents contextes?\u201d Ce sont des questions importantes qui, je pense, sont de plus en plus populaires. \u00bb La psychologie de l\u2019environnement devenant une discipline de plus en plus demand\u00e9e, l\u2019expertise des personnes travaillant dans ce domaine est appliqu\u00e9e \u00e0 une vari\u00e9t\u00e9 de sujets sans cesse croissante. La Dre McCunn esp\u00e8re que cette tendance se poursuivra, afin que l\u2019ensemble des comp\u00e9tences de ses coll\u00e8gues puisse \u00eatre utilis\u00e9 pour aider \u00e0 r\u00e9soudre des probl\u00e8mes importants. \u00ab Je souhaite que la psychologie de l\u2019environnement fasse partie d\u2019un grand nombre d\u2019\u00e9quipes tr\u00e8s diverses. Bien s\u00fbr, les architectes et les urbanistes, mais aussi les cliniciens, les m\u00e9decins, les neuroscientifiques, etc. Je crois que nous sommes de bons partenaires et nous pouvons ajouter des facettes aux questions de recherche qui peuvent enrichir une r\u00e9ponse et la rendre plus compl\u00e8te. Il est tr\u00e8s difficile de tirer des conclusions \u00e0 partir de quelques variables seulement. La mobilisation des donn\u00e9es et de la mod\u00e9lisation dans le domaine de la psychologie de l\u2019environnement peut nous aider \u00e0 aider les autres \u00e0 obtenir des r\u00e9ponses plus fiables \u00e0 de vastes questions de soci\u00e9t\u00e9 sur ce qui pousse les gens \u00e0 agir et \u00e0 penser de telle ou telle mani\u00e8re. J\u2019aimerais voir la psychologie de l\u2019environnement mettre \u00e0 contribution son expertise dans toutes sortes de contextes et dans toutes sortes d\u2019\u00e9quipes. \u00bb Mais soyez rassur\u00e9 \u2013 si un psychologue de l\u2019environnement se retrouve chez vous, il ne jugera pas la disposition de votre argenterie ni l\u2019endroit o\u00f9 vous avez plac\u00e9 votre sauci\u00e8re, \u00e0 c\u00f4t\u00e9 du pot de Nutella. Du moins, pas plus que n\u2019importe qui d\u2019autre.\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/cpa.ca\/fr\/psychology-month-profile-dr-lindsay-mccunn-and-dr-john-zelenski-environmental-psychology\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/cpa.ca\/wp-content\/uploads\/2023\/05\/android-chrome-512x512-onwhite.png\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/cpa.ca\/wp-content\/uploads\/2023\/05\/android-chrome-512x512-onwhite.png\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2022-02-25T05:01:59+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2022-05-05T17:54:48+00:00\" \/>\n\t\t<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/CPA.SCP\/\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary\" \/>\n\t\t<meta name=\"twitter:site\" content=\"@CPA_SCP\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Profils du Mois de la psychologie : Dre Lindsay McCunn et Dr John Zelenski, Environmental Psychology - Canadian Psychological Association\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Dre Lindsay McCunn Dr. John Zelenski Dre Lindsay McCunn et Dr John Zelenski, Environmental Psychology La psychologie de l\u2019environnement compte deux branches principales. Nous avons parl\u00e9 \u00e0 la Dre Lindsay McCunn de la branche de la psychologie de l\u2019architecture (la conception de b\u00e2timents et de pi\u00e8ces pour le bien-\u00eatre des occupants) et au Dr John Zelenski, de la psychologie \u00e9cologique (qui s\u2019int\u00e9resse aux comportements \u00e9cologiquement durables par l\u2019interm\u00e9diaire de la connexion des gens \u00e0 la nature). \u00c0 propos de Dre Lindsay McCunn et Dr John Zelenski Psychologie de l\u2019environnement \u00ab Quand je dis que je ne vous juge pas, je pense que je veux vraiment dire \u201cpas plus que les autres.\u201d \u00bb. Je suis un peu nerveux \u00e0 l\u2019id\u00e9e que, pendant notre r\u00e9union Zoom, la Dre Lindsay McCunn et le Dr John Zelenski puissent juger mon arri\u00e8re-plan, d\u00e9cid\u00e9ment tr\u00e8s encombr\u00e9. Tous mes appareils \u00e9lectrom\u00e9nagers sont plac\u00e9s sur une tablette derri\u00e8re moi, ce qui donne l\u2019impression (exacte, il se trouve) que mon bureau \u00e0 domicile est un coin exigu pr\u00e8s de la cuisine. La Dre McCunn et le Dr Zelenski sont des psychologues de l\u2019environnement, c\u2019est-\u00e0-dire des sp\u00e9cialistes des espaces que nous occupons et de la mani\u00e8re dont nous interagissons avec eux. Le Dr Zelenski est plut\u00f4t gentil et honn\u00eate \u2013 en tant qu\u2019\u00eatres humains, nous percevons des indices subtils, \u00e0 partir des espaces de chacun, mais cela n\u2019est probablement pas propre aux psychologues de l\u2019environnement. Nous jugeons tous les arri\u00e8re-plans Zoom, ne serait-ce qu\u2019un peu. La Dre Lindsay McCunn est professeure de psychologie \u00e0 l\u2019Universit\u00e9 Vancouver Island. Elle est la pr\u00e9sidente de la Section de psychologie de l\u2019environnement de la SCP et la r\u00e9dactrice en chef adjointe du Journal of Environmental Psychology. Selon elle, les arri\u00e8re-plans Zoom des gens ou la fa\u00e7on dont ils am\u00e9nagent leurs jardins ou leurs espaces de vie sont sources de curiosit\u00e9 pour chacun d\u2019entre nous. \u00ab La fa\u00e7on dont les gens s\u2019expriment, organisent leur domicile et placent des objets importants est vraiment int\u00e9ressante. Sam Gosling a \u00e9crit un livre intitul\u00e9 Snoopologie; il s\u2019agit d\u2019une \u00e9tude portant sur la fa\u00e7on dont on peut d\u00e9duire la personnalit\u00e9 et la fa\u00e7on de penser des gens en fonction de la mani\u00e8re dont ils rangent leurs bibelots et leurs affaires dans leur maison et leur bureau. \u00bb La Dre McCunn se sp\u00e9cialise en psychologie de l\u2019environnement et d\u00e9crit ainsi sa sp\u00e9cialit\u00e9. \u00ab La psychologie de l\u2019environnement, c\u2019est l\u2019\u00e9tude des transactions entre les personnes et les lieux. Et j\u2019entends par l\u00e0 beaucoup de types d\u2019endroits \u2013 un caf\u00e9, un bureau, une \u00e9cole, un parc, un oc\u00e9an, une montagne. Nous \u00e9tudions les diff\u00e9rentes fa\u00e7ons dont les gens interagissent avec leur environnement. De la m\u00eame mani\u00e8re qu\u2019un psychologue social \u00e9tudie et analyse les relations et les interactions entre les individus et les autres, les psychologues de l\u2019environnement \u00e9tudient et analysent les relations entre les personnes et les lieux. Dans mes recherches, je m\u2019int\u00e9resse \u00e0 la fa\u00e7on dont les gens interagissent dans les collectivit\u00e9s et les milieux de travail, en particulier dans les h\u00f4pitaux, les \u00e9coles et les bureaux. \u00c0 ce titre, je me penche sur le personnel, principalement, et sur les personnes qui utilisent les environnements d\u2019une mani\u00e8re diff\u00e9rente de celle \u00e0 laquelle on pourrait s\u2019attendre, comme les \u00e9tudiants et les patients, les enseignants, etc. \u00bb. Le Dr John Zelenski est professeur au d\u00e9partement de psychologie de l\u2019Universit\u00e9 Carleton. Il est \u00e9galement un psychologue de l\u2019environnement, mais il se sp\u00e9cialise dans un domaine bien diff\u00e9rent de celui de la Dre McCunn. On pourrait dire que l\u2019un et l\u2019autre repr\u00e9sentent les deux principales branches de la psychologie de l\u2019environnement \u2013 la psychologie de l\u2019architecture (Dre McCunn) et la psychologie de l\u2019\u00e9cologie (Dr Zelenski). \u00ab En plus d\u2019\u00eatre un psychologue de l\u2019environnement, je me consid\u00e8re aussi comme un psychologue de la personnalit\u00e9 qui se r\u00e9clame de la psychologie positive. Je me suis beaucoup int\u00e9ress\u00e9 \u00e0 ce que nous appelons le rapport \u00e0 la nature, ou ce que d\u2019autres appellent \u201cla connexion avec la nature\u201d. Je parle ici des impressions subjectives des gens : font-ils partie de la nature ou la nature est-elle distincte d\u2019eux et n\u2019a pas grand-chose \u00e0 voir avec leur perception d\u2019eux-m\u00eames? Je me suis aussi beaucoup int\u00e9ress\u00e9 de fa\u00e7on g\u00e9n\u00e9rale par ce que j\u2019appelle un \u201cchemin heureux vers la durabilit\u00e9\u201d. C\u2019est l\u2019id\u00e9e que nous savons que la nature est capable de rendre les gens de bonne humeur. La nature est associ\u00e9e au bonheur, tant sur de longues p\u00e9riodes que sur le moment. Nous savons que les gens qui passent beaucoup de temps dans la nature et qui se sentent tr\u00e8s li\u00e9s \u00e0 la nature adoptent des comportements proenvironnement et \u00e9cologiquement durables. Au cours des derni\u00e8res ann\u00e9es, nous avons commenc\u00e9 \u00e0 penser que l\u2019inverse est peut-\u00eatre vrai aussi. Si l\u2019on peut amener les gens \u00e0 faire quelques petits gestes pour la nature, en adoptant des comportements \u00e9cologiquement durables, il serait possible de se servir de cela pour qu\u2019ils se sentent plus proches de la nature et plus heureux de pratiquer ces activit\u00e9s. Nous pensons que les actions en faveur de l\u2019environnement ne doivent pas n\u00e9cessairement \u00eatre on\u00e9reuses et que nous pouvons les associer \u00e0 des \u00e9motions positives. \u00bb Ce que \u00ab consacrer du temps dans la nature \u00bb signifie pour chaque personne est subjectif. Il s\u2019agit peut-\u00eatre de prendre un week-end pour faire de la randonn\u00e9e dans les collines, de passer une journ\u00e9e \u00e0 p\u00eacher sur la glace ou simplement d\u2019aller dans son jardin et s\u2019occuper de son potager de radis. Pour la Dre McCunn, cela a entra\u00een\u00e9 de grands changements depuis le d\u00e9but de la pand\u00e9mie de COVID-19. Elle nous parle par Zoom dans ce qui semble \u00eatre un chalet dans les bois. Depuis quelques ann\u00e9es, elle et sa famille vivaient dans le centre-ville de Nanaimo, en Colombie-Britannique, en face du service d\u2019ambulance, du service de police et de la caserne de pompiers. Les sir\u00e8nes ont augment\u00e9 consid\u00e9rablement lorsque la pand\u00e9mie a commenc\u00e9, leurs habitudes de sommeil ont commenc\u00e9 \u00e0 en \u00eatre affect\u00e9es et ils ont d\u00e9cid\u00e9 de louer un endroit \u00e0 la campagne. \u00ab Ce fut en quelque sorte une bonne \u00e9tude de cas en psychologie de l\u2019environnement, dans la mesure o\u00f9 nous pouvions r\u00e9aliser ce qui nous stimulait dans notre environnement familial, puis d\u00e9cider comment le modifier pour notre sant\u00e9 mentale. Nous avons donc pens\u00e9 \u00e0 d\u00e9m\u00e9nager dans un cadre naturel plus vaste o\u00f9 nous pourrions avoir un peu plus de contr\u00f4le sur les choses qui nous stimulent. Nous avons \u00e9t\u00e9 tr\u00e8s chanceux de pouvoir louer quelque chose \u00e0 la campagne. C\u2019\u00e9tait int\u00e9ressant, parce que j\u2019\u00e9tais tr\u00e8s attach\u00e9e \u00e0 la maison que nous poss\u00e9dions. L\u2019une des choses que nous \u00e9tudions, comme psychologues de l\u2019environnement, est le \u201csentiment d\u2019appartenance\u201d ou un sentiment d\u2019appartenance \u00e0 un lieu, un sentiment identitaire ou un sentiment de d\u00e9pendance. Au d\u00e9but de la pand\u00e9mie, j\u2019ai entendu beaucoup de questions sur la fa\u00e7on dont les gens faisaient face au sentiment de perte qu\u2019ils ressentaient depuis qu\u2019ils travaillaient \u00e0 domicile. Pas seulement un sentiment de perte en rapport avec des \u00e9l\u00e9ments sociaux, mais aussi une perte des moyens habituels par lesquels ils se rendaient \u00e0 leur lieu de travail. Peut-\u00eatre prenaient-ils le m\u00eame autobus tous les jours ou arr\u00eataient-ils au m\u00eame caf\u00e9 lorsqu\u2019ils se rendaient \u00e0 l\u2019\u00e9cole ou au travail. M\u00eame le caract\u00e8re physique de l\u2019environnement de bureau ou de la salle de classe elle-m\u00eame \u2013 cet environnement leur manquait. Je me suis donc demand\u00e9 comment je r\u00e9agirais lorsque je m\u2019\u00e9loignerais de mon environnement familier auquel je m\u2019\u00e9tais vraiment attach\u00e9. Je ne voulais pas me mettre dans une position o\u00f9 je perdrais mon lien avec mon cadre habituel, mais je me suis rapidement attach\u00e9e \u00e0 cet endroit et aux caract\u00e9ristiques naturelles qui l\u2019entourent. Ce fut une belle aventure d\u2019explorer la psychologie de l\u2019environnement de l\u2019int\u00e9rieur et dans ce contexte. \u00bb Se sentir proche de la nature, ce peut \u00eatre aussi simple que de pouvoir sortir et toucher \u00e0 un arbre, ou regarder par la fen\u00eatre une montagne ou une vari\u00e9t\u00e9 d\u2019esp\u00e8ces d\u2019oiseaux. Alors, comment cela peut-il se traduire par des comportements plus respectueux de l\u2019environnement, au moment o\u00f9 le changement climatique est devenu le probl\u00e8me le plus urgent de notre \u00e9poque? Le Dr Zelenski donne l\u2019exemple que voici. \u00ab Nous avons beaucoup de bonnes preuves circonstancielles et d\u2019\u00e9tudes de laboratoire, et nous essayons de les assembler. Quelques programmes ont \u00e9t\u00e9 prometteurs! Mon ancienne \u00e9tudiante, amie et collaboratrice, Lisa Nisbet, a collabor\u00e9 avec la Fondation David Suzuki pour relever le D\u00e9fi nature 30\u00d730. Ce d\u00e9fi consiste \u00e0 consacrer 30 minutes dans la nature chaque jour pendant 30 jours. Les personnes qui s\u2019inscrivent \u00e0 ce d\u00e9fi ont tendance \u00e0 \u00eatre plut\u00f4t \u00e9cologistes et d\u00e9j\u00e0 tr\u00e8s proches de la nature. Mais au cours de ce mois, cette connexion semble se d\u00e9velopper. Ce n\u2019est pas un essai contr\u00f4l\u00e9 randomis\u00e9, mais il semble que le fait de passer du temps dans la nature donne \u00e0 ces personnes le sentiment d\u2019\u00eatre plus proches, ce qui les incite \u00e0 adopter des comportements \u00e9cologiquement durables. \u00bb L\u2019\u00e9cologie est une division de la psychologie de l\u2019environnement (relativement) nouvelle, et elle a sans aucun doute pris beaucoup d\u2019ampleur au cours des 20 derni\u00e8res ann\u00e9es, les changements climatiques \u00e9tant rapidement devenus un sujet de premier plan pour beaucoup d\u2019entre nous. Le Dr Zelenski n\u2019est pas le seul \u00e0 avoir \u00e9volu\u00e9 dans cette direction. \u00ab L\u2019attention et l\u2019importance accord\u00e9es \u00e0 l\u2019aspect \u00e9cologique de la psychologie de l\u2019environnement semblent s\u2019\u00eatre accrues au cours des 10 ou 15 derni\u00e8res ann\u00e9es. Je suis venu \u00e0 la psychologie \u00e9cologique apr\u00e8s mon doctorat, par simple int\u00e9r\u00eat personnel, et j\u2019ai l\u2019impression d\u2019\u00eatre l\u2019un des millions de personnes qui ont suivi le mouvement, et ce, pour plusieurs raisons. Les gens semblent de plus en plus manifester des sympt\u00f4mes de d\u00e9pression, d\u2019anxi\u00e9t\u00e9, etc., et la nature semble offrir un r\u00e9pit agr\u00e9able. De plus, la prise de conscience relative aux changements climatiques ne cesse de cro\u00eetre, car nous en voyons de plus en plus les effets. Et les d\u00e9cideurs politiques souhaitent savoir ce que les sciences sociales peuvent apporter pour r\u00e9soudre ces probl\u00e8mes. \u00bb La dimension \u00e9cologique de la discipline a \u00e9man\u00e9 naturellement de la branche traditionnelle de la psychologie de l\u2019architecture, qui existe depuis les ann\u00e9es 1960. Selon la Dre McCunn, il existe quelques programmes d\u2019\u00e9tudes sup\u00e9rieures officiels en \u00ab psychologie de l\u2019environnement \u00bb au Canada, mais il y en a plus en Angleterre et aux \u00c9tats-Unis, aux Pays-Bas et en Am\u00e9rique du Sud. Donc, lorsqu\u2019elle dit aux gens qu\u2019elle est une \u00ab psychologue de l\u2019environnement \u00bb, ceux-ci savent souvent ce qu\u2019elle veut dire. \u00ab Certaines personnes, \u00e0 juste titre, divisent la dimension de la psychologie de l\u2019architecture et la dimension de la psychologie de l\u2019\u00e9cologie. Je le fais aussi si je veux expliquer aux gens ce que j\u2019\u00e9tudie, parce que je suis plut\u00f4t du c\u00f4t\u00e9 de l\u2019architecture. Je travaille avec des ing\u00e9nieurs, des gestionnaires d\u2019installations et des urbanistes, mais j\u2019ai aussi des coll\u00e8gues, comme John, qui s\u2019int\u00e9ressent au lien avec la nature et travaillent avec des personnes qui \u00e9tudient les attitudes et les comportements proenvironnement. L\u2019id\u00e9e de conservation de la nature est devenue tr\u00e8s populaire dans le domaine de la psychologie de l\u2019environnement, sans pour autant prendre le pas sur la dimension architecturale, qui s\u2019int\u00e9resse \u00e0 l\u2019infrastructure des immeubles, etc. En fait, la psychologie de l\u2019environnement a d\u00e9but\u00e9 dans le contexte de l\u2019architecture, mais elle s\u2019est largement \u00e9tendue \u00e0 son autre volet, qui consiste \u00e0 poser aux gens des questions sur leur conscience \u00e9cologique et leur rapport \u00e0 la nature. \u00bb Les deux branches vont de pair. Pensez \u00e0 la tendance \u00e0 construire des b\u00e2timents \u00ab verts \u00bb, avec du chauffage \u00e0 faible consommation d\u2019\u00e9nergie, des panneaux solaires, voire un jardin sur le toit. Selon la Dre McCunn, \u00ab Quand un ing\u00e9nieur me demande : \u201cdevrions-nous concevoir ce b\u00e2timent en tenant compte de la durabilit\u00e9\u201d, il veut en r\u00e9alit\u00e9 savoir \u2013 \u201cles gens vont-ils le remarquer? S\u2019en soucient-ils? Vont-ils apporter des changements \u00e0 leurs comportements \u00e0 l\u2019int\u00e9rieur (et \u00e0 l\u2019ext\u00e9rieur) de l\u2019immeuble pour cette raison?\u201d Je peux les aider \u00e0 \u00e9tudier la mani\u00e8re dont les gens se comportent, travaillent et fonctionnent dans des b\u00e2timents plus (ou moins) durables. J\u2019ai fait une \u00e9tude dans une \u00e9cole d\u2019\u00e9tudes sup\u00e9rieures qui a montr\u00e9 que le fait qu\u2019un immeuble de bureaux soit \u201cvert\u201d ou durable ne signifie pas n\u00e9cessairement que cela permettra de pr\u00e9dire une forte productivit\u00e9 ou une forte satisfaction. Il est important de garder un \u0153il critique sur ce que l\u2019on attend d\u2019une conception durable et sur ce que l\u2019on n\u2019attend pas. \u00bb Pensez \u00e0 des espaces dans lesquels vous vous \u00eates sentis imm\u00e9diatement \u00e0 l\u2019aise avec les personnes qui vous entouraient \u2013 et d\u2019autres o\u00f9 ce n\u2019\u00e9tait pas le cas. Il est possible que ce ne soit pas les personnes pr\u00e9sentes qui en soient la cause, mais la conception de l\u2019espace qui a rendu les interactions plus embarrassantes, ou qui a rendu cette pi\u00e8ce, ce b\u00e2timent ou ce wagon plus confortable. La Dre McClunn pr\u00e9cise. \u00ab Si l\u2019on veut qu\u2019un certain espace soit accueillant et confortable, on peut le concevoir pour qu\u2019un certain nombre de personnes puissent s\u2019y asseoir \u00e0 une certaine distance. Je pense \u00e0 la conception d\u2019un caf\u00e9, ou un restaurant ou m\u00eame une salle de classe o\u00f9 l\u2019on veut que les gens s\u2019assoient d\u2019une certaine fa\u00e7on et cohabitent d\u2019une certaine mani\u00e8re. Je pense qu\u2019il est important d\u2019utiliser diff\u00e9rentes m\u00e9thodes, tout comme les autres psychologues le font. Nous sommes capables d\u2019int\u00e9grer une vari\u00e9t\u00e9 de m\u00e9thodes combin\u00e9es dans notre travail. Nous utilisons l\u2019observation naturaliste pour observer et voir comment les gens se d\u00e9placent et se comportent dans un espace afin de prendre des d\u00e9cisions de conception \u00e0 partir de nos observations. Nous effectuons beaucoup de sondages et d\u2019entrevues et, \u00e0 partir de ceux-ci, nous pouvons aider les architectes et les concepteurs \u00e0 rendre les b\u00e2timents les plus humains possible. Si l\u2019objet du travail clinique et d\u2019autres types d\u2019intervention psychologique est d\u2019aider les gens \u00e0 se sentir bien, alors la psychologie de l\u2019environnement est tout \u00e0 fait en phase avec cela. Nous voulons que les b\u00e2timents soient con\u00e7us de mani\u00e8re \u00e0 aider les gens \u00e0 se sentir aussi bien, motiv\u00e9s, enthousiastes et en forme que possible. \u00bb Le Dr Zelenski jette \u00e9galement un pont entre les deux c\u00f4t\u00e9s de la psychologie de l\u2019environnement, et ce, de diff\u00e9rentes mani\u00e8res. La collaboration avec des groupes qui font d\u00e9j\u00e0 un travail environnemental lui permet de recueillir plus facilement des donn\u00e9es, et l\u2019analyse de ces donn\u00e9es permet \u00e0 ces groupes de fonctionner de mani\u00e8re plus efficace et efficiente. \u00ab J\u2019ai collabor\u00e9 avec un architecte, faisant ainsi le pont entre ces deux composantes de la psychologie de l\u2019environnement. Il \u00e9tait tr\u00e8s int\u00e9ress\u00e9 par la construction de b\u00e2timents qui donneraient envie aux gens de se comporter de mani\u00e8re \u00e9cologique. De m\u00eame, il ne s\u2019agit peut-\u00eatre pas seulement de l\u2019int\u00e9rieur du b\u00e2timent, mais aussi des espaces naturels proches du b\u00e2timent qui pourraient encourager ces comportements. Il s\u2019agit de poser une question plus nuanc\u00e9e sur les types de milieux naturels \u00e0 proximit\u00e9 qui pourraient aider les gens \u00e0 se sentir mieux, \u00e0 \u00eatre plus heureux et plus productifs. Il y a un petit organisme sans but lucratif qui fournit des trousses d\u2019analyse de l\u2019eau. Il les distribue aux gens, qui les utilisent pour tester la qualit\u00e9 de l\u2019eau \u00e0 proximit\u00e9; les gens t\u00e9l\u00e9chargent ensuite leurs donn\u00e9es dans un genre de base de donn\u00e9es participative qui permet de voir si le lac ou la rivi\u00e8re pr\u00e8s de chez eux est en bon ou en mauvais \u00e9tat, et comment cela \u00e9volue au fil du temps. Il serait difficile pour moi de monter une exp\u00e9rience dans laquelle je distribuerais des tas de trousses d\u2019analyse de l\u2019eau, mais je peux essayer de suivre les personnes qui le font d\u00e9j\u00e0 pour voir si cela change leur sentiment de connexion avec la nature, si cela les rend heureux et si cela leur donne envie de faire d\u2019autres choses bonnes pour l\u2019environnement que de simplement tester l\u2019eau. \u00bb Depuis la mise en place de mesures de confinement en raison de la pand\u00e9mie, nous entendons beaucoup de personnes dire qu\u2019elles appr\u00e9cient davantage la nature. C\u2019est un moyen s\u00fbr de sortir de chez soi. Si on ne peut pas aller dans un centre commercial bond\u00e9 ou \u00e0 un concert, on peut toujours aller dans un parc et se promener. Les gens voient la nature comme une source de bien-\u00eatre et un bon moyen de s\u2019adapter, et certaines \u00e9tudes indiquent que la nature est l\u2019une des choses les plus positives que les gens ont ressenties au cours des deux derni\u00e8res ann\u00e9es, o\u00f9 la distanciation physique \u00e9tait impos\u00e9e. Mais ce lien avec la nature, ainsi que la prise de conscience de la grave menace que repr\u00e9sente le changement climatique, cr\u00e9e \u00e0 certains \u00e9gards de nouveaux probl\u00e8mes. Selon le Dr Zelenski, \u00ab Beaucoup de gens parlent d\u2019\u00e9coanxi\u00e9t\u00e9 et le fait que les gens soient de plus en plus conscients des changements climatiques pourrait \u00eatre une arme \u00e0 double tranchant. Cela peut donc \u00eatre motivant \u2013 ce qui est un r\u00e9sultat positif, les gens voulant se comporter d\u2019une mani\u00e8re plus \u00e9cologique \u2013 mais certaines personnes pourraient \u00eatre boulevers\u00e9es ou inqui\u00e8tes \u00e0 tel point que cela cr\u00e9era de nouvelles formes de stress et d\u2019inqui\u00e9tude qui, chez elles, peuvent \u00eatre inadapt\u00e9es. \u00bb L\u2019un des moyens de lutter contre l\u2019\u00e9coanxi\u00e9t\u00e9, un nouveau mot \u00e0 la mode dans le domaine de la pr\u00e9servation de l\u2019environnement, consiste \u00e0 faire conna\u00eetre les psychologues de l\u2019environnement et \u00e0 solliciter leurs conseils. Cette sensibilisation accrue se ressent \u00e9galement dans la dimension architecturale, car les contributions des experts de ce domaine sont maintenant per\u00e7ues par beaucoup comme \u00e9tant inestimables. La Dre McCunn dit qu\u2019elle a vu ce changement directement. \u00ab Lorsque je rencontre des ing\u00e9nieurs, des architectes et des urbanistes, je constate qu\u2019ils sont davantage sensibili\u00e9s \u00e0 la psychologie de l\u2019environnement et qu\u2019ils sont tout \u00e0 fait dispos\u00e9s \u00e0 travailler avec nous. Lorsque je faisais ma ma\u00eetrise, j\u2019ai remarqu\u00e9 que tr\u00e8s peu de personnes occupant ces postes voulaient travailler avec un sp\u00e9cialiste en sciences sociales. Plusieurs d\u2019entre eux disaient qu\u2019ils faisaient ce genre de recherche accessoirement, et qu\u2019ils \u201csavaient d\u00e9j\u00e0 comment \u00e9tudier les gens\u201d. Aujourd\u2019hui, ils font appel \u00e0 moi car ils veulent int\u00e9grer cette dimension professionnelle \u00e0 leur activit\u00e9 ou \u00e0 leurs processus. La cognition spatiale, par exemple, est un sujet tr\u00e8s habituel en psychologie de l\u2019environnement. Je pense qu\u2019il est important de le mentionner car la population vieillit. Les psychologues de l\u2019environnement consultent souvent les concepteurs pour savoir comment aider les personnes atteintes de d\u00e9mence \u00e0 s\u2019orienter dans une maison de soins, par exemple. Nous pouvons les observer et les aider avec des pancartes et des symboles, et des moyens d\u2019int\u00e9grer leur psychologie dans la conception pour leur faciliter la vie. \u00bb \u00cates-vous d\u00e9j\u00e0 all\u00e9 dans un magasin o\u00f9 il y a, sur le sol, un motif tr\u00e8s simple qui se transforme un peu \u00e0 l\u2019approche des toilettes, et un peu plus pr\u00e8s de la caisse? Peut-\u00eatre y a-t-il des rampes d\u2019escalier de couleur vive le long des murs, et le si\u00e8ge des toilettes est-il d\u2019une couleur nettement diff\u00e9rente du reste des toilettes. Le magasin est bien \u00e9clair\u00e9, mais pas trop, car il y a peu de surfaces r\u00e9fl\u00e9chissantes et pas de miroirs. Un magasin qui ressemble \u00e0 \u00e7a a probablement \u00e9t\u00e9 con\u00e7u pour \u00eatre accessible aux personnes atteintes de d\u00e9mence, avec l\u2019aide de psychologues de l\u2019environnement. Les personnes atteintes de la maladie d\u2019Alzheimer et de diff\u00e9rents types de d\u00e9mence sont g\u00e9n\u00e9ralement suivies par une \u00e9quipe de soins, notamment par un neuroscientifique (voir le portrait de la neuropsychologie clinique pr\u00e9sent\u00e9 plus t\u00f4t ce mois-ci). De plus en plus, les psychologues de l\u2019environnement travaillent au sein d\u2019\u00e9quipes interdisciplinaires plus larges, et les neurosciences elles-m\u00eames prennent une place plus importante dans la discipline. La Dre McCunn dit qu\u2019elle le constate gr\u00e2ce aux articles propos\u00e9s au Journal of Environmental Psychology. \u00ab Il y a beaucoup d\u2019articles qui fusionnent les neurosciences et la psychologie de l\u2019environnement. Je fais aussi cela dans mon propre travail \u2013 j\u2019ai presque termin\u00e9 une deuxi\u00e8me ma\u00eetrise en neurosciences appliqu\u00e9es, simplement pour approfondir mes recherches dans le domaine des neurosciences environnementales. J\u2019aime chercher \u00e0 comprendre des concepts tels que \u201cque se passe-t-il dans le cerveau lorsque nous ressentons un attachement \u00e0 un lieu? Est-ce diff\u00e9rent de l\u2019attachement que l\u2019on ressent face \u00e0 une personne? Que se passe-t-il dans le cerveau lorsque nous rencontrons diff\u00e9rents contextes?\u201d Ce sont des questions importantes qui, je pense, sont de plus en plus populaires. \u00bb La psychologie de l\u2019environnement devenant une discipline de plus en plus demand\u00e9e, l\u2019expertise des personnes travaillant dans ce domaine est appliqu\u00e9e \u00e0 une vari\u00e9t\u00e9 de sujets sans cesse croissante. La Dre McCunn esp\u00e8re que cette tendance se poursuivra, afin que l\u2019ensemble des comp\u00e9tences de ses coll\u00e8gues puisse \u00eatre utilis\u00e9 pour aider \u00e0 r\u00e9soudre des probl\u00e8mes importants. \u00ab Je souhaite que la psychologie de l\u2019environnement fasse partie d\u2019un grand nombre d\u2019\u00e9quipes tr\u00e8s diverses. Bien s\u00fbr, les architectes et les urbanistes, mais aussi les cliniciens, les m\u00e9decins, les neuroscientifiques, etc. Je crois que nous sommes de bons partenaires et nous pouvons ajouter des facettes aux questions de recherche qui peuvent enrichir une r\u00e9ponse et la rendre plus compl\u00e8te. Il est tr\u00e8s difficile de tirer des conclusions \u00e0 partir de quelques variables seulement. La mobilisation des donn\u00e9es et de la mod\u00e9lisation dans le domaine de la psychologie de l\u2019environnement peut nous aider \u00e0 aider les autres \u00e0 obtenir des r\u00e9ponses plus fiables \u00e0 de vastes questions de soci\u00e9t\u00e9 sur ce qui pousse les gens \u00e0 agir et \u00e0 penser de telle ou telle mani\u00e8re. J\u2019aimerais voir la psychologie de l\u2019environnement mettre \u00e0 contribution son expertise dans toutes sortes de contextes et dans toutes sortes d\u2019\u00e9quipes. \u00bb Mais soyez rassur\u00e9 \u2013 si un psychologue de l\u2019environnement se retrouve chez vous, il ne jugera pas la disposition de votre argenterie ni l\u2019endroit o\u00f9 vous avez plac\u00e9 votre sauci\u00e8re, \u00e0 c\u00f4t\u00e9 du pot de Nutella. Du moins, pas plus que n\u2019importe qui d\u2019autre.\" \/>\n\t\t<meta name=\"twitter:creator\" content=\"@CPA_SCP\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/cpa.ca\/wp-content\/uploads\/2023\/05\/android-chrome-512x512-onwhite.png\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BlogPosting\",\"@id\":\"https:\\\/\\\/cpa.ca\\\/fr\\\/psychology-month-profile-dr-lindsay-mccunn-and-dr-john-zelenski-environmental-psychology\\\/#blogposting\",\"name\":\"Profils du Mois de la psychologie : Dre Lindsay McCunn et Dr John Zelenski, Environmental Psychology - Canadian Psychological Association\",\"headline\":\"Profils du Mois de la psychologie : Dre Lindsay McCunn et Dr John Zelenski, Environmental Psychology\",\"author\":{\"@id\":\"https:\\\/\\\/cpa.ca\\\/fr\\\/author\\\/timbleeker\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/cpa.ca\\\/fr\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/cpa.ca\\\/docs\\\/File\\\/Psychology Month\\\/Lindsay McCunn.jpg\",\"@id\":\"https:\\\/\\\/cpa.ca\\\/fr\\\/psychology-month-profile-dr-lindsay-mccunn-and-dr-john-zelenski-environmental-psychology\\\/#articleImage\"},\"datePublished\":\"2022-02-25T00:01:59-05:00\",\"dateModified\":\"2022-05-05T13:54:48-04:00\",\"inLanguage\":\"fr-FR\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/cpa.ca\\\/fr\\\/psychology-month-profile-dr-lindsay-mccunn-and-dr-john-zelenski-environmental-psychology\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/cpa.ca\\\/fr\\\/psychology-month-profile-dr-lindsay-mccunn-and-dr-john-zelenski-environmental-psychology\\\/#webpage\"},\"articleSection\":\"Psych Profiles FR, Psychology Month 2022 FR, Facultatif\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/cpa.ca\\\/fr\\\/psychology-month-profile-dr-lindsay-mccunn-and-dr-john-zelenski-environmental-psychology\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/cpa.ca\\\/fr\\\/#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/cpa.ca\\\/fr\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/cpa.ca\\\/fr\\\/category\\\/psychprofilesfr\\\/#listItem\",\"name\":\"Psych Profiles FR\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/cpa.ca\\\/fr\\\/category\\\/psychprofilesfr\\\/#listItem\",\"position\":2,\"name\":\"Psych Profiles FR\",\"item\":\"https:\\\/\\\/cpa.ca\\\/fr\\\/category\\\/psychprofilesfr\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/cpa.ca\\\/fr\\\/category\\\/psychprofilesfr\\\/psychmonth2022fr\\\/#listItem\",\"name\":\"Psychology Month 2022 FR\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/cpa.ca\\\/fr\\\/#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/cpa.ca\\\/fr\\\/category\\\/psychprofilesfr\\\/psychmonth2022fr\\\/#listItem\",\"position\":3,\"name\":\"Psychology Month 2022 FR\",\"item\":\"https:\\\/\\\/cpa.ca\\\/fr\\\/category\\\/psychprofilesfr\\\/psychmonth2022fr\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/cpa.ca\\\/fr\\\/psychology-month-profile-dr-lindsay-mccunn-and-dr-john-zelenski-environmental-psychology\\\/#listItem\",\"name\":\"Profils du Mois de la psychologie : Dre Lindsay McCunn et Dr John Zelenski, Environmental Psychology\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/cpa.ca\\\/fr\\\/category\\\/psychprofilesfr\\\/#listItem\",\"name\":\"Psych Profiles FR\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/cpa.ca\\\/fr\\\/psychology-month-profile-dr-lindsay-mccunn-and-dr-john-zelenski-environmental-psychology\\\/#listItem\",\"position\":4,\"name\":\"Profils du Mois de la psychologie : Dre Lindsay McCunn et Dr John Zelenski, Environmental Psychology\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/cpa.ca\\\/fr\\\/category\\\/psychprofilesfr\\\/psychmonth2022fr\\\/#listItem\",\"name\":\"Psychology Month 2022 FR\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/cpa.ca\\\/fr\\\/#organization\",\"name\":\"Canadian Psychological Association\",\"description\":\"The national voice for psychology in Canada\",\"url\":\"https:\\\/\\\/cpa.ca\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/cpa.ca\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/CPA-Main-Logo-Colour-PNG.png\",\"@id\":\"https:\\\/\\\/cpa.ca\\\/fr\\\/psychology-month-profile-dr-lindsay-mccunn-and-dr-john-zelenski-environmental-psychology\\\/#organizationLogo\",\"width\":800,\"height\":392,\"caption\":\"Canadian Psychological Association\"},\"image\":{\"@id\":\"https:\\\/\\\/cpa.ca\\\/fr\\\/psychology-month-profile-dr-lindsay-mccunn-and-dr-john-zelenski-environmental-psychology\\\/#organizationLogo\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/CPA.SCP\\\/\",\"https:\\\/\\\/twitter.com\\\/CPA_SCP\",\"https:\\\/\\\/www.instagram.com\\\/canadianpsychological\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/CPAVideoChannel\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/canadian-psychological-association\\\/\",\"https:\\\/\\\/soundcloud.com\\\/user-389503679\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/cpa.ca\\\/fr\\\/author\\\/timbleeker\\\/#author\",\"url\":\"https:\\\/\\\/cpa.ca\\\/fr\\\/author\\\/timbleeker\\\/\",\"name\":\"CPA Webmaster\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/cpa.ca\\\/fr\\\/psychology-month-profile-dr-lindsay-mccunn-and-dr-john-zelenski-environmental-psychology\\\/#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/485db738ea25becbb841399e79f2a2faffb8931ad30cb1f8589302d5a94cbbd9?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"CPA Webmaster\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/cpa.ca\\\/fr\\\/psychology-month-profile-dr-lindsay-mccunn-and-dr-john-zelenski-environmental-psychology\\\/#webpage\",\"url\":\"https:\\\/\\\/cpa.ca\\\/fr\\\/psychology-month-profile-dr-lindsay-mccunn-and-dr-john-zelenski-environmental-psychology\\\/\",\"name\":\"Profils du Mois de la psychologie : Dre Lindsay McCunn et Dr John Zelenski, Environmental Psychology - Canadian Psychological Association\",\"description\":\"Dre Lindsay McCunn Dr. John Zelenski Dre Lindsay McCunn et Dr John Zelenski, Environmental Psychology La psychologie de l\\u2019environnement compte deux branches principales. Nous avons parl\\u00e9 \\u00e0 la Dre Lindsay McCunn de la branche de la psychologie de l\\u2019architecture (la conception de b\\u00e2timents et de pi\\u00e8ces pour le bien-\\u00eatre des occupants) et au Dr John Zelenski, de la psychologie \\u00e9cologique (qui s\\u2019int\\u00e9resse aux comportements \\u00e9cologiquement durables par l\\u2019interm\\u00e9diaire de la connexion des gens \\u00e0 la nature). \\u00c0 propos de Dre Lindsay McCunn et Dr John Zelenski Psychologie de l\\u2019environnement \\u00ab Quand je dis que je ne vous juge pas, je pense que je veux vraiment dire \\u201cpas plus que les autres.\\u201d \\u00bb. Je suis un peu nerveux \\u00e0 l\\u2019id\\u00e9e que, pendant notre r\\u00e9union Zoom, la Dre Lindsay McCunn et le Dr John Zelenski puissent juger mon arri\\u00e8re-plan, d\\u00e9cid\\u00e9ment tr\\u00e8s encombr\\u00e9. Tous mes appareils \\u00e9lectrom\\u00e9nagers sont plac\\u00e9s sur une tablette derri\\u00e8re moi, ce qui donne l\\u2019impression (exacte, il se trouve) que mon bureau \\u00e0 domicile est un coin exigu pr\\u00e8s de la cuisine. La Dre McCunn et le Dr Zelenski sont des psychologues de l\\u2019environnement, c\\u2019est-\\u00e0-dire des sp\\u00e9cialistes des espaces que nous occupons et de la mani\\u00e8re dont nous interagissons avec eux. Le Dr Zelenski est plut\\u00f4t gentil et honn\\u00eate \\u2013 en tant qu\\u2019\\u00eatres humains, nous percevons des indices subtils, \\u00e0 partir des espaces de chacun, mais cela n\\u2019est probablement pas propre aux psychologues de l\\u2019environnement. Nous jugeons tous les arri\\u00e8re-plans Zoom, ne serait-ce qu\\u2019un peu. La Dre Lindsay McCunn est professeure de psychologie \\u00e0 l\\u2019Universit\\u00e9 Vancouver Island. Elle est la pr\\u00e9sidente de la Section de psychologie de l\\u2019environnement de la SCP et la r\\u00e9dactrice en chef adjointe du Journal of Environmental Psychology. Selon elle, les arri\\u00e8re-plans Zoom des gens ou la fa\\u00e7on dont ils am\\u00e9nagent leurs jardins ou leurs espaces de vie sont sources de curiosit\\u00e9 pour chacun d\\u2019entre nous. \\u00ab La fa\\u00e7on dont les gens s\\u2019expriment, organisent leur domicile et placent des objets importants est vraiment int\\u00e9ressante. Sam Gosling a \\u00e9crit un livre intitul\\u00e9 Snoopologie; il s\\u2019agit d\\u2019une \\u00e9tude portant sur la fa\\u00e7on dont on peut d\\u00e9duire la personnalit\\u00e9 et la fa\\u00e7on de penser des gens en fonction de la mani\\u00e8re dont ils rangent leurs bibelots et leurs affaires dans leur maison et leur bureau. \\u00bb La Dre McCunn se sp\\u00e9cialise en psychologie de l\\u2019environnement et d\\u00e9crit ainsi sa sp\\u00e9cialit\\u00e9. \\u00ab La psychologie de l\\u2019environnement, c\\u2019est l\\u2019\\u00e9tude des transactions entre les personnes et les lieux. Et j\\u2019entends par l\\u00e0 beaucoup de types d\\u2019endroits \\u2013 un caf\\u00e9, un bureau, une \\u00e9cole, un parc, un oc\\u00e9an, une montagne. Nous \\u00e9tudions les diff\\u00e9rentes fa\\u00e7ons dont les gens interagissent avec leur environnement. De la m\\u00eame mani\\u00e8re qu\\u2019un psychologue social \\u00e9tudie et analyse les relations et les interactions entre les individus et les autres, les psychologues de l\\u2019environnement \\u00e9tudient et analysent les relations entre les personnes et les lieux. Dans mes recherches, je m\\u2019int\\u00e9resse \\u00e0 la fa\\u00e7on dont les gens interagissent dans les collectivit\\u00e9s et les milieux de travail, en particulier dans les h\\u00f4pitaux, les \\u00e9coles et les bureaux. \\u00c0 ce titre, je me penche sur le personnel, principalement, et sur les personnes qui utilisent les environnements d\\u2019une mani\\u00e8re diff\\u00e9rente de celle \\u00e0 laquelle on pourrait s\\u2019attendre, comme les \\u00e9tudiants et les patients, les enseignants, etc. \\u00bb. Le Dr John Zelenski est professeur au d\\u00e9partement de psychologie de l\\u2019Universit\\u00e9 Carleton. Il est \\u00e9galement un psychologue de l\\u2019environnement, mais il se sp\\u00e9cialise dans un domaine bien diff\\u00e9rent de celui de la Dre McCunn. On pourrait dire que l\\u2019un et l\\u2019autre repr\\u00e9sentent les deux principales branches de la psychologie de l\\u2019environnement \\u2013 la psychologie de l\\u2019architecture (Dre McCunn) et la psychologie de l\\u2019\\u00e9cologie (Dr Zelenski). \\u00ab En plus d\\u2019\\u00eatre un psychologue de l\\u2019environnement, je me consid\\u00e8re aussi comme un psychologue de la personnalit\\u00e9 qui se r\\u00e9clame de la psychologie positive. Je me suis beaucoup int\\u00e9ress\\u00e9 \\u00e0 ce que nous appelons le rapport \\u00e0 la nature, ou ce que d\\u2019autres appellent \\u201cla connexion avec la nature\\u201d. Je parle ici des impressions subjectives des gens : font-ils partie de la nature ou la nature est-elle distincte d\\u2019eux et n\\u2019a pas grand-chose \\u00e0 voir avec leur perception d\\u2019eux-m\\u00eames? Je me suis aussi beaucoup int\\u00e9ress\\u00e9 de fa\\u00e7on g\\u00e9n\\u00e9rale par ce que j\\u2019appelle un \\u201cchemin heureux vers la durabilit\\u00e9\\u201d. C\\u2019est l\\u2019id\\u00e9e que nous savons que la nature est capable de rendre les gens de bonne humeur. La nature est associ\\u00e9e au bonheur, tant sur de longues p\\u00e9riodes que sur le moment. Nous savons que les gens qui passent beaucoup de temps dans la nature et qui se sentent tr\\u00e8s li\\u00e9s \\u00e0 la nature adoptent des comportements proenvironnement et \\u00e9cologiquement durables. Au cours des derni\\u00e8res ann\\u00e9es, nous avons commenc\\u00e9 \\u00e0 penser que l\\u2019inverse est peut-\\u00eatre vrai aussi. Si l\\u2019on peut amener les gens \\u00e0 faire quelques petits gestes pour la nature, en adoptant des comportements \\u00e9cologiquement durables, il serait possible de se servir de cela pour qu\\u2019ils se sentent plus proches de la nature et plus heureux de pratiquer ces activit\\u00e9s. Nous pensons que les actions en faveur de l\\u2019environnement ne doivent pas n\\u00e9cessairement \\u00eatre on\\u00e9reuses et que nous pouvons les associer \\u00e0 des \\u00e9motions positives. \\u00bb Ce que \\u00ab consacrer du temps dans la nature \\u00bb signifie pour chaque personne est subjectif. Il s\\u2019agit peut-\\u00eatre de prendre un week-end pour faire de la randonn\\u00e9e dans les collines, de passer une journ\\u00e9e \\u00e0 p\\u00eacher sur la glace ou simplement d\\u2019aller dans son jardin et s\\u2019occuper de son potager de radis. Pour la Dre McCunn, cela a entra\\u00een\\u00e9 de grands changements depuis le d\\u00e9but de la pand\\u00e9mie de COVID-19. Elle nous parle par Zoom dans ce qui semble \\u00eatre un chalet dans les bois. Depuis quelques ann\\u00e9es, elle et sa famille vivaient dans le centre-ville de Nanaimo, en Colombie-Britannique, en face du service d\\u2019ambulance, du service de police et de la caserne de pompiers. Les sir\\u00e8nes ont augment\\u00e9 consid\\u00e9rablement lorsque la pand\\u00e9mie a commenc\\u00e9, leurs habitudes de sommeil ont commenc\\u00e9 \\u00e0 en \\u00eatre affect\\u00e9es et ils ont d\\u00e9cid\\u00e9 de louer un endroit \\u00e0 la campagne. \\u00ab Ce fut en quelque sorte une bonne \\u00e9tude de cas en psychologie de l\\u2019environnement, dans la mesure o\\u00f9 nous pouvions r\\u00e9aliser ce qui nous stimulait dans notre environnement familial, puis d\\u00e9cider comment le modifier pour notre sant\\u00e9 mentale. Nous avons donc pens\\u00e9 \\u00e0 d\\u00e9m\\u00e9nager dans un cadre naturel plus vaste o\\u00f9 nous pourrions avoir un peu plus de contr\\u00f4le sur les choses qui nous stimulent. Nous avons \\u00e9t\\u00e9 tr\\u00e8s chanceux de pouvoir louer quelque chose \\u00e0 la campagne. C\\u2019\\u00e9tait int\\u00e9ressant, parce que j\\u2019\\u00e9tais tr\\u00e8s attach\\u00e9e \\u00e0 la maison que nous poss\\u00e9dions. L\\u2019une des choses que nous \\u00e9tudions, comme psychologues de l\\u2019environnement, est le \\u201csentiment d\\u2019appartenance\\u201d ou un sentiment d\\u2019appartenance \\u00e0 un lieu, un sentiment identitaire ou un sentiment de d\\u00e9pendance. Au d\\u00e9but de la pand\\u00e9mie, j\\u2019ai entendu beaucoup de questions sur la fa\\u00e7on dont les gens faisaient face au sentiment de perte qu\\u2019ils ressentaient depuis qu\\u2019ils travaillaient \\u00e0 domicile. Pas seulement un sentiment de perte en rapport avec des \\u00e9l\\u00e9ments sociaux, mais aussi une perte des moyens habituels par lesquels ils se rendaient \\u00e0 leur lieu de travail. Peut-\\u00eatre prenaient-ils le m\\u00eame autobus tous les jours ou arr\\u00eataient-ils au m\\u00eame caf\\u00e9 lorsqu\\u2019ils se rendaient \\u00e0 l\\u2019\\u00e9cole ou au travail. M\\u00eame le caract\\u00e8re physique de l\\u2019environnement de bureau ou de la salle de classe elle-m\\u00eame \\u2013 cet environnement leur manquait. Je me suis donc demand\\u00e9 comment je r\\u00e9agirais lorsque je m\\u2019\\u00e9loignerais de mon environnement familier auquel je m\\u2019\\u00e9tais vraiment attach\\u00e9. Je ne voulais pas me mettre dans une position o\\u00f9 je perdrais mon lien avec mon cadre habituel, mais je me suis rapidement attach\\u00e9e \\u00e0 cet endroit et aux caract\\u00e9ristiques naturelles qui l\\u2019entourent. Ce fut une belle aventure d\\u2019explorer la psychologie de l\\u2019environnement de l\\u2019int\\u00e9rieur et dans ce contexte. \\u00bb Se sentir proche de la nature, ce peut \\u00eatre aussi simple que de pouvoir sortir et toucher \\u00e0 un arbre, ou regarder par la fen\\u00eatre une montagne ou une vari\\u00e9t\\u00e9 d\\u2019esp\\u00e8ces d\\u2019oiseaux. Alors, comment cela peut-il se traduire par des comportements plus respectueux de l\\u2019environnement, au moment o\\u00f9 le changement climatique est devenu le probl\\u00e8me le plus urgent de notre \\u00e9poque? Le Dr Zelenski donne l\\u2019exemple que voici. \\u00ab Nous avons beaucoup de bonnes preuves circonstancielles et d\\u2019\\u00e9tudes de laboratoire, et nous essayons de les assembler. Quelques programmes ont \\u00e9t\\u00e9 prometteurs! Mon ancienne \\u00e9tudiante, amie et collaboratrice, Lisa Nisbet, a collabor\\u00e9 avec la Fondation David Suzuki pour relever le D\\u00e9fi nature 30\\u00d730. Ce d\\u00e9fi consiste \\u00e0 consacrer 30 minutes dans la nature chaque jour pendant 30 jours. Les personnes qui s\\u2019inscrivent \\u00e0 ce d\\u00e9fi ont tendance \\u00e0 \\u00eatre plut\\u00f4t \\u00e9cologistes et d\\u00e9j\\u00e0 tr\\u00e8s proches de la nature. Mais au cours de ce mois, cette connexion semble se d\\u00e9velopper. Ce n\\u2019est pas un essai contr\\u00f4l\\u00e9 randomis\\u00e9, mais il semble que le fait de passer du temps dans la nature donne \\u00e0 ces personnes le sentiment d\\u2019\\u00eatre plus proches, ce qui les incite \\u00e0 adopter des comportements \\u00e9cologiquement durables. \\u00bb L\\u2019\\u00e9cologie est une division de la psychologie de l\\u2019environnement (relativement) nouvelle, et elle a sans aucun doute pris beaucoup d\\u2019ampleur au cours des 20 derni\\u00e8res ann\\u00e9es, les changements climatiques \\u00e9tant rapidement devenus un sujet de premier plan pour beaucoup d\\u2019entre nous. Le Dr Zelenski n\\u2019est pas le seul \\u00e0 avoir \\u00e9volu\\u00e9 dans cette direction. \\u00ab L\\u2019attention et l\\u2019importance accord\\u00e9es \\u00e0 l\\u2019aspect \\u00e9cologique de la psychologie de l\\u2019environnement semblent s\\u2019\\u00eatre accrues au cours des 10 ou 15 derni\\u00e8res ann\\u00e9es. Je suis venu \\u00e0 la psychologie \\u00e9cologique apr\\u00e8s mon doctorat, par simple int\\u00e9r\\u00eat personnel, et j\\u2019ai l\\u2019impression d\\u2019\\u00eatre l\\u2019un des millions de personnes qui ont suivi le mouvement, et ce, pour plusieurs raisons. Les gens semblent de plus en plus manifester des sympt\\u00f4mes de d\\u00e9pression, d\\u2019anxi\\u00e9t\\u00e9, etc., et la nature semble offrir un r\\u00e9pit agr\\u00e9able. De plus, la prise de conscience relative aux changements climatiques ne cesse de cro\\u00eetre, car nous en voyons de plus en plus les effets. Et les d\\u00e9cideurs politiques souhaitent savoir ce que les sciences sociales peuvent apporter pour r\\u00e9soudre ces probl\\u00e8mes. \\u00bb La dimension \\u00e9cologique de la discipline a \\u00e9man\\u00e9 naturellement de la branche traditionnelle de la psychologie de l\\u2019architecture, qui existe depuis les ann\\u00e9es 1960. Selon la Dre McCunn, il existe quelques programmes d\\u2019\\u00e9tudes sup\\u00e9rieures officiels en \\u00ab psychologie de l\\u2019environnement \\u00bb au Canada, mais il y en a plus en Angleterre et aux \\u00c9tats-Unis, aux Pays-Bas et en Am\\u00e9rique du Sud. Donc, lorsqu\\u2019elle dit aux gens qu\\u2019elle est une \\u00ab psychologue de l\\u2019environnement \\u00bb, ceux-ci savent souvent ce qu\\u2019elle veut dire. \\u00ab Certaines personnes, \\u00e0 juste titre, divisent la dimension de la psychologie de l\\u2019architecture et la dimension de la psychologie de l\\u2019\\u00e9cologie. Je le fais aussi si je veux expliquer aux gens ce que j\\u2019\\u00e9tudie, parce que je suis plut\\u00f4t du c\\u00f4t\\u00e9 de l\\u2019architecture. Je travaille avec des ing\\u00e9nieurs, des gestionnaires d\\u2019installations et des urbanistes, mais j\\u2019ai aussi des coll\\u00e8gues, comme John, qui s\\u2019int\\u00e9ressent au lien avec la nature et travaillent avec des personnes qui \\u00e9tudient les attitudes et les comportements proenvironnement. L\\u2019id\\u00e9e de conservation de la nature est devenue tr\\u00e8s populaire dans le domaine de la psychologie de l\\u2019environnement, sans pour autant prendre le pas sur la dimension architecturale, qui s\\u2019int\\u00e9resse \\u00e0 l\\u2019infrastructure des immeubles, etc. En fait, la psychologie de l\\u2019environnement a d\\u00e9but\\u00e9 dans le contexte de l\\u2019architecture, mais elle s\\u2019est largement \\u00e9tendue \\u00e0 son autre volet, qui consiste \\u00e0 poser aux gens des questions sur leur conscience \\u00e9cologique et leur rapport \\u00e0 la nature. \\u00bb Les deux branches vont de pair. Pensez \\u00e0 la tendance \\u00e0 construire des b\\u00e2timents \\u00ab verts \\u00bb, avec du chauffage \\u00e0 faible consommation d\\u2019\\u00e9nergie, des panneaux solaires, voire un jardin sur le toit. Selon la Dre McCunn, \\u00ab Quand un ing\\u00e9nieur me demande : \\u201cdevrions-nous concevoir ce b\\u00e2timent en tenant compte de la durabilit\\u00e9\\u201d, il veut en r\\u00e9alit\\u00e9 savoir \\u2013 \\u201cles gens vont-ils le remarquer? S\\u2019en soucient-ils? Vont-ils apporter des changements \\u00e0 leurs comportements \\u00e0 l\\u2019int\\u00e9rieur (et \\u00e0 l\\u2019ext\\u00e9rieur) de l\\u2019immeuble pour cette raison?\\u201d Je peux les aider \\u00e0 \\u00e9tudier la mani\\u00e8re dont les gens se comportent, travaillent et fonctionnent dans des b\\u00e2timents plus (ou moins) durables. J\\u2019ai fait une \\u00e9tude dans une \\u00e9cole d\\u2019\\u00e9tudes sup\\u00e9rieures qui a montr\\u00e9 que le fait qu\\u2019un immeuble de bureaux soit \\u201cvert\\u201d ou durable ne signifie pas n\\u00e9cessairement que cela permettra de pr\\u00e9dire une forte productivit\\u00e9 ou une forte satisfaction. Il est important de garder un \\u0153il critique sur ce que l\\u2019on attend d\\u2019une conception durable et sur ce que l\\u2019on n\\u2019attend pas. \\u00bb Pensez \\u00e0 des espaces dans lesquels vous vous \\u00eates sentis imm\\u00e9diatement \\u00e0 l\\u2019aise avec les personnes qui vous entouraient \\u2013 et d\\u2019autres o\\u00f9 ce n\\u2019\\u00e9tait pas le cas. Il est possible que ce ne soit pas les personnes pr\\u00e9sentes qui en soient la cause, mais la conception de l\\u2019espace qui a rendu les interactions plus embarrassantes, ou qui a rendu cette pi\\u00e8ce, ce b\\u00e2timent ou ce wagon plus confortable. La Dre McClunn pr\\u00e9cise. \\u00ab Si l\\u2019on veut qu\\u2019un certain espace soit accueillant et confortable, on peut le concevoir pour qu\\u2019un certain nombre de personnes puissent s\\u2019y asseoir \\u00e0 une certaine distance. Je pense \\u00e0 la conception d\\u2019un caf\\u00e9, ou un restaurant ou m\\u00eame une salle de classe o\\u00f9 l\\u2019on veut que les gens s\\u2019assoient d\\u2019une certaine fa\\u00e7on et cohabitent d\\u2019une certaine mani\\u00e8re. Je pense qu\\u2019il est important d\\u2019utiliser diff\\u00e9rentes m\\u00e9thodes, tout comme les autres psychologues le font. Nous sommes capables d\\u2019int\\u00e9grer une vari\\u00e9t\\u00e9 de m\\u00e9thodes combin\\u00e9es dans notre travail. Nous utilisons l\\u2019observation naturaliste pour observer et voir comment les gens se d\\u00e9placent et se comportent dans un espace afin de prendre des d\\u00e9cisions de conception \\u00e0 partir de nos observations. Nous effectuons beaucoup de sondages et d\\u2019entrevues et, \\u00e0 partir de ceux-ci, nous pouvons aider les architectes et les concepteurs \\u00e0 rendre les b\\u00e2timents les plus humains possible. Si l\\u2019objet du travail clinique et d\\u2019autres types d\\u2019intervention psychologique est d\\u2019aider les gens \\u00e0 se sentir bien, alors la psychologie de l\\u2019environnement est tout \\u00e0 fait en phase avec cela. Nous voulons que les b\\u00e2timents soient con\\u00e7us de mani\\u00e8re \\u00e0 aider les gens \\u00e0 se sentir aussi bien, motiv\\u00e9s, enthousiastes et en forme que possible. \\u00bb Le Dr Zelenski jette \\u00e9galement un pont entre les deux c\\u00f4t\\u00e9s de la psychologie de l\\u2019environnement, et ce, de diff\\u00e9rentes mani\\u00e8res. La collaboration avec des groupes qui font d\\u00e9j\\u00e0 un travail environnemental lui permet de recueillir plus facilement des donn\\u00e9es, et l\\u2019analyse de ces donn\\u00e9es permet \\u00e0 ces groupes de fonctionner de mani\\u00e8re plus efficace et efficiente. \\u00ab J\\u2019ai collabor\\u00e9 avec un architecte, faisant ainsi le pont entre ces deux composantes de la psychologie de l\\u2019environnement. Il \\u00e9tait tr\\u00e8s int\\u00e9ress\\u00e9 par la construction de b\\u00e2timents qui donneraient envie aux gens de se comporter de mani\\u00e8re \\u00e9cologique. De m\\u00eame, il ne s\\u2019agit peut-\\u00eatre pas seulement de l\\u2019int\\u00e9rieur du b\\u00e2timent, mais aussi des espaces naturels proches du b\\u00e2timent qui pourraient encourager ces comportements. Il s\\u2019agit de poser une question plus nuanc\\u00e9e sur les types de milieux naturels \\u00e0 proximit\\u00e9 qui pourraient aider les gens \\u00e0 se sentir mieux, \\u00e0 \\u00eatre plus heureux et plus productifs. Il y a un petit organisme sans but lucratif qui fournit des trousses d\\u2019analyse de l\\u2019eau. Il les distribue aux gens, qui les utilisent pour tester la qualit\\u00e9 de l\\u2019eau \\u00e0 proximit\\u00e9; les gens t\\u00e9l\\u00e9chargent ensuite leurs donn\\u00e9es dans un genre de base de donn\\u00e9es participative qui permet de voir si le lac ou la rivi\\u00e8re pr\\u00e8s de chez eux est en bon ou en mauvais \\u00e9tat, et comment cela \\u00e9volue au fil du temps. Il serait difficile pour moi de monter une exp\\u00e9rience dans laquelle je distribuerais des tas de trousses d\\u2019analyse de l\\u2019eau, mais je peux essayer de suivre les personnes qui le font d\\u00e9j\\u00e0 pour voir si cela change leur sentiment de connexion avec la nature, si cela les rend heureux et si cela leur donne envie de faire d\\u2019autres choses bonnes pour l\\u2019environnement que de simplement tester l\\u2019eau. \\u00bb Depuis la mise en place de mesures de confinement en raison de la pand\\u00e9mie, nous entendons beaucoup de personnes dire qu\\u2019elles appr\\u00e9cient davantage la nature. C\\u2019est un moyen s\\u00fbr de sortir de chez soi. Si on ne peut pas aller dans un centre commercial bond\\u00e9 ou \\u00e0 un concert, on peut toujours aller dans un parc et se promener. Les gens voient la nature comme une source de bien-\\u00eatre et un bon moyen de s\\u2019adapter, et certaines \\u00e9tudes indiquent que la nature est l\\u2019une des choses les plus positives que les gens ont ressenties au cours des deux derni\\u00e8res ann\\u00e9es, o\\u00f9 la distanciation physique \\u00e9tait impos\\u00e9e. Mais ce lien avec la nature, ainsi que la prise de conscience de la grave menace que repr\\u00e9sente le changement climatique, cr\\u00e9e \\u00e0 certains \\u00e9gards de nouveaux probl\\u00e8mes. Selon le Dr Zelenski, \\u00ab Beaucoup de gens parlent d\\u2019\\u00e9coanxi\\u00e9t\\u00e9 et le fait que les gens soient de plus en plus conscients des changements climatiques pourrait \\u00eatre une arme \\u00e0 double tranchant. Cela peut donc \\u00eatre motivant \\u2013 ce qui est un r\\u00e9sultat positif, les gens voulant se comporter d\\u2019une mani\\u00e8re plus \\u00e9cologique \\u2013 mais certaines personnes pourraient \\u00eatre boulevers\\u00e9es ou inqui\\u00e8tes \\u00e0 tel point que cela cr\\u00e9era de nouvelles formes de stress et d\\u2019inqui\\u00e9tude qui, chez elles, peuvent \\u00eatre inadapt\\u00e9es. \\u00bb L\\u2019un des moyens de lutter contre l\\u2019\\u00e9coanxi\\u00e9t\\u00e9, un nouveau mot \\u00e0 la mode dans le domaine de la pr\\u00e9servation de l\\u2019environnement, consiste \\u00e0 faire conna\\u00eetre les psychologues de l\\u2019environnement et \\u00e0 solliciter leurs conseils. Cette sensibilisation accrue se ressent \\u00e9galement dans la dimension architecturale, car les contributions des experts de ce domaine sont maintenant per\\u00e7ues par beaucoup comme \\u00e9tant inestimables. La Dre McCunn dit qu\\u2019elle a vu ce changement directement. \\u00ab Lorsque je rencontre des ing\\u00e9nieurs, des architectes et des urbanistes, je constate qu\\u2019ils sont davantage sensibili\\u00e9s \\u00e0 la psychologie de l\\u2019environnement et qu\\u2019ils sont tout \\u00e0 fait dispos\\u00e9s \\u00e0 travailler avec nous. Lorsque je faisais ma ma\\u00eetrise, j\\u2019ai remarqu\\u00e9 que tr\\u00e8s peu de personnes occupant ces postes voulaient travailler avec un sp\\u00e9cialiste en sciences sociales. Plusieurs d\\u2019entre eux disaient qu\\u2019ils faisaient ce genre de recherche accessoirement, et qu\\u2019ils \\u201csavaient d\\u00e9j\\u00e0 comment \\u00e9tudier les gens\\u201d. Aujourd\\u2019hui, ils font appel \\u00e0 moi car ils veulent int\\u00e9grer cette dimension professionnelle \\u00e0 leur activit\\u00e9 ou \\u00e0 leurs processus. La cognition spatiale, par exemple, est un sujet tr\\u00e8s habituel en psychologie de l\\u2019environnement. Je pense qu\\u2019il est important de le mentionner car la population vieillit. Les psychologues de l\\u2019environnement consultent souvent les concepteurs pour savoir comment aider les personnes atteintes de d\\u00e9mence \\u00e0 s\\u2019orienter dans une maison de soins, par exemple. Nous pouvons les observer et les aider avec des pancartes et des symboles, et des moyens d\\u2019int\\u00e9grer leur psychologie dans la conception pour leur faciliter la vie. \\u00bb \\u00cates-vous d\\u00e9j\\u00e0 all\\u00e9 dans un magasin o\\u00f9 il y a, sur le sol, un motif tr\\u00e8s simple qui se transforme un peu \\u00e0 l\\u2019approche des toilettes, et un peu plus pr\\u00e8s de la caisse? Peut-\\u00eatre y a-t-il des rampes d\\u2019escalier de couleur vive le long des murs, et le si\\u00e8ge des toilettes est-il d\\u2019une couleur nettement diff\\u00e9rente du reste des toilettes. Le magasin est bien \\u00e9clair\\u00e9, mais pas trop, car il y a peu de surfaces r\\u00e9fl\\u00e9chissantes et pas de miroirs. Un magasin qui ressemble \\u00e0 \\u00e7a a probablement \\u00e9t\\u00e9 con\\u00e7u pour \\u00eatre accessible aux personnes atteintes de d\\u00e9mence, avec l\\u2019aide de psychologues de l\\u2019environnement. Les personnes atteintes de la maladie d\\u2019Alzheimer et de diff\\u00e9rents types de d\\u00e9mence sont g\\u00e9n\\u00e9ralement suivies par une \\u00e9quipe de soins, notamment par un neuroscientifique (voir le portrait de la neuropsychologie clinique pr\\u00e9sent\\u00e9 plus t\\u00f4t ce mois-ci). De plus en plus, les psychologues de l\\u2019environnement travaillent au sein d\\u2019\\u00e9quipes interdisciplinaires plus larges, et les neurosciences elles-m\\u00eames prennent une place plus importante dans la discipline. La Dre McCunn dit qu\\u2019elle le constate gr\\u00e2ce aux articles propos\\u00e9s au Journal of Environmental Psychology. \\u00ab Il y a beaucoup d\\u2019articles qui fusionnent les neurosciences et la psychologie de l\\u2019environnement. Je fais aussi cela dans mon propre travail \\u2013 j\\u2019ai presque termin\\u00e9 une deuxi\\u00e8me ma\\u00eetrise en neurosciences appliqu\\u00e9es, simplement pour approfondir mes recherches dans le domaine des neurosciences environnementales. J\\u2019aime chercher \\u00e0 comprendre des concepts tels que \\u201cque se passe-t-il dans le cerveau lorsque nous ressentons un attachement \\u00e0 un lieu? Est-ce diff\\u00e9rent de l\\u2019attachement que l\\u2019on ressent face \\u00e0 une personne? Que se passe-t-il dans le cerveau lorsque nous rencontrons diff\\u00e9rents contextes?\\u201d Ce sont des questions importantes qui, je pense, sont de plus en plus populaires. \\u00bb La psychologie de l\\u2019environnement devenant une discipline de plus en plus demand\\u00e9e, l\\u2019expertise des personnes travaillant dans ce domaine est appliqu\\u00e9e \\u00e0 une vari\\u00e9t\\u00e9 de sujets sans cesse croissante. La Dre McCunn esp\\u00e8re que cette tendance se poursuivra, afin que l\\u2019ensemble des comp\\u00e9tences de ses coll\\u00e8gues puisse \\u00eatre utilis\\u00e9 pour aider \\u00e0 r\\u00e9soudre des probl\\u00e8mes importants. \\u00ab Je souhaite que la psychologie de l\\u2019environnement fasse partie d\\u2019un grand nombre d\\u2019\\u00e9quipes tr\\u00e8s diverses. Bien s\\u00fbr, les architectes et les urbanistes, mais aussi les cliniciens, les m\\u00e9decins, les neuroscientifiques, etc. Je crois que nous sommes de bons partenaires et nous pouvons ajouter des facettes aux questions de recherche qui peuvent enrichir une r\\u00e9ponse et la rendre plus compl\\u00e8te. Il est tr\\u00e8s difficile de tirer des conclusions \\u00e0 partir de quelques variables seulement. La mobilisation des donn\\u00e9es et de la mod\\u00e9lisation dans le domaine de la psychologie de l\\u2019environnement peut nous aider \\u00e0 aider les autres \\u00e0 obtenir des r\\u00e9ponses plus fiables \\u00e0 de vastes questions de soci\\u00e9t\\u00e9 sur ce qui pousse les gens \\u00e0 agir et \\u00e0 penser de telle ou telle mani\\u00e8re. J\\u2019aimerais voir la psychologie de l\\u2019environnement mettre \\u00e0 contribution son expertise dans toutes sortes de contextes et dans toutes sortes d\\u2019\\u00e9quipes. \\u00bb Mais soyez rassur\\u00e9 \\u2013 si un psychologue de l\\u2019environnement se retrouve chez vous, il ne jugera pas la disposition de votre argenterie ni l\\u2019endroit o\\u00f9 vous avez plac\\u00e9 votre sauci\\u00e8re, \\u00e0 c\\u00f4t\\u00e9 du pot de Nutella. Du moins, pas plus que n\\u2019importe qui d\\u2019autre.\",\"inLanguage\":\"fr-FR\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/cpa.ca\\\/fr\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/cpa.ca\\\/fr\\\/psychology-month-profile-dr-lindsay-mccunn-and-dr-john-zelenski-environmental-psychology\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/cpa.ca\\\/fr\\\/author\\\/timbleeker\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/cpa.ca\\\/fr\\\/author\\\/timbleeker\\\/#author\"},\"datePublished\":\"2022-02-25T00:01:59-05:00\",\"dateModified\":\"2022-05-05T13:54:48-04:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/cpa.ca\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/cpa.ca\\\/fr\\\/\",\"name\":\"Canadian Psychological Association\",\"description\":\"The national voice for psychology in Canada\",\"inLanguage\":\"fr-FR\",\"publisher\":{\"@id\":\"https:\\\/\\\/cpa.ca\\\/fr\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"Profils du Mois de la psychologie : Dre Lindsay McCunn et Dr John Zelenski, Environmental Psychology - Canadian Psychological Association","description":"Dre Lindsay McCunn Dr. John Zelenski Dre Lindsay McCunn et Dr John Zelenski, Environmental Psychology La psychologie de l\u2019environnement compte deux branches principales. Nous avons parl\u00e9 \u00e0 la Dre Lindsay McCunn de la branche de la psychologie de l\u2019architecture (la conception de b\u00e2timents et de pi\u00e8ces pour le bien-\u00eatre des occupants) et au Dr John Zelenski, de la psychologie \u00e9cologique (qui s\u2019int\u00e9resse aux comportements \u00e9cologiquement durables par l\u2019interm\u00e9diaire de la connexion des gens \u00e0 la nature). \u00c0 propos de Dre Lindsay McCunn et Dr John Zelenski Psychologie de l\u2019environnement \u00ab Quand je dis que je ne vous juge pas, je pense que je veux vraiment dire \u201cpas plus que les autres.\u201d \u00bb. Je suis un peu nerveux \u00e0 l\u2019id\u00e9e que, pendant notre r\u00e9union Zoom, la Dre Lindsay McCunn et le Dr John Zelenski puissent juger mon arri\u00e8re-plan, d\u00e9cid\u00e9ment tr\u00e8s encombr\u00e9. Tous mes appareils \u00e9lectrom\u00e9nagers sont plac\u00e9s sur une tablette derri\u00e8re moi, ce qui donne l\u2019impression (exacte, il se trouve) que mon bureau \u00e0 domicile est un coin exigu pr\u00e8s de la cuisine. La Dre McCunn et le Dr Zelenski sont des psychologues de l\u2019environnement, c\u2019est-\u00e0-dire des sp\u00e9cialistes des espaces que nous occupons et de la mani\u00e8re dont nous interagissons avec eux. Le Dr Zelenski est plut\u00f4t gentil et honn\u00eate \u2013 en tant qu\u2019\u00eatres humains, nous percevons des indices subtils, \u00e0 partir des espaces de chacun, mais cela n\u2019est probablement pas propre aux psychologues de l\u2019environnement. Nous jugeons tous les arri\u00e8re-plans Zoom, ne serait-ce qu\u2019un peu. La Dre Lindsay McCunn est professeure de psychologie \u00e0 l\u2019Universit\u00e9 Vancouver Island. Elle est la pr\u00e9sidente de la Section de psychologie de l\u2019environnement de la SCP et la r\u00e9dactrice en chef adjointe du Journal of Environmental Psychology. Selon elle, les arri\u00e8re-plans Zoom des gens ou la fa\u00e7on dont ils am\u00e9nagent leurs jardins ou leurs espaces de vie sont sources de curiosit\u00e9 pour chacun d\u2019entre nous. \u00ab La fa\u00e7on dont les gens s\u2019expriment, organisent leur domicile et placent des objets importants est vraiment int\u00e9ressante. Sam Gosling a \u00e9crit un livre intitul\u00e9 Snoopologie; il s\u2019agit d\u2019une \u00e9tude portant sur la fa\u00e7on dont on peut d\u00e9duire la personnalit\u00e9 et la fa\u00e7on de penser des gens en fonction de la mani\u00e8re dont ils rangent leurs bibelots et leurs affaires dans leur maison et leur bureau. \u00bb La Dre McCunn se sp\u00e9cialise en psychologie de l\u2019environnement et d\u00e9crit ainsi sa sp\u00e9cialit\u00e9. \u00ab La psychologie de l\u2019environnement, c\u2019est l\u2019\u00e9tude des transactions entre les personnes et les lieux. Et j\u2019entends par l\u00e0 beaucoup de types d\u2019endroits \u2013 un caf\u00e9, un bureau, une \u00e9cole, un parc, un oc\u00e9an, une montagne. Nous \u00e9tudions les diff\u00e9rentes fa\u00e7ons dont les gens interagissent avec leur environnement. De la m\u00eame mani\u00e8re qu\u2019un psychologue social \u00e9tudie et analyse les relations et les interactions entre les individus et les autres, les psychologues de l\u2019environnement \u00e9tudient et analysent les relations entre les personnes et les lieux. Dans mes recherches, je m\u2019int\u00e9resse \u00e0 la fa\u00e7on dont les gens interagissent dans les collectivit\u00e9s et les milieux de travail, en particulier dans les h\u00f4pitaux, les \u00e9coles et les bureaux. \u00c0 ce titre, je me penche sur le personnel, principalement, et sur les personnes qui utilisent les environnements d\u2019une mani\u00e8re diff\u00e9rente de celle \u00e0 laquelle on pourrait s\u2019attendre, comme les \u00e9tudiants et les patients, les enseignants, etc. \u00bb. Le Dr John Zelenski est professeur au d\u00e9partement de psychologie de l\u2019Universit\u00e9 Carleton. Il est \u00e9galement un psychologue de l\u2019environnement, mais il se sp\u00e9cialise dans un domaine bien diff\u00e9rent de celui de la Dre McCunn. On pourrait dire que l\u2019un et l\u2019autre repr\u00e9sentent les deux principales branches de la psychologie de l\u2019environnement \u2013 la psychologie de l\u2019architecture (Dre McCunn) et la psychologie de l\u2019\u00e9cologie (Dr Zelenski). \u00ab En plus d\u2019\u00eatre un psychologue de l\u2019environnement, je me consid\u00e8re aussi comme un psychologue de la personnalit\u00e9 qui se r\u00e9clame de la psychologie positive. Je me suis beaucoup int\u00e9ress\u00e9 \u00e0 ce que nous appelons le rapport \u00e0 la nature, ou ce que d\u2019autres appellent \u201cla connexion avec la nature\u201d. Je parle ici des impressions subjectives des gens : font-ils partie de la nature ou la nature est-elle distincte d\u2019eux et n\u2019a pas grand-chose \u00e0 voir avec leur perception d\u2019eux-m\u00eames? Je me suis aussi beaucoup int\u00e9ress\u00e9 de fa\u00e7on g\u00e9n\u00e9rale par ce que j\u2019appelle un \u201cchemin heureux vers la durabilit\u00e9\u201d. C\u2019est l\u2019id\u00e9e que nous savons que la nature est capable de rendre les gens de bonne humeur. La nature est associ\u00e9e au bonheur, tant sur de longues p\u00e9riodes que sur le moment. Nous savons que les gens qui passent beaucoup de temps dans la nature et qui se sentent tr\u00e8s li\u00e9s \u00e0 la nature adoptent des comportements proenvironnement et \u00e9cologiquement durables. Au cours des derni\u00e8res ann\u00e9es, nous avons commenc\u00e9 \u00e0 penser que l\u2019inverse est peut-\u00eatre vrai aussi. Si l\u2019on peut amener les gens \u00e0 faire quelques petits gestes pour la nature, en adoptant des comportements \u00e9cologiquement durables, il serait possible de se servir de cela pour qu\u2019ils se sentent plus proches de la nature et plus heureux de pratiquer ces activit\u00e9s. Nous pensons que les actions en faveur de l\u2019environnement ne doivent pas n\u00e9cessairement \u00eatre on\u00e9reuses et que nous pouvons les associer \u00e0 des \u00e9motions positives. \u00bb Ce que \u00ab consacrer du temps dans la nature \u00bb signifie pour chaque personne est subjectif. Il s\u2019agit peut-\u00eatre de prendre un week-end pour faire de la randonn\u00e9e dans les collines, de passer une journ\u00e9e \u00e0 p\u00eacher sur la glace ou simplement d\u2019aller dans son jardin et s\u2019occuper de son potager de radis. Pour la Dre McCunn, cela a entra\u00een\u00e9 de grands changements depuis le d\u00e9but de la pand\u00e9mie de COVID-19. Elle nous parle par Zoom dans ce qui semble \u00eatre un chalet dans les bois. Depuis quelques ann\u00e9es, elle et sa famille vivaient dans le centre-ville de Nanaimo, en Colombie-Britannique, en face du service d\u2019ambulance, du service de police et de la caserne de pompiers. Les sir\u00e8nes ont augment\u00e9 consid\u00e9rablement lorsque la pand\u00e9mie a commenc\u00e9, leurs habitudes de sommeil ont commenc\u00e9 \u00e0 en \u00eatre affect\u00e9es et ils ont d\u00e9cid\u00e9 de louer un endroit \u00e0 la campagne. \u00ab Ce fut en quelque sorte une bonne \u00e9tude de cas en psychologie de l\u2019environnement, dans la mesure o\u00f9 nous pouvions r\u00e9aliser ce qui nous stimulait dans notre environnement familial, puis d\u00e9cider comment le modifier pour notre sant\u00e9 mentale. Nous avons donc pens\u00e9 \u00e0 d\u00e9m\u00e9nager dans un cadre naturel plus vaste o\u00f9 nous pourrions avoir un peu plus de contr\u00f4le sur les choses qui nous stimulent. Nous avons \u00e9t\u00e9 tr\u00e8s chanceux de pouvoir louer quelque chose \u00e0 la campagne. C\u2019\u00e9tait int\u00e9ressant, parce que j\u2019\u00e9tais tr\u00e8s attach\u00e9e \u00e0 la maison que nous poss\u00e9dions. L\u2019une des choses que nous \u00e9tudions, comme psychologues de l\u2019environnement, est le \u201csentiment d\u2019appartenance\u201d ou un sentiment d\u2019appartenance \u00e0 un lieu, un sentiment identitaire ou un sentiment de d\u00e9pendance. Au d\u00e9but de la pand\u00e9mie, j\u2019ai entendu beaucoup de questions sur la fa\u00e7on dont les gens faisaient face au sentiment de perte qu\u2019ils ressentaient depuis qu\u2019ils travaillaient \u00e0 domicile. Pas seulement un sentiment de perte en rapport avec des \u00e9l\u00e9ments sociaux, mais aussi une perte des moyens habituels par lesquels ils se rendaient \u00e0 leur lieu de travail. Peut-\u00eatre prenaient-ils le m\u00eame autobus tous les jours ou arr\u00eataient-ils au m\u00eame caf\u00e9 lorsqu\u2019ils se rendaient \u00e0 l\u2019\u00e9cole ou au travail. M\u00eame le caract\u00e8re physique de l\u2019environnement de bureau ou de la salle de classe elle-m\u00eame \u2013 cet environnement leur manquait. Je me suis donc demand\u00e9 comment je r\u00e9agirais lorsque je m\u2019\u00e9loignerais de mon environnement familier auquel je m\u2019\u00e9tais vraiment attach\u00e9. Je ne voulais pas me mettre dans une position o\u00f9 je perdrais mon lien avec mon cadre habituel, mais je me suis rapidement attach\u00e9e \u00e0 cet endroit et aux caract\u00e9ristiques naturelles qui l\u2019entourent. Ce fut une belle aventure d\u2019explorer la psychologie de l\u2019environnement de l\u2019int\u00e9rieur et dans ce contexte. \u00bb Se sentir proche de la nature, ce peut \u00eatre aussi simple que de pouvoir sortir et toucher \u00e0 un arbre, ou regarder par la fen\u00eatre une montagne ou une vari\u00e9t\u00e9 d\u2019esp\u00e8ces d\u2019oiseaux. Alors, comment cela peut-il se traduire par des comportements plus respectueux de l\u2019environnement, au moment o\u00f9 le changement climatique est devenu le probl\u00e8me le plus urgent de notre \u00e9poque? Le Dr Zelenski donne l\u2019exemple que voici. \u00ab Nous avons beaucoup de bonnes preuves circonstancielles et d\u2019\u00e9tudes de laboratoire, et nous essayons de les assembler. Quelques programmes ont \u00e9t\u00e9 prometteurs! Mon ancienne \u00e9tudiante, amie et collaboratrice, Lisa Nisbet, a collabor\u00e9 avec la Fondation David Suzuki pour relever le D\u00e9fi nature 30\u00d730. Ce d\u00e9fi consiste \u00e0 consacrer 30 minutes dans la nature chaque jour pendant 30 jours. Les personnes qui s\u2019inscrivent \u00e0 ce d\u00e9fi ont tendance \u00e0 \u00eatre plut\u00f4t \u00e9cologistes et d\u00e9j\u00e0 tr\u00e8s proches de la nature. Mais au cours de ce mois, cette connexion semble se d\u00e9velopper. Ce n\u2019est pas un essai contr\u00f4l\u00e9 randomis\u00e9, mais il semble que le fait de passer du temps dans la nature donne \u00e0 ces personnes le sentiment d\u2019\u00eatre plus proches, ce qui les incite \u00e0 adopter des comportements \u00e9cologiquement durables. \u00bb L\u2019\u00e9cologie est une division de la psychologie de l\u2019environnement (relativement) nouvelle, et elle a sans aucun doute pris beaucoup d\u2019ampleur au cours des 20 derni\u00e8res ann\u00e9es, les changements climatiques \u00e9tant rapidement devenus un sujet de premier plan pour beaucoup d\u2019entre nous. Le Dr Zelenski n\u2019est pas le seul \u00e0 avoir \u00e9volu\u00e9 dans cette direction. \u00ab L\u2019attention et l\u2019importance accord\u00e9es \u00e0 l\u2019aspect \u00e9cologique de la psychologie de l\u2019environnement semblent s\u2019\u00eatre accrues au cours des 10 ou 15 derni\u00e8res ann\u00e9es. Je suis venu \u00e0 la psychologie \u00e9cologique apr\u00e8s mon doctorat, par simple int\u00e9r\u00eat personnel, et j\u2019ai l\u2019impression d\u2019\u00eatre l\u2019un des millions de personnes qui ont suivi le mouvement, et ce, pour plusieurs raisons. Les gens semblent de plus en plus manifester des sympt\u00f4mes de d\u00e9pression, d\u2019anxi\u00e9t\u00e9, etc., et la nature semble offrir un r\u00e9pit agr\u00e9able. De plus, la prise de conscience relative aux changements climatiques ne cesse de cro\u00eetre, car nous en voyons de plus en plus les effets. Et les d\u00e9cideurs politiques souhaitent savoir ce que les sciences sociales peuvent apporter pour r\u00e9soudre ces probl\u00e8mes. \u00bb La dimension \u00e9cologique de la discipline a \u00e9man\u00e9 naturellement de la branche traditionnelle de la psychologie de l\u2019architecture, qui existe depuis les ann\u00e9es 1960. Selon la Dre McCunn, il existe quelques programmes d\u2019\u00e9tudes sup\u00e9rieures officiels en \u00ab psychologie de l\u2019environnement \u00bb au Canada, mais il y en a plus en Angleterre et aux \u00c9tats-Unis, aux Pays-Bas et en Am\u00e9rique du Sud. Donc, lorsqu\u2019elle dit aux gens qu\u2019elle est une \u00ab psychologue de l\u2019environnement \u00bb, ceux-ci savent souvent ce qu\u2019elle veut dire. \u00ab Certaines personnes, \u00e0 juste titre, divisent la dimension de la psychologie de l\u2019architecture et la dimension de la psychologie de l\u2019\u00e9cologie. Je le fais aussi si je veux expliquer aux gens ce que j\u2019\u00e9tudie, parce que je suis plut\u00f4t du c\u00f4t\u00e9 de l\u2019architecture. Je travaille avec des ing\u00e9nieurs, des gestionnaires d\u2019installations et des urbanistes, mais j\u2019ai aussi des coll\u00e8gues, comme John, qui s\u2019int\u00e9ressent au lien avec la nature et travaillent avec des personnes qui \u00e9tudient les attitudes et les comportements proenvironnement. L\u2019id\u00e9e de conservation de la nature est devenue tr\u00e8s populaire dans le domaine de la psychologie de l\u2019environnement, sans pour autant prendre le pas sur la dimension architecturale, qui s\u2019int\u00e9resse \u00e0 l\u2019infrastructure des immeubles, etc. En fait, la psychologie de l\u2019environnement a d\u00e9but\u00e9 dans le contexte de l\u2019architecture, mais elle s\u2019est largement \u00e9tendue \u00e0 son autre volet, qui consiste \u00e0 poser aux gens des questions sur leur conscience \u00e9cologique et leur rapport \u00e0 la nature. \u00bb Les deux branches vont de pair. Pensez \u00e0 la tendance \u00e0 construire des b\u00e2timents \u00ab verts \u00bb, avec du chauffage \u00e0 faible consommation d\u2019\u00e9nergie, des panneaux solaires, voire un jardin sur le toit. Selon la Dre McCunn, \u00ab Quand un ing\u00e9nieur me demande : \u201cdevrions-nous concevoir ce b\u00e2timent en tenant compte de la durabilit\u00e9\u201d, il veut en r\u00e9alit\u00e9 savoir \u2013 \u201cles gens vont-ils le remarquer? S\u2019en soucient-ils? Vont-ils apporter des changements \u00e0 leurs comportements \u00e0 l\u2019int\u00e9rieur (et \u00e0 l\u2019ext\u00e9rieur) de l\u2019immeuble pour cette raison?\u201d Je peux les aider \u00e0 \u00e9tudier la mani\u00e8re dont les gens se comportent, travaillent et fonctionnent dans des b\u00e2timents plus (ou moins) durables. J\u2019ai fait une \u00e9tude dans une \u00e9cole d\u2019\u00e9tudes sup\u00e9rieures qui a montr\u00e9 que le fait qu\u2019un immeuble de bureaux soit \u201cvert\u201d ou durable ne signifie pas n\u00e9cessairement que cela permettra de pr\u00e9dire une forte productivit\u00e9 ou une forte satisfaction. Il est important de garder un \u0153il critique sur ce que l\u2019on attend d\u2019une conception durable et sur ce que l\u2019on n\u2019attend pas. \u00bb Pensez \u00e0 des espaces dans lesquels vous vous \u00eates sentis imm\u00e9diatement \u00e0 l\u2019aise avec les personnes qui vous entouraient \u2013 et d\u2019autres o\u00f9 ce n\u2019\u00e9tait pas le cas. Il est possible que ce ne soit pas les personnes pr\u00e9sentes qui en soient la cause, mais la conception de l\u2019espace qui a rendu les interactions plus embarrassantes, ou qui a rendu cette pi\u00e8ce, ce b\u00e2timent ou ce wagon plus confortable. La Dre McClunn pr\u00e9cise. \u00ab Si l\u2019on veut qu\u2019un certain espace soit accueillant et confortable, on peut le concevoir pour qu\u2019un certain nombre de personnes puissent s\u2019y asseoir \u00e0 une certaine distance. Je pense \u00e0 la conception d\u2019un caf\u00e9, ou un restaurant ou m\u00eame une salle de classe o\u00f9 l\u2019on veut que les gens s\u2019assoient d\u2019une certaine fa\u00e7on et cohabitent d\u2019une certaine mani\u00e8re. Je pense qu\u2019il est important d\u2019utiliser diff\u00e9rentes m\u00e9thodes, tout comme les autres psychologues le font. Nous sommes capables d\u2019int\u00e9grer une vari\u00e9t\u00e9 de m\u00e9thodes combin\u00e9es dans notre travail. Nous utilisons l\u2019observation naturaliste pour observer et voir comment les gens se d\u00e9placent et se comportent dans un espace afin de prendre des d\u00e9cisions de conception \u00e0 partir de nos observations. Nous effectuons beaucoup de sondages et d\u2019entrevues et, \u00e0 partir de ceux-ci, nous pouvons aider les architectes et les concepteurs \u00e0 rendre les b\u00e2timents les plus humains possible. Si l\u2019objet du travail clinique et d\u2019autres types d\u2019intervention psychologique est d\u2019aider les gens \u00e0 se sentir bien, alors la psychologie de l\u2019environnement est tout \u00e0 fait en phase avec cela. Nous voulons que les b\u00e2timents soient con\u00e7us de mani\u00e8re \u00e0 aider les gens \u00e0 se sentir aussi bien, motiv\u00e9s, enthousiastes et en forme que possible. \u00bb Le Dr Zelenski jette \u00e9galement un pont entre les deux c\u00f4t\u00e9s de la psychologie de l\u2019environnement, et ce, de diff\u00e9rentes mani\u00e8res. La collaboration avec des groupes qui font d\u00e9j\u00e0 un travail environnemental lui permet de recueillir plus facilement des donn\u00e9es, et l\u2019analyse de ces donn\u00e9es permet \u00e0 ces groupes de fonctionner de mani\u00e8re plus efficace et efficiente. \u00ab J\u2019ai collabor\u00e9 avec un architecte, faisant ainsi le pont entre ces deux composantes de la psychologie de l\u2019environnement. Il \u00e9tait tr\u00e8s int\u00e9ress\u00e9 par la construction de b\u00e2timents qui donneraient envie aux gens de se comporter de mani\u00e8re \u00e9cologique. De m\u00eame, il ne s\u2019agit peut-\u00eatre pas seulement de l\u2019int\u00e9rieur du b\u00e2timent, mais aussi des espaces naturels proches du b\u00e2timent qui pourraient encourager ces comportements. Il s\u2019agit de poser une question plus nuanc\u00e9e sur les types de milieux naturels \u00e0 proximit\u00e9 qui pourraient aider les gens \u00e0 se sentir mieux, \u00e0 \u00eatre plus heureux et plus productifs. Il y a un petit organisme sans but lucratif qui fournit des trousses d\u2019analyse de l\u2019eau. Il les distribue aux gens, qui les utilisent pour tester la qualit\u00e9 de l\u2019eau \u00e0 proximit\u00e9; les gens t\u00e9l\u00e9chargent ensuite leurs donn\u00e9es dans un genre de base de donn\u00e9es participative qui permet de voir si le lac ou la rivi\u00e8re pr\u00e8s de chez eux est en bon ou en mauvais \u00e9tat, et comment cela \u00e9volue au fil du temps. Il serait difficile pour moi de monter une exp\u00e9rience dans laquelle je distribuerais des tas de trousses d\u2019analyse de l\u2019eau, mais je peux essayer de suivre les personnes qui le font d\u00e9j\u00e0 pour voir si cela change leur sentiment de connexion avec la nature, si cela les rend heureux et si cela leur donne envie de faire d\u2019autres choses bonnes pour l\u2019environnement que de simplement tester l\u2019eau. \u00bb Depuis la mise en place de mesures de confinement en raison de la pand\u00e9mie, nous entendons beaucoup de personnes dire qu\u2019elles appr\u00e9cient davantage la nature. C\u2019est un moyen s\u00fbr de sortir de chez soi. Si on ne peut pas aller dans un centre commercial bond\u00e9 ou \u00e0 un concert, on peut toujours aller dans un parc et se promener. Les gens voient la nature comme une source de bien-\u00eatre et un bon moyen de s\u2019adapter, et certaines \u00e9tudes indiquent que la nature est l\u2019une des choses les plus positives que les gens ont ressenties au cours des deux derni\u00e8res ann\u00e9es, o\u00f9 la distanciation physique \u00e9tait impos\u00e9e. Mais ce lien avec la nature, ainsi que la prise de conscience de la grave menace que repr\u00e9sente le changement climatique, cr\u00e9e \u00e0 certains \u00e9gards de nouveaux probl\u00e8mes. Selon le Dr Zelenski, \u00ab Beaucoup de gens parlent d\u2019\u00e9coanxi\u00e9t\u00e9 et le fait que les gens soient de plus en plus conscients des changements climatiques pourrait \u00eatre une arme \u00e0 double tranchant. Cela peut donc \u00eatre motivant \u2013 ce qui est un r\u00e9sultat positif, les gens voulant se comporter d\u2019une mani\u00e8re plus \u00e9cologique \u2013 mais certaines personnes pourraient \u00eatre boulevers\u00e9es ou inqui\u00e8tes \u00e0 tel point que cela cr\u00e9era de nouvelles formes de stress et d\u2019inqui\u00e9tude qui, chez elles, peuvent \u00eatre inadapt\u00e9es. \u00bb L\u2019un des moyens de lutter contre l\u2019\u00e9coanxi\u00e9t\u00e9, un nouveau mot \u00e0 la mode dans le domaine de la pr\u00e9servation de l\u2019environnement, consiste \u00e0 faire conna\u00eetre les psychologues de l\u2019environnement et \u00e0 solliciter leurs conseils. Cette sensibilisation accrue se ressent \u00e9galement dans la dimension architecturale, car les contributions des experts de ce domaine sont maintenant per\u00e7ues par beaucoup comme \u00e9tant inestimables. La Dre McCunn dit qu\u2019elle a vu ce changement directement. \u00ab Lorsque je rencontre des ing\u00e9nieurs, des architectes et des urbanistes, je constate qu\u2019ils sont davantage sensibili\u00e9s \u00e0 la psychologie de l\u2019environnement et qu\u2019ils sont tout \u00e0 fait dispos\u00e9s \u00e0 travailler avec nous. Lorsque je faisais ma ma\u00eetrise, j\u2019ai remarqu\u00e9 que tr\u00e8s peu de personnes occupant ces postes voulaient travailler avec un sp\u00e9cialiste en sciences sociales. Plusieurs d\u2019entre eux disaient qu\u2019ils faisaient ce genre de recherche accessoirement, et qu\u2019ils \u201csavaient d\u00e9j\u00e0 comment \u00e9tudier les gens\u201d. Aujourd\u2019hui, ils font appel \u00e0 moi car ils veulent int\u00e9grer cette dimension professionnelle \u00e0 leur activit\u00e9 ou \u00e0 leurs processus. La cognition spatiale, par exemple, est un sujet tr\u00e8s habituel en psychologie de l\u2019environnement. Je pense qu\u2019il est important de le mentionner car la population vieillit. Les psychologues de l\u2019environnement consultent souvent les concepteurs pour savoir comment aider les personnes atteintes de d\u00e9mence \u00e0 s\u2019orienter dans une maison de soins, par exemple. Nous pouvons les observer et les aider avec des pancartes et des symboles, et des moyens d\u2019int\u00e9grer leur psychologie dans la conception pour leur faciliter la vie. \u00bb \u00cates-vous d\u00e9j\u00e0 all\u00e9 dans un magasin o\u00f9 il y a, sur le sol, un motif tr\u00e8s simple qui se transforme un peu \u00e0 l\u2019approche des toilettes, et un peu plus pr\u00e8s de la caisse? Peut-\u00eatre y a-t-il des rampes d\u2019escalier de couleur vive le long des murs, et le si\u00e8ge des toilettes est-il d\u2019une couleur nettement diff\u00e9rente du reste des toilettes. Le magasin est bien \u00e9clair\u00e9, mais pas trop, car il y a peu de surfaces r\u00e9fl\u00e9chissantes et pas de miroirs. Un magasin qui ressemble \u00e0 \u00e7a a probablement \u00e9t\u00e9 con\u00e7u pour \u00eatre accessible aux personnes atteintes de d\u00e9mence, avec l\u2019aide de psychologues de l\u2019environnement. Les personnes atteintes de la maladie d\u2019Alzheimer et de diff\u00e9rents types de d\u00e9mence sont g\u00e9n\u00e9ralement suivies par une \u00e9quipe de soins, notamment par un neuroscientifique (voir le portrait de la neuropsychologie clinique pr\u00e9sent\u00e9 plus t\u00f4t ce mois-ci). De plus en plus, les psychologues de l\u2019environnement travaillent au sein d\u2019\u00e9quipes interdisciplinaires plus larges, et les neurosciences elles-m\u00eames prennent une place plus importante dans la discipline. La Dre McCunn dit qu\u2019elle le constate gr\u00e2ce aux articles propos\u00e9s au Journal of Environmental Psychology. \u00ab Il y a beaucoup d\u2019articles qui fusionnent les neurosciences et la psychologie de l\u2019environnement. Je fais aussi cela dans mon propre travail \u2013 j\u2019ai presque termin\u00e9 une deuxi\u00e8me ma\u00eetrise en neurosciences appliqu\u00e9es, simplement pour approfondir mes recherches dans le domaine des neurosciences environnementales. J\u2019aime chercher \u00e0 comprendre des concepts tels que \u201cque se passe-t-il dans le cerveau lorsque nous ressentons un attachement \u00e0 un lieu? Est-ce diff\u00e9rent de l\u2019attachement que l\u2019on ressent face \u00e0 une personne? Que se passe-t-il dans le cerveau lorsque nous rencontrons diff\u00e9rents contextes?\u201d Ce sont des questions importantes qui, je pense, sont de plus en plus populaires. \u00bb La psychologie de l\u2019environnement devenant une discipline de plus en plus demand\u00e9e, l\u2019expertise des personnes travaillant dans ce domaine est appliqu\u00e9e \u00e0 une vari\u00e9t\u00e9 de sujets sans cesse croissante. La Dre McCunn esp\u00e8re que cette tendance se poursuivra, afin que l\u2019ensemble des comp\u00e9tences de ses coll\u00e8gues puisse \u00eatre utilis\u00e9 pour aider \u00e0 r\u00e9soudre des probl\u00e8mes importants. \u00ab Je souhaite que la psychologie de l\u2019environnement fasse partie d\u2019un grand nombre d\u2019\u00e9quipes tr\u00e8s diverses. Bien s\u00fbr, les architectes et les urbanistes, mais aussi les cliniciens, les m\u00e9decins, les neuroscientifiques, etc. Je crois que nous sommes de bons partenaires et nous pouvons ajouter des facettes aux questions de recherche qui peuvent enrichir une r\u00e9ponse et la rendre plus compl\u00e8te. Il est tr\u00e8s difficile de tirer des conclusions \u00e0 partir de quelques variables seulement. La mobilisation des donn\u00e9es et de la mod\u00e9lisation dans le domaine de la psychologie de l\u2019environnement peut nous aider \u00e0 aider les autres \u00e0 obtenir des r\u00e9ponses plus fiables \u00e0 de vastes questions de soci\u00e9t\u00e9 sur ce qui pousse les gens \u00e0 agir et \u00e0 penser de telle ou telle mani\u00e8re. J\u2019aimerais voir la psychologie de l\u2019environnement mettre \u00e0 contribution son expertise dans toutes sortes de contextes et dans toutes sortes d\u2019\u00e9quipes. \u00bb Mais soyez rassur\u00e9 \u2013 si un psychologue de l\u2019environnement se retrouve chez vous, il ne jugera pas la disposition de votre argenterie ni l\u2019endroit o\u00f9 vous avez plac\u00e9 votre sauci\u00e8re, \u00e0 c\u00f4t\u00e9 du pot de Nutella. Du moins, pas plus que n\u2019importe qui d\u2019autre.","canonical_url":"https:\/\/cpa.ca\/fr\/psychology-month-profile-dr-lindsay-mccunn-and-dr-john-zelenski-environmental-psychology\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BlogPosting","@id":"https:\/\/cpa.ca\/fr\/psychology-month-profile-dr-lindsay-mccunn-and-dr-john-zelenski-environmental-psychology\/#blogposting","name":"Profils du Mois de la psychologie : Dre Lindsay McCunn et Dr John Zelenski, Environmental Psychology - Canadian Psychological Association","headline":"Profils du Mois de la psychologie : Dre Lindsay McCunn et Dr John Zelenski, Environmental Psychology","author":{"@id":"https:\/\/cpa.ca\/fr\/author\/timbleeker\/#author"},"publisher":{"@id":"https:\/\/cpa.ca\/fr\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/cpa.ca\/docs\/File\/Psychology Month\/Lindsay McCunn.jpg","@id":"https:\/\/cpa.ca\/fr\/psychology-month-profile-dr-lindsay-mccunn-and-dr-john-zelenski-environmental-psychology\/#articleImage"},"datePublished":"2022-02-25T00:01:59-05:00","dateModified":"2022-05-05T13:54:48-04:00","inLanguage":"fr-FR","mainEntityOfPage":{"@id":"https:\/\/cpa.ca\/fr\/psychology-month-profile-dr-lindsay-mccunn-and-dr-john-zelenski-environmental-psychology\/#webpage"},"isPartOf":{"@id":"https:\/\/cpa.ca\/fr\/psychology-month-profile-dr-lindsay-mccunn-and-dr-john-zelenski-environmental-psychology\/#webpage"},"articleSection":"Psych Profiles FR, Psychology Month 2022 FR, Facultatif"},{"@type":"BreadcrumbList","@id":"https:\/\/cpa.ca\/fr\/psychology-month-profile-dr-lindsay-mccunn-and-dr-john-zelenski-environmental-psychology\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/cpa.ca\/fr\/#listItem","position":1,"name":"Home","item":"https:\/\/cpa.ca\/fr\/","nextItem":{"@type":"ListItem","@id":"https:\/\/cpa.ca\/fr\/category\/psychprofilesfr\/#listItem","name":"Psych Profiles FR"}},{"@type":"ListItem","@id":"https:\/\/cpa.ca\/fr\/category\/psychprofilesfr\/#listItem","position":2,"name":"Psych Profiles FR","item":"https:\/\/cpa.ca\/fr\/category\/psychprofilesfr\/","nextItem":{"@type":"ListItem","@id":"https:\/\/cpa.ca\/fr\/category\/psychprofilesfr\/psychmonth2022fr\/#listItem","name":"Psychology Month 2022 FR"},"previousItem":{"@type":"ListItem","@id":"https:\/\/cpa.ca\/fr\/#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/cpa.ca\/fr\/category\/psychprofilesfr\/psychmonth2022fr\/#listItem","position":3,"name":"Psychology Month 2022 FR","item":"https:\/\/cpa.ca\/fr\/category\/psychprofilesfr\/psychmonth2022fr\/","nextItem":{"@type":"ListItem","@id":"https:\/\/cpa.ca\/fr\/psychology-month-profile-dr-lindsay-mccunn-and-dr-john-zelenski-environmental-psychology\/#listItem","name":"Profils du Mois de la psychologie : Dre Lindsay McCunn et Dr John Zelenski, Environmental Psychology"},"previousItem":{"@type":"ListItem","@id":"https:\/\/cpa.ca\/fr\/category\/psychprofilesfr\/#listItem","name":"Psych Profiles FR"}},{"@type":"ListItem","@id":"https:\/\/cpa.ca\/fr\/psychology-month-profile-dr-lindsay-mccunn-and-dr-john-zelenski-environmental-psychology\/#listItem","position":4,"name":"Profils du Mois de la psychologie : Dre Lindsay McCunn et Dr John Zelenski, Environmental Psychology","previousItem":{"@type":"ListItem","@id":"https:\/\/cpa.ca\/fr\/category\/psychprofilesfr\/psychmonth2022fr\/#listItem","name":"Psychology Month 2022 FR"}}]},{"@type":"Organization","@id":"https:\/\/cpa.ca\/fr\/#organization","name":"Canadian Psychological Association","description":"The national voice for psychology in Canada","url":"https:\/\/cpa.ca\/fr\/","logo":{"@type":"ImageObject","url":"https:\/\/cpa.ca\/wp-content\/uploads\/2023\/05\/CPA-Main-Logo-Colour-PNG.png","@id":"https:\/\/cpa.ca\/fr\/psychology-month-profile-dr-lindsay-mccunn-and-dr-john-zelenski-environmental-psychology\/#organizationLogo","width":800,"height":392,"caption":"Canadian Psychological Association"},"image":{"@id":"https:\/\/cpa.ca\/fr\/psychology-month-profile-dr-lindsay-mccunn-and-dr-john-zelenski-environmental-psychology\/#organizationLogo"},"sameAs":["https:\/\/www.facebook.com\/CPA.SCP\/","https:\/\/twitter.com\/CPA_SCP","https:\/\/www.instagram.com\/canadianpsychological\/","https:\/\/www.youtube.com\/user\/CPAVideoChannel","https:\/\/www.linkedin.com\/company\/canadian-psychological-association\/","https:\/\/soundcloud.com\/user-389503679"]},{"@type":"Person","@id":"https:\/\/cpa.ca\/fr\/author\/timbleeker\/#author","url":"https:\/\/cpa.ca\/fr\/author\/timbleeker\/","name":"CPA Webmaster","image":{"@type":"ImageObject","@id":"https:\/\/cpa.ca\/fr\/psychology-month-profile-dr-lindsay-mccunn-and-dr-john-zelenski-environmental-psychology\/#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/485db738ea25becbb841399e79f2a2faffb8931ad30cb1f8589302d5a94cbbd9?s=96&d=mm&r=g","width":96,"height":96,"caption":"CPA Webmaster"}},{"@type":"WebPage","@id":"https:\/\/cpa.ca\/fr\/psychology-month-profile-dr-lindsay-mccunn-and-dr-john-zelenski-environmental-psychology\/#webpage","url":"https:\/\/cpa.ca\/fr\/psychology-month-profile-dr-lindsay-mccunn-and-dr-john-zelenski-environmental-psychology\/","name":"Profils du Mois de la psychologie : Dre Lindsay McCunn et Dr John Zelenski, Environmental Psychology - Canadian Psychological Association","description":"Dre Lindsay McCunn Dr. John Zelenski Dre Lindsay McCunn et Dr John Zelenski, Environmental Psychology La psychologie de l\u2019environnement compte deux branches principales. Nous avons parl\u00e9 \u00e0 la Dre Lindsay McCunn de la branche de la psychologie de l\u2019architecture (la conception de b\u00e2timents et de pi\u00e8ces pour le bien-\u00eatre des occupants) et au Dr John Zelenski, de la psychologie \u00e9cologique (qui s\u2019int\u00e9resse aux comportements \u00e9cologiquement durables par l\u2019interm\u00e9diaire de la connexion des gens \u00e0 la nature). \u00c0 propos de Dre Lindsay McCunn et Dr John Zelenski Psychologie de l\u2019environnement \u00ab Quand je dis que je ne vous juge pas, je pense que je veux vraiment dire \u201cpas plus que les autres.\u201d \u00bb. Je suis un peu nerveux \u00e0 l\u2019id\u00e9e que, pendant notre r\u00e9union Zoom, la Dre Lindsay McCunn et le Dr John Zelenski puissent juger mon arri\u00e8re-plan, d\u00e9cid\u00e9ment tr\u00e8s encombr\u00e9. Tous mes appareils \u00e9lectrom\u00e9nagers sont plac\u00e9s sur une tablette derri\u00e8re moi, ce qui donne l\u2019impression (exacte, il se trouve) que mon bureau \u00e0 domicile est un coin exigu pr\u00e8s de la cuisine. La Dre McCunn et le Dr Zelenski sont des psychologues de l\u2019environnement, c\u2019est-\u00e0-dire des sp\u00e9cialistes des espaces que nous occupons et de la mani\u00e8re dont nous interagissons avec eux. Le Dr Zelenski est plut\u00f4t gentil et honn\u00eate \u2013 en tant qu\u2019\u00eatres humains, nous percevons des indices subtils, \u00e0 partir des espaces de chacun, mais cela n\u2019est probablement pas propre aux psychologues de l\u2019environnement. Nous jugeons tous les arri\u00e8re-plans Zoom, ne serait-ce qu\u2019un peu. La Dre Lindsay McCunn est professeure de psychologie \u00e0 l\u2019Universit\u00e9 Vancouver Island. Elle est la pr\u00e9sidente de la Section de psychologie de l\u2019environnement de la SCP et la r\u00e9dactrice en chef adjointe du Journal of Environmental Psychology. Selon elle, les arri\u00e8re-plans Zoom des gens ou la fa\u00e7on dont ils am\u00e9nagent leurs jardins ou leurs espaces de vie sont sources de curiosit\u00e9 pour chacun d\u2019entre nous. \u00ab La fa\u00e7on dont les gens s\u2019expriment, organisent leur domicile et placent des objets importants est vraiment int\u00e9ressante. Sam Gosling a \u00e9crit un livre intitul\u00e9 Snoopologie; il s\u2019agit d\u2019une \u00e9tude portant sur la fa\u00e7on dont on peut d\u00e9duire la personnalit\u00e9 et la fa\u00e7on de penser des gens en fonction de la mani\u00e8re dont ils rangent leurs bibelots et leurs affaires dans leur maison et leur bureau. \u00bb La Dre McCunn se sp\u00e9cialise en psychologie de l\u2019environnement et d\u00e9crit ainsi sa sp\u00e9cialit\u00e9. \u00ab La psychologie de l\u2019environnement, c\u2019est l\u2019\u00e9tude des transactions entre les personnes et les lieux. Et j\u2019entends par l\u00e0 beaucoup de types d\u2019endroits \u2013 un caf\u00e9, un bureau, une \u00e9cole, un parc, un oc\u00e9an, une montagne. Nous \u00e9tudions les diff\u00e9rentes fa\u00e7ons dont les gens interagissent avec leur environnement. De la m\u00eame mani\u00e8re qu\u2019un psychologue social \u00e9tudie et analyse les relations et les interactions entre les individus et les autres, les psychologues de l\u2019environnement \u00e9tudient et analysent les relations entre les personnes et les lieux. Dans mes recherches, je m\u2019int\u00e9resse \u00e0 la fa\u00e7on dont les gens interagissent dans les collectivit\u00e9s et les milieux de travail, en particulier dans les h\u00f4pitaux, les \u00e9coles et les bureaux. \u00c0 ce titre, je me penche sur le personnel, principalement, et sur les personnes qui utilisent les environnements d\u2019une mani\u00e8re diff\u00e9rente de celle \u00e0 laquelle on pourrait s\u2019attendre, comme les \u00e9tudiants et les patients, les enseignants, etc. \u00bb. Le Dr John Zelenski est professeur au d\u00e9partement de psychologie de l\u2019Universit\u00e9 Carleton. Il est \u00e9galement un psychologue de l\u2019environnement, mais il se sp\u00e9cialise dans un domaine bien diff\u00e9rent de celui de la Dre McCunn. On pourrait dire que l\u2019un et l\u2019autre repr\u00e9sentent les deux principales branches de la psychologie de l\u2019environnement \u2013 la psychologie de l\u2019architecture (Dre McCunn) et la psychologie de l\u2019\u00e9cologie (Dr Zelenski). \u00ab En plus d\u2019\u00eatre un psychologue de l\u2019environnement, je me consid\u00e8re aussi comme un psychologue de la personnalit\u00e9 qui se r\u00e9clame de la psychologie positive. Je me suis beaucoup int\u00e9ress\u00e9 \u00e0 ce que nous appelons le rapport \u00e0 la nature, ou ce que d\u2019autres appellent \u201cla connexion avec la nature\u201d. Je parle ici des impressions subjectives des gens : font-ils partie de la nature ou la nature est-elle distincte d\u2019eux et n\u2019a pas grand-chose \u00e0 voir avec leur perception d\u2019eux-m\u00eames? Je me suis aussi beaucoup int\u00e9ress\u00e9 de fa\u00e7on g\u00e9n\u00e9rale par ce que j\u2019appelle un \u201cchemin heureux vers la durabilit\u00e9\u201d. C\u2019est l\u2019id\u00e9e que nous savons que la nature est capable de rendre les gens de bonne humeur. La nature est associ\u00e9e au bonheur, tant sur de longues p\u00e9riodes que sur le moment. Nous savons que les gens qui passent beaucoup de temps dans la nature et qui se sentent tr\u00e8s li\u00e9s \u00e0 la nature adoptent des comportements proenvironnement et \u00e9cologiquement durables. Au cours des derni\u00e8res ann\u00e9es, nous avons commenc\u00e9 \u00e0 penser que l\u2019inverse est peut-\u00eatre vrai aussi. Si l\u2019on peut amener les gens \u00e0 faire quelques petits gestes pour la nature, en adoptant des comportements \u00e9cologiquement durables, il serait possible de se servir de cela pour qu\u2019ils se sentent plus proches de la nature et plus heureux de pratiquer ces activit\u00e9s. Nous pensons que les actions en faveur de l\u2019environnement ne doivent pas n\u00e9cessairement \u00eatre on\u00e9reuses et que nous pouvons les associer \u00e0 des \u00e9motions positives. \u00bb Ce que \u00ab consacrer du temps dans la nature \u00bb signifie pour chaque personne est subjectif. Il s\u2019agit peut-\u00eatre de prendre un week-end pour faire de la randonn\u00e9e dans les collines, de passer une journ\u00e9e \u00e0 p\u00eacher sur la glace ou simplement d\u2019aller dans son jardin et s\u2019occuper de son potager de radis. Pour la Dre McCunn, cela a entra\u00een\u00e9 de grands changements depuis le d\u00e9but de la pand\u00e9mie de COVID-19. Elle nous parle par Zoom dans ce qui semble \u00eatre un chalet dans les bois. Depuis quelques ann\u00e9es, elle et sa famille vivaient dans le centre-ville de Nanaimo, en Colombie-Britannique, en face du service d\u2019ambulance, du service de police et de la caserne de pompiers. Les sir\u00e8nes ont augment\u00e9 consid\u00e9rablement lorsque la pand\u00e9mie a commenc\u00e9, leurs habitudes de sommeil ont commenc\u00e9 \u00e0 en \u00eatre affect\u00e9es et ils ont d\u00e9cid\u00e9 de louer un endroit \u00e0 la campagne. \u00ab Ce fut en quelque sorte une bonne \u00e9tude de cas en psychologie de l\u2019environnement, dans la mesure o\u00f9 nous pouvions r\u00e9aliser ce qui nous stimulait dans notre environnement familial, puis d\u00e9cider comment le modifier pour notre sant\u00e9 mentale. Nous avons donc pens\u00e9 \u00e0 d\u00e9m\u00e9nager dans un cadre naturel plus vaste o\u00f9 nous pourrions avoir un peu plus de contr\u00f4le sur les choses qui nous stimulent. Nous avons \u00e9t\u00e9 tr\u00e8s chanceux de pouvoir louer quelque chose \u00e0 la campagne. C\u2019\u00e9tait int\u00e9ressant, parce que j\u2019\u00e9tais tr\u00e8s attach\u00e9e \u00e0 la maison que nous poss\u00e9dions. L\u2019une des choses que nous \u00e9tudions, comme psychologues de l\u2019environnement, est le \u201csentiment d\u2019appartenance\u201d ou un sentiment d\u2019appartenance \u00e0 un lieu, un sentiment identitaire ou un sentiment de d\u00e9pendance. Au d\u00e9but de la pand\u00e9mie, j\u2019ai entendu beaucoup de questions sur la fa\u00e7on dont les gens faisaient face au sentiment de perte qu\u2019ils ressentaient depuis qu\u2019ils travaillaient \u00e0 domicile. Pas seulement un sentiment de perte en rapport avec des \u00e9l\u00e9ments sociaux, mais aussi une perte des moyens habituels par lesquels ils se rendaient \u00e0 leur lieu de travail. Peut-\u00eatre prenaient-ils le m\u00eame autobus tous les jours ou arr\u00eataient-ils au m\u00eame caf\u00e9 lorsqu\u2019ils se rendaient \u00e0 l\u2019\u00e9cole ou au travail. M\u00eame le caract\u00e8re physique de l\u2019environnement de bureau ou de la salle de classe elle-m\u00eame \u2013 cet environnement leur manquait. Je me suis donc demand\u00e9 comment je r\u00e9agirais lorsque je m\u2019\u00e9loignerais de mon environnement familier auquel je m\u2019\u00e9tais vraiment attach\u00e9. Je ne voulais pas me mettre dans une position o\u00f9 je perdrais mon lien avec mon cadre habituel, mais je me suis rapidement attach\u00e9e \u00e0 cet endroit et aux caract\u00e9ristiques naturelles qui l\u2019entourent. Ce fut une belle aventure d\u2019explorer la psychologie de l\u2019environnement de l\u2019int\u00e9rieur et dans ce contexte. \u00bb Se sentir proche de la nature, ce peut \u00eatre aussi simple que de pouvoir sortir et toucher \u00e0 un arbre, ou regarder par la fen\u00eatre une montagne ou une vari\u00e9t\u00e9 d\u2019esp\u00e8ces d\u2019oiseaux. Alors, comment cela peut-il se traduire par des comportements plus respectueux de l\u2019environnement, au moment o\u00f9 le changement climatique est devenu le probl\u00e8me le plus urgent de notre \u00e9poque? Le Dr Zelenski donne l\u2019exemple que voici. \u00ab Nous avons beaucoup de bonnes preuves circonstancielles et d\u2019\u00e9tudes de laboratoire, et nous essayons de les assembler. Quelques programmes ont \u00e9t\u00e9 prometteurs! Mon ancienne \u00e9tudiante, amie et collaboratrice, Lisa Nisbet, a collabor\u00e9 avec la Fondation David Suzuki pour relever le D\u00e9fi nature 30\u00d730. Ce d\u00e9fi consiste \u00e0 consacrer 30 minutes dans la nature chaque jour pendant 30 jours. Les personnes qui s\u2019inscrivent \u00e0 ce d\u00e9fi ont tendance \u00e0 \u00eatre plut\u00f4t \u00e9cologistes et d\u00e9j\u00e0 tr\u00e8s proches de la nature. Mais au cours de ce mois, cette connexion semble se d\u00e9velopper. Ce n\u2019est pas un essai contr\u00f4l\u00e9 randomis\u00e9, mais il semble que le fait de passer du temps dans la nature donne \u00e0 ces personnes le sentiment d\u2019\u00eatre plus proches, ce qui les incite \u00e0 adopter des comportements \u00e9cologiquement durables. \u00bb L\u2019\u00e9cologie est une division de la psychologie de l\u2019environnement (relativement) nouvelle, et elle a sans aucun doute pris beaucoup d\u2019ampleur au cours des 20 derni\u00e8res ann\u00e9es, les changements climatiques \u00e9tant rapidement devenus un sujet de premier plan pour beaucoup d\u2019entre nous. Le Dr Zelenski n\u2019est pas le seul \u00e0 avoir \u00e9volu\u00e9 dans cette direction. \u00ab L\u2019attention et l\u2019importance accord\u00e9es \u00e0 l\u2019aspect \u00e9cologique de la psychologie de l\u2019environnement semblent s\u2019\u00eatre accrues au cours des 10 ou 15 derni\u00e8res ann\u00e9es. Je suis venu \u00e0 la psychologie \u00e9cologique apr\u00e8s mon doctorat, par simple int\u00e9r\u00eat personnel, et j\u2019ai l\u2019impression d\u2019\u00eatre l\u2019un des millions de personnes qui ont suivi le mouvement, et ce, pour plusieurs raisons. Les gens semblent de plus en plus manifester des sympt\u00f4mes de d\u00e9pression, d\u2019anxi\u00e9t\u00e9, etc., et la nature semble offrir un r\u00e9pit agr\u00e9able. De plus, la prise de conscience relative aux changements climatiques ne cesse de cro\u00eetre, car nous en voyons de plus en plus les effets. Et les d\u00e9cideurs politiques souhaitent savoir ce que les sciences sociales peuvent apporter pour r\u00e9soudre ces probl\u00e8mes. \u00bb La dimension \u00e9cologique de la discipline a \u00e9man\u00e9 naturellement de la branche traditionnelle de la psychologie de l\u2019architecture, qui existe depuis les ann\u00e9es 1960. Selon la Dre McCunn, il existe quelques programmes d\u2019\u00e9tudes sup\u00e9rieures officiels en \u00ab psychologie de l\u2019environnement \u00bb au Canada, mais il y en a plus en Angleterre et aux \u00c9tats-Unis, aux Pays-Bas et en Am\u00e9rique du Sud. Donc, lorsqu\u2019elle dit aux gens qu\u2019elle est une \u00ab psychologue de l\u2019environnement \u00bb, ceux-ci savent souvent ce qu\u2019elle veut dire. \u00ab Certaines personnes, \u00e0 juste titre, divisent la dimension de la psychologie de l\u2019architecture et la dimension de la psychologie de l\u2019\u00e9cologie. Je le fais aussi si je veux expliquer aux gens ce que j\u2019\u00e9tudie, parce que je suis plut\u00f4t du c\u00f4t\u00e9 de l\u2019architecture. Je travaille avec des ing\u00e9nieurs, des gestionnaires d\u2019installations et des urbanistes, mais j\u2019ai aussi des coll\u00e8gues, comme John, qui s\u2019int\u00e9ressent au lien avec la nature et travaillent avec des personnes qui \u00e9tudient les attitudes et les comportements proenvironnement. L\u2019id\u00e9e de conservation de la nature est devenue tr\u00e8s populaire dans le domaine de la psychologie de l\u2019environnement, sans pour autant prendre le pas sur la dimension architecturale, qui s\u2019int\u00e9resse \u00e0 l\u2019infrastructure des immeubles, etc. En fait, la psychologie de l\u2019environnement a d\u00e9but\u00e9 dans le contexte de l\u2019architecture, mais elle s\u2019est largement \u00e9tendue \u00e0 son autre volet, qui consiste \u00e0 poser aux gens des questions sur leur conscience \u00e9cologique et leur rapport \u00e0 la nature. \u00bb Les deux branches vont de pair. Pensez \u00e0 la tendance \u00e0 construire des b\u00e2timents \u00ab verts \u00bb, avec du chauffage \u00e0 faible consommation d\u2019\u00e9nergie, des panneaux solaires, voire un jardin sur le toit. Selon la Dre McCunn, \u00ab Quand un ing\u00e9nieur me demande : \u201cdevrions-nous concevoir ce b\u00e2timent en tenant compte de la durabilit\u00e9\u201d, il veut en r\u00e9alit\u00e9 savoir \u2013 \u201cles gens vont-ils le remarquer? S\u2019en soucient-ils? Vont-ils apporter des changements \u00e0 leurs comportements \u00e0 l\u2019int\u00e9rieur (et \u00e0 l\u2019ext\u00e9rieur) de l\u2019immeuble pour cette raison?\u201d Je peux les aider \u00e0 \u00e9tudier la mani\u00e8re dont les gens se comportent, travaillent et fonctionnent dans des b\u00e2timents plus (ou moins) durables. J\u2019ai fait une \u00e9tude dans une \u00e9cole d\u2019\u00e9tudes sup\u00e9rieures qui a montr\u00e9 que le fait qu\u2019un immeuble de bureaux soit \u201cvert\u201d ou durable ne signifie pas n\u00e9cessairement que cela permettra de pr\u00e9dire une forte productivit\u00e9 ou une forte satisfaction. Il est important de garder un \u0153il critique sur ce que l\u2019on attend d\u2019une conception durable et sur ce que l\u2019on n\u2019attend pas. \u00bb Pensez \u00e0 des espaces dans lesquels vous vous \u00eates sentis imm\u00e9diatement \u00e0 l\u2019aise avec les personnes qui vous entouraient \u2013 et d\u2019autres o\u00f9 ce n\u2019\u00e9tait pas le cas. Il est possible que ce ne soit pas les personnes pr\u00e9sentes qui en soient la cause, mais la conception de l\u2019espace qui a rendu les interactions plus embarrassantes, ou qui a rendu cette pi\u00e8ce, ce b\u00e2timent ou ce wagon plus confortable. La Dre McClunn pr\u00e9cise. \u00ab Si l\u2019on veut qu\u2019un certain espace soit accueillant et confortable, on peut le concevoir pour qu\u2019un certain nombre de personnes puissent s\u2019y asseoir \u00e0 une certaine distance. Je pense \u00e0 la conception d\u2019un caf\u00e9, ou un restaurant ou m\u00eame une salle de classe o\u00f9 l\u2019on veut que les gens s\u2019assoient d\u2019une certaine fa\u00e7on et cohabitent d\u2019une certaine mani\u00e8re. Je pense qu\u2019il est important d\u2019utiliser diff\u00e9rentes m\u00e9thodes, tout comme les autres psychologues le font. Nous sommes capables d\u2019int\u00e9grer une vari\u00e9t\u00e9 de m\u00e9thodes combin\u00e9es dans notre travail. Nous utilisons l\u2019observation naturaliste pour observer et voir comment les gens se d\u00e9placent et se comportent dans un espace afin de prendre des d\u00e9cisions de conception \u00e0 partir de nos observations. Nous effectuons beaucoup de sondages et d\u2019entrevues et, \u00e0 partir de ceux-ci, nous pouvons aider les architectes et les concepteurs \u00e0 rendre les b\u00e2timents les plus humains possible. Si l\u2019objet du travail clinique et d\u2019autres types d\u2019intervention psychologique est d\u2019aider les gens \u00e0 se sentir bien, alors la psychologie de l\u2019environnement est tout \u00e0 fait en phase avec cela. Nous voulons que les b\u00e2timents soient con\u00e7us de mani\u00e8re \u00e0 aider les gens \u00e0 se sentir aussi bien, motiv\u00e9s, enthousiastes et en forme que possible. \u00bb Le Dr Zelenski jette \u00e9galement un pont entre les deux c\u00f4t\u00e9s de la psychologie de l\u2019environnement, et ce, de diff\u00e9rentes mani\u00e8res. La collaboration avec des groupes qui font d\u00e9j\u00e0 un travail environnemental lui permet de recueillir plus facilement des donn\u00e9es, et l\u2019analyse de ces donn\u00e9es permet \u00e0 ces groupes de fonctionner de mani\u00e8re plus efficace et efficiente. \u00ab J\u2019ai collabor\u00e9 avec un architecte, faisant ainsi le pont entre ces deux composantes de la psychologie de l\u2019environnement. Il \u00e9tait tr\u00e8s int\u00e9ress\u00e9 par la construction de b\u00e2timents qui donneraient envie aux gens de se comporter de mani\u00e8re \u00e9cologique. De m\u00eame, il ne s\u2019agit peut-\u00eatre pas seulement de l\u2019int\u00e9rieur du b\u00e2timent, mais aussi des espaces naturels proches du b\u00e2timent qui pourraient encourager ces comportements. Il s\u2019agit de poser une question plus nuanc\u00e9e sur les types de milieux naturels \u00e0 proximit\u00e9 qui pourraient aider les gens \u00e0 se sentir mieux, \u00e0 \u00eatre plus heureux et plus productifs. Il y a un petit organisme sans but lucratif qui fournit des trousses d\u2019analyse de l\u2019eau. Il les distribue aux gens, qui les utilisent pour tester la qualit\u00e9 de l\u2019eau \u00e0 proximit\u00e9; les gens t\u00e9l\u00e9chargent ensuite leurs donn\u00e9es dans un genre de base de donn\u00e9es participative qui permet de voir si le lac ou la rivi\u00e8re pr\u00e8s de chez eux est en bon ou en mauvais \u00e9tat, et comment cela \u00e9volue au fil du temps. Il serait difficile pour moi de monter une exp\u00e9rience dans laquelle je distribuerais des tas de trousses d\u2019analyse de l\u2019eau, mais je peux essayer de suivre les personnes qui le font d\u00e9j\u00e0 pour voir si cela change leur sentiment de connexion avec la nature, si cela les rend heureux et si cela leur donne envie de faire d\u2019autres choses bonnes pour l\u2019environnement que de simplement tester l\u2019eau. \u00bb Depuis la mise en place de mesures de confinement en raison de la pand\u00e9mie, nous entendons beaucoup de personnes dire qu\u2019elles appr\u00e9cient davantage la nature. C\u2019est un moyen s\u00fbr de sortir de chez soi. Si on ne peut pas aller dans un centre commercial bond\u00e9 ou \u00e0 un concert, on peut toujours aller dans un parc et se promener. Les gens voient la nature comme une source de bien-\u00eatre et un bon moyen de s\u2019adapter, et certaines \u00e9tudes indiquent que la nature est l\u2019une des choses les plus positives que les gens ont ressenties au cours des deux derni\u00e8res ann\u00e9es, o\u00f9 la distanciation physique \u00e9tait impos\u00e9e. Mais ce lien avec la nature, ainsi que la prise de conscience de la grave menace que repr\u00e9sente le changement climatique, cr\u00e9e \u00e0 certains \u00e9gards de nouveaux probl\u00e8mes. Selon le Dr Zelenski, \u00ab Beaucoup de gens parlent d\u2019\u00e9coanxi\u00e9t\u00e9 et le fait que les gens soient de plus en plus conscients des changements climatiques pourrait \u00eatre une arme \u00e0 double tranchant. Cela peut donc \u00eatre motivant \u2013 ce qui est un r\u00e9sultat positif, les gens voulant se comporter d\u2019une mani\u00e8re plus \u00e9cologique \u2013 mais certaines personnes pourraient \u00eatre boulevers\u00e9es ou inqui\u00e8tes \u00e0 tel point que cela cr\u00e9era de nouvelles formes de stress et d\u2019inqui\u00e9tude qui, chez elles, peuvent \u00eatre inadapt\u00e9es. \u00bb L\u2019un des moyens de lutter contre l\u2019\u00e9coanxi\u00e9t\u00e9, un nouveau mot \u00e0 la mode dans le domaine de la pr\u00e9servation de l\u2019environnement, consiste \u00e0 faire conna\u00eetre les psychologues de l\u2019environnement et \u00e0 solliciter leurs conseils. Cette sensibilisation accrue se ressent \u00e9galement dans la dimension architecturale, car les contributions des experts de ce domaine sont maintenant per\u00e7ues par beaucoup comme \u00e9tant inestimables. La Dre McCunn dit qu\u2019elle a vu ce changement directement. \u00ab Lorsque je rencontre des ing\u00e9nieurs, des architectes et des urbanistes, je constate qu\u2019ils sont davantage sensibili\u00e9s \u00e0 la psychologie de l\u2019environnement et qu\u2019ils sont tout \u00e0 fait dispos\u00e9s \u00e0 travailler avec nous. Lorsque je faisais ma ma\u00eetrise, j\u2019ai remarqu\u00e9 que tr\u00e8s peu de personnes occupant ces postes voulaient travailler avec un sp\u00e9cialiste en sciences sociales. Plusieurs d\u2019entre eux disaient qu\u2019ils faisaient ce genre de recherche accessoirement, et qu\u2019ils \u201csavaient d\u00e9j\u00e0 comment \u00e9tudier les gens\u201d. Aujourd\u2019hui, ils font appel \u00e0 moi car ils veulent int\u00e9grer cette dimension professionnelle \u00e0 leur activit\u00e9 ou \u00e0 leurs processus. La cognition spatiale, par exemple, est un sujet tr\u00e8s habituel en psychologie de l\u2019environnement. Je pense qu\u2019il est important de le mentionner car la population vieillit. Les psychologues de l\u2019environnement consultent souvent les concepteurs pour savoir comment aider les personnes atteintes de d\u00e9mence \u00e0 s\u2019orienter dans une maison de soins, par exemple. Nous pouvons les observer et les aider avec des pancartes et des symboles, et des moyens d\u2019int\u00e9grer leur psychologie dans la conception pour leur faciliter la vie. \u00bb \u00cates-vous d\u00e9j\u00e0 all\u00e9 dans un magasin o\u00f9 il y a, sur le sol, un motif tr\u00e8s simple qui se transforme un peu \u00e0 l\u2019approche des toilettes, et un peu plus pr\u00e8s de la caisse? Peut-\u00eatre y a-t-il des rampes d\u2019escalier de couleur vive le long des murs, et le si\u00e8ge des toilettes est-il d\u2019une couleur nettement diff\u00e9rente du reste des toilettes. Le magasin est bien \u00e9clair\u00e9, mais pas trop, car il y a peu de surfaces r\u00e9fl\u00e9chissantes et pas de miroirs. Un magasin qui ressemble \u00e0 \u00e7a a probablement \u00e9t\u00e9 con\u00e7u pour \u00eatre accessible aux personnes atteintes de d\u00e9mence, avec l\u2019aide de psychologues de l\u2019environnement. Les personnes atteintes de la maladie d\u2019Alzheimer et de diff\u00e9rents types de d\u00e9mence sont g\u00e9n\u00e9ralement suivies par une \u00e9quipe de soins, notamment par un neuroscientifique (voir le portrait de la neuropsychologie clinique pr\u00e9sent\u00e9 plus t\u00f4t ce mois-ci). De plus en plus, les psychologues de l\u2019environnement travaillent au sein d\u2019\u00e9quipes interdisciplinaires plus larges, et les neurosciences elles-m\u00eames prennent une place plus importante dans la discipline. La Dre McCunn dit qu\u2019elle le constate gr\u00e2ce aux articles propos\u00e9s au Journal of Environmental Psychology. \u00ab Il y a beaucoup d\u2019articles qui fusionnent les neurosciences et la psychologie de l\u2019environnement. Je fais aussi cela dans mon propre travail \u2013 j\u2019ai presque termin\u00e9 une deuxi\u00e8me ma\u00eetrise en neurosciences appliqu\u00e9es, simplement pour approfondir mes recherches dans le domaine des neurosciences environnementales. J\u2019aime chercher \u00e0 comprendre des concepts tels que \u201cque se passe-t-il dans le cerveau lorsque nous ressentons un attachement \u00e0 un lieu? Est-ce diff\u00e9rent de l\u2019attachement que l\u2019on ressent face \u00e0 une personne? Que se passe-t-il dans le cerveau lorsque nous rencontrons diff\u00e9rents contextes?\u201d Ce sont des questions importantes qui, je pense, sont de plus en plus populaires. \u00bb La psychologie de l\u2019environnement devenant une discipline de plus en plus demand\u00e9e, l\u2019expertise des personnes travaillant dans ce domaine est appliqu\u00e9e \u00e0 une vari\u00e9t\u00e9 de sujets sans cesse croissante. La Dre McCunn esp\u00e8re que cette tendance se poursuivra, afin que l\u2019ensemble des comp\u00e9tences de ses coll\u00e8gues puisse \u00eatre utilis\u00e9 pour aider \u00e0 r\u00e9soudre des probl\u00e8mes importants. \u00ab Je souhaite que la psychologie de l\u2019environnement fasse partie d\u2019un grand nombre d\u2019\u00e9quipes tr\u00e8s diverses. Bien s\u00fbr, les architectes et les urbanistes, mais aussi les cliniciens, les m\u00e9decins, les neuroscientifiques, etc. Je crois que nous sommes de bons partenaires et nous pouvons ajouter des facettes aux questions de recherche qui peuvent enrichir une r\u00e9ponse et la rendre plus compl\u00e8te. Il est tr\u00e8s difficile de tirer des conclusions \u00e0 partir de quelques variables seulement. La mobilisation des donn\u00e9es et de la mod\u00e9lisation dans le domaine de la psychologie de l\u2019environnement peut nous aider \u00e0 aider les autres \u00e0 obtenir des r\u00e9ponses plus fiables \u00e0 de vastes questions de soci\u00e9t\u00e9 sur ce qui pousse les gens \u00e0 agir et \u00e0 penser de telle ou telle mani\u00e8re. J\u2019aimerais voir la psychologie de l\u2019environnement mettre \u00e0 contribution son expertise dans toutes sortes de contextes et dans toutes sortes d\u2019\u00e9quipes. \u00bb Mais soyez rassur\u00e9 \u2013 si un psychologue de l\u2019environnement se retrouve chez vous, il ne jugera pas la disposition de votre argenterie ni l\u2019endroit o\u00f9 vous avez plac\u00e9 votre sauci\u00e8re, \u00e0 c\u00f4t\u00e9 du pot de Nutella. Du moins, pas plus que n\u2019importe qui d\u2019autre.","inLanguage":"fr-FR","isPartOf":{"@id":"https:\/\/cpa.ca\/fr\/#website"},"breadcrumb":{"@id":"https:\/\/cpa.ca\/fr\/psychology-month-profile-dr-lindsay-mccunn-and-dr-john-zelenski-environmental-psychology\/#breadcrumblist"},"author":{"@id":"https:\/\/cpa.ca\/fr\/author\/timbleeker\/#author"},"creator":{"@id":"https:\/\/cpa.ca\/fr\/author\/timbleeker\/#author"},"datePublished":"2022-02-25T00:01:59-05:00","dateModified":"2022-05-05T13:54:48-04:00"},{"@type":"WebSite","@id":"https:\/\/cpa.ca\/fr\/#website","url":"https:\/\/cpa.ca\/fr\/","name":"Canadian Psychological Association","description":"The national voice for psychology in Canada","inLanguage":"fr-FR","publisher":{"@id":"https:\/\/cpa.ca\/fr\/#organization"}}]},"og:locale":"fr_FR","og:site_name":"Canadian Psychological Association - The national voice for psychology in Canada","og:type":"article","og:title":"Profils du Mois de la psychologie : Dre Lindsay McCunn et Dr John Zelenski, Environmental Psychology - Canadian Psychological Association","og:description":"Dre Lindsay McCunn Dr. John Zelenski Dre Lindsay McCunn et Dr John Zelenski, Environmental Psychology La psychologie de l\u2019environnement compte deux branches principales. Nous avons parl\u00e9 \u00e0 la Dre Lindsay McCunn de la branche de la psychologie de l\u2019architecture (la conception de b\u00e2timents et de pi\u00e8ces pour le bien-\u00eatre des occupants) et au Dr John Zelenski, de la psychologie \u00e9cologique (qui s\u2019int\u00e9resse aux comportements \u00e9cologiquement durables par l\u2019interm\u00e9diaire de la connexion des gens \u00e0 la nature). \u00c0 propos de Dre Lindsay McCunn et Dr John Zelenski Psychologie de l\u2019environnement \u00ab Quand je dis que je ne vous juge pas, je pense que je veux vraiment dire \u201cpas plus que les autres.\u201d \u00bb. Je suis un peu nerveux \u00e0 l\u2019id\u00e9e que, pendant notre r\u00e9union Zoom, la Dre Lindsay McCunn et le Dr John Zelenski puissent juger mon arri\u00e8re-plan, d\u00e9cid\u00e9ment tr\u00e8s encombr\u00e9. Tous mes appareils \u00e9lectrom\u00e9nagers sont plac\u00e9s sur une tablette derri\u00e8re moi, ce qui donne l\u2019impression (exacte, il se trouve) que mon bureau \u00e0 domicile est un coin exigu pr\u00e8s de la cuisine. La Dre McCunn et le Dr Zelenski sont des psychologues de l\u2019environnement, c\u2019est-\u00e0-dire des sp\u00e9cialistes des espaces que nous occupons et de la mani\u00e8re dont nous interagissons avec eux. Le Dr Zelenski est plut\u00f4t gentil et honn\u00eate \u2013 en tant qu\u2019\u00eatres humains, nous percevons des indices subtils, \u00e0 partir des espaces de chacun, mais cela n\u2019est probablement pas propre aux psychologues de l\u2019environnement. Nous jugeons tous les arri\u00e8re-plans Zoom, ne serait-ce qu\u2019un peu. La Dre Lindsay McCunn est professeure de psychologie \u00e0 l\u2019Universit\u00e9 Vancouver Island. Elle est la pr\u00e9sidente de la Section de psychologie de l\u2019environnement de la SCP et la r\u00e9dactrice en chef adjointe du Journal of Environmental Psychology. Selon elle, les arri\u00e8re-plans Zoom des gens ou la fa\u00e7on dont ils am\u00e9nagent leurs jardins ou leurs espaces de vie sont sources de curiosit\u00e9 pour chacun d\u2019entre nous. \u00ab La fa\u00e7on dont les gens s\u2019expriment, organisent leur domicile et placent des objets importants est vraiment int\u00e9ressante. Sam Gosling a \u00e9crit un livre intitul\u00e9 Snoopologie; il s\u2019agit d\u2019une \u00e9tude portant sur la fa\u00e7on dont on peut d\u00e9duire la personnalit\u00e9 et la fa\u00e7on de penser des gens en fonction de la mani\u00e8re dont ils rangent leurs bibelots et leurs affaires dans leur maison et leur bureau. \u00bb La Dre McCunn se sp\u00e9cialise en psychologie de l\u2019environnement et d\u00e9crit ainsi sa sp\u00e9cialit\u00e9. \u00ab La psychologie de l\u2019environnement, c\u2019est l\u2019\u00e9tude des transactions entre les personnes et les lieux. Et j\u2019entends par l\u00e0 beaucoup de types d\u2019endroits \u2013 un caf\u00e9, un bureau, une \u00e9cole, un parc, un oc\u00e9an, une montagne. Nous \u00e9tudions les diff\u00e9rentes fa\u00e7ons dont les gens interagissent avec leur environnement. De la m\u00eame mani\u00e8re qu\u2019un psychologue social \u00e9tudie et analyse les relations et les interactions entre les individus et les autres, les psychologues de l\u2019environnement \u00e9tudient et analysent les relations entre les personnes et les lieux. Dans mes recherches, je m\u2019int\u00e9resse \u00e0 la fa\u00e7on dont les gens interagissent dans les collectivit\u00e9s et les milieux de travail, en particulier dans les h\u00f4pitaux, les \u00e9coles et les bureaux. \u00c0 ce titre, je me penche sur le personnel, principalement, et sur les personnes qui utilisent les environnements d\u2019une mani\u00e8re diff\u00e9rente de celle \u00e0 laquelle on pourrait s\u2019attendre, comme les \u00e9tudiants et les patients, les enseignants, etc. \u00bb. Le Dr John Zelenski est professeur au d\u00e9partement de psychologie de l\u2019Universit\u00e9 Carleton. Il est \u00e9galement un psychologue de l\u2019environnement, mais il se sp\u00e9cialise dans un domaine bien diff\u00e9rent de celui de la Dre McCunn. On pourrait dire que l\u2019un et l\u2019autre repr\u00e9sentent les deux principales branches de la psychologie de l\u2019environnement \u2013 la psychologie de l\u2019architecture (Dre McCunn) et la psychologie de l\u2019\u00e9cologie (Dr Zelenski). \u00ab En plus d\u2019\u00eatre un psychologue de l\u2019environnement, je me consid\u00e8re aussi comme un psychologue de la personnalit\u00e9 qui se r\u00e9clame de la psychologie positive. Je me suis beaucoup int\u00e9ress\u00e9 \u00e0 ce que nous appelons le rapport \u00e0 la nature, ou ce que d\u2019autres appellent \u201cla connexion avec la nature\u201d. Je parle ici des impressions subjectives des gens : font-ils partie de la nature ou la nature est-elle distincte d\u2019eux et n\u2019a pas grand-chose \u00e0 voir avec leur perception d\u2019eux-m\u00eames? Je me suis aussi beaucoup int\u00e9ress\u00e9 de fa\u00e7on g\u00e9n\u00e9rale par ce que j\u2019appelle un \u201cchemin heureux vers la durabilit\u00e9\u201d. C\u2019est l\u2019id\u00e9e que nous savons que la nature est capable de rendre les gens de bonne humeur. La nature est associ\u00e9e au bonheur, tant sur de longues p\u00e9riodes que sur le moment. Nous savons que les gens qui passent beaucoup de temps dans la nature et qui se sentent tr\u00e8s li\u00e9s \u00e0 la nature adoptent des comportements proenvironnement et \u00e9cologiquement durables. Au cours des derni\u00e8res ann\u00e9es, nous avons commenc\u00e9 \u00e0 penser que l\u2019inverse est peut-\u00eatre vrai aussi. Si l\u2019on peut amener les gens \u00e0 faire quelques petits gestes pour la nature, en adoptant des comportements \u00e9cologiquement durables, il serait possible de se servir de cela pour qu\u2019ils se sentent plus proches de la nature et plus heureux de pratiquer ces activit\u00e9s. Nous pensons que les actions en faveur de l\u2019environnement ne doivent pas n\u00e9cessairement \u00eatre on\u00e9reuses et que nous pouvons les associer \u00e0 des \u00e9motions positives. \u00bb Ce que \u00ab consacrer du temps dans la nature \u00bb signifie pour chaque personne est subjectif. Il s\u2019agit peut-\u00eatre de prendre un week-end pour faire de la randonn\u00e9e dans les collines, de passer une journ\u00e9e \u00e0 p\u00eacher sur la glace ou simplement d\u2019aller dans son jardin et s\u2019occuper de son potager de radis. Pour la Dre McCunn, cela a entra\u00een\u00e9 de grands changements depuis le d\u00e9but de la pand\u00e9mie de COVID-19. Elle nous parle par Zoom dans ce qui semble \u00eatre un chalet dans les bois. Depuis quelques ann\u00e9es, elle et sa famille vivaient dans le centre-ville de Nanaimo, en Colombie-Britannique, en face du service d\u2019ambulance, du service de police et de la caserne de pompiers. Les sir\u00e8nes ont augment\u00e9 consid\u00e9rablement lorsque la pand\u00e9mie a commenc\u00e9, leurs habitudes de sommeil ont commenc\u00e9 \u00e0 en \u00eatre affect\u00e9es et ils ont d\u00e9cid\u00e9 de louer un endroit \u00e0 la campagne. \u00ab Ce fut en quelque sorte une bonne \u00e9tude de cas en psychologie de l\u2019environnement, dans la mesure o\u00f9 nous pouvions r\u00e9aliser ce qui nous stimulait dans notre environnement familial, puis d\u00e9cider comment le modifier pour notre sant\u00e9 mentale. Nous avons donc pens\u00e9 \u00e0 d\u00e9m\u00e9nager dans un cadre naturel plus vaste o\u00f9 nous pourrions avoir un peu plus de contr\u00f4le sur les choses qui nous stimulent. Nous avons \u00e9t\u00e9 tr\u00e8s chanceux de pouvoir louer quelque chose \u00e0 la campagne. C\u2019\u00e9tait int\u00e9ressant, parce que j\u2019\u00e9tais tr\u00e8s attach\u00e9e \u00e0 la maison que nous poss\u00e9dions. L\u2019une des choses que nous \u00e9tudions, comme psychologues de l\u2019environnement, est le \u201csentiment d\u2019appartenance\u201d ou un sentiment d\u2019appartenance \u00e0 un lieu, un sentiment identitaire ou un sentiment de d\u00e9pendance. Au d\u00e9but de la pand\u00e9mie, j\u2019ai entendu beaucoup de questions sur la fa\u00e7on dont les gens faisaient face au sentiment de perte qu\u2019ils ressentaient depuis qu\u2019ils travaillaient \u00e0 domicile. Pas seulement un sentiment de perte en rapport avec des \u00e9l\u00e9ments sociaux, mais aussi une perte des moyens habituels par lesquels ils se rendaient \u00e0 leur lieu de travail. Peut-\u00eatre prenaient-ils le m\u00eame autobus tous les jours ou arr\u00eataient-ils au m\u00eame caf\u00e9 lorsqu\u2019ils se rendaient \u00e0 l\u2019\u00e9cole ou au travail. M\u00eame le caract\u00e8re physique de l\u2019environnement de bureau ou de la salle de classe elle-m\u00eame \u2013 cet environnement leur manquait. Je me suis donc demand\u00e9 comment je r\u00e9agirais lorsque je m\u2019\u00e9loignerais de mon environnement familier auquel je m\u2019\u00e9tais vraiment attach\u00e9. Je ne voulais pas me mettre dans une position o\u00f9 je perdrais mon lien avec mon cadre habituel, mais je me suis rapidement attach\u00e9e \u00e0 cet endroit et aux caract\u00e9ristiques naturelles qui l\u2019entourent. Ce fut une belle aventure d\u2019explorer la psychologie de l\u2019environnement de l\u2019int\u00e9rieur et dans ce contexte. \u00bb Se sentir proche de la nature, ce peut \u00eatre aussi simple que de pouvoir sortir et toucher \u00e0 un arbre, ou regarder par la fen\u00eatre une montagne ou une vari\u00e9t\u00e9 d\u2019esp\u00e8ces d\u2019oiseaux. Alors, comment cela peut-il se traduire par des comportements plus respectueux de l\u2019environnement, au moment o\u00f9 le changement climatique est devenu le probl\u00e8me le plus urgent de notre \u00e9poque? Le Dr Zelenski donne l\u2019exemple que voici. \u00ab Nous avons beaucoup de bonnes preuves circonstancielles et d\u2019\u00e9tudes de laboratoire, et nous essayons de les assembler. Quelques programmes ont \u00e9t\u00e9 prometteurs! Mon ancienne \u00e9tudiante, amie et collaboratrice, Lisa Nisbet, a collabor\u00e9 avec la Fondation David Suzuki pour relever le D\u00e9fi nature 30\u00d730. Ce d\u00e9fi consiste \u00e0 consacrer 30 minutes dans la nature chaque jour pendant 30 jours. Les personnes qui s\u2019inscrivent \u00e0 ce d\u00e9fi ont tendance \u00e0 \u00eatre plut\u00f4t \u00e9cologistes et d\u00e9j\u00e0 tr\u00e8s proches de la nature. Mais au cours de ce mois, cette connexion semble se d\u00e9velopper. Ce n\u2019est pas un essai contr\u00f4l\u00e9 randomis\u00e9, mais il semble que le fait de passer du temps dans la nature donne \u00e0 ces personnes le sentiment d\u2019\u00eatre plus proches, ce qui les incite \u00e0 adopter des comportements \u00e9cologiquement durables. \u00bb L\u2019\u00e9cologie est une division de la psychologie de l\u2019environnement (relativement) nouvelle, et elle a sans aucun doute pris beaucoup d\u2019ampleur au cours des 20 derni\u00e8res ann\u00e9es, les changements climatiques \u00e9tant rapidement devenus un sujet de premier plan pour beaucoup d\u2019entre nous. Le Dr Zelenski n\u2019est pas le seul \u00e0 avoir \u00e9volu\u00e9 dans cette direction. \u00ab L\u2019attention et l\u2019importance accord\u00e9es \u00e0 l\u2019aspect \u00e9cologique de la psychologie de l\u2019environnement semblent s\u2019\u00eatre accrues au cours des 10 ou 15 derni\u00e8res ann\u00e9es. Je suis venu \u00e0 la psychologie \u00e9cologique apr\u00e8s mon doctorat, par simple int\u00e9r\u00eat personnel, et j\u2019ai l\u2019impression d\u2019\u00eatre l\u2019un des millions de personnes qui ont suivi le mouvement, et ce, pour plusieurs raisons. Les gens semblent de plus en plus manifester des sympt\u00f4mes de d\u00e9pression, d\u2019anxi\u00e9t\u00e9, etc., et la nature semble offrir un r\u00e9pit agr\u00e9able. De plus, la prise de conscience relative aux changements climatiques ne cesse de cro\u00eetre, car nous en voyons de plus en plus les effets. Et les d\u00e9cideurs politiques souhaitent savoir ce que les sciences sociales peuvent apporter pour r\u00e9soudre ces probl\u00e8mes. \u00bb La dimension \u00e9cologique de la discipline a \u00e9man\u00e9 naturellement de la branche traditionnelle de la psychologie de l\u2019architecture, qui existe depuis les ann\u00e9es 1960. Selon la Dre McCunn, il existe quelques programmes d\u2019\u00e9tudes sup\u00e9rieures officiels en \u00ab psychologie de l\u2019environnement \u00bb au Canada, mais il y en a plus en Angleterre et aux \u00c9tats-Unis, aux Pays-Bas et en Am\u00e9rique du Sud. Donc, lorsqu\u2019elle dit aux gens qu\u2019elle est une \u00ab psychologue de l\u2019environnement \u00bb, ceux-ci savent souvent ce qu\u2019elle veut dire. \u00ab Certaines personnes, \u00e0 juste titre, divisent la dimension de la psychologie de l\u2019architecture et la dimension de la psychologie de l\u2019\u00e9cologie. Je le fais aussi si je veux expliquer aux gens ce que j\u2019\u00e9tudie, parce que je suis plut\u00f4t du c\u00f4t\u00e9 de l\u2019architecture. Je travaille avec des ing\u00e9nieurs, des gestionnaires d\u2019installations et des urbanistes, mais j\u2019ai aussi des coll\u00e8gues, comme John, qui s\u2019int\u00e9ressent au lien avec la nature et travaillent avec des personnes qui \u00e9tudient les attitudes et les comportements proenvironnement. L\u2019id\u00e9e de conservation de la nature est devenue tr\u00e8s populaire dans le domaine de la psychologie de l\u2019environnement, sans pour autant prendre le pas sur la dimension architecturale, qui s\u2019int\u00e9resse \u00e0 l\u2019infrastructure des immeubles, etc. En fait, la psychologie de l\u2019environnement a d\u00e9but\u00e9 dans le contexte de l\u2019architecture, mais elle s\u2019est largement \u00e9tendue \u00e0 son autre volet, qui consiste \u00e0 poser aux gens des questions sur leur conscience \u00e9cologique et leur rapport \u00e0 la nature. \u00bb Les deux branches vont de pair. Pensez \u00e0 la tendance \u00e0 construire des b\u00e2timents \u00ab verts \u00bb, avec du chauffage \u00e0 faible consommation d\u2019\u00e9nergie, des panneaux solaires, voire un jardin sur le toit. Selon la Dre McCunn, \u00ab Quand un ing\u00e9nieur me demande : \u201cdevrions-nous concevoir ce b\u00e2timent en tenant compte de la durabilit\u00e9\u201d, il veut en r\u00e9alit\u00e9 savoir \u2013 \u201cles gens vont-ils le remarquer? S\u2019en soucient-ils? Vont-ils apporter des changements \u00e0 leurs comportements \u00e0 l\u2019int\u00e9rieur (et \u00e0 l\u2019ext\u00e9rieur) de l\u2019immeuble pour cette raison?\u201d Je peux les aider \u00e0 \u00e9tudier la mani\u00e8re dont les gens se comportent, travaillent et fonctionnent dans des b\u00e2timents plus (ou moins) durables. J\u2019ai fait une \u00e9tude dans une \u00e9cole d\u2019\u00e9tudes sup\u00e9rieures qui a montr\u00e9 que le fait qu\u2019un immeuble de bureaux soit \u201cvert\u201d ou durable ne signifie pas n\u00e9cessairement que cela permettra de pr\u00e9dire une forte productivit\u00e9 ou une forte satisfaction. Il est important de garder un \u0153il critique sur ce que l\u2019on attend d\u2019une conception durable et sur ce que l\u2019on n\u2019attend pas. \u00bb Pensez \u00e0 des espaces dans lesquels vous vous \u00eates sentis imm\u00e9diatement \u00e0 l\u2019aise avec les personnes qui vous entouraient \u2013 et d\u2019autres o\u00f9 ce n\u2019\u00e9tait pas le cas. Il est possible que ce ne soit pas les personnes pr\u00e9sentes qui en soient la cause, mais la conception de l\u2019espace qui a rendu les interactions plus embarrassantes, ou qui a rendu cette pi\u00e8ce, ce b\u00e2timent ou ce wagon plus confortable. La Dre McClunn pr\u00e9cise. \u00ab Si l\u2019on veut qu\u2019un certain espace soit accueillant et confortable, on peut le concevoir pour qu\u2019un certain nombre de personnes puissent s\u2019y asseoir \u00e0 une certaine distance. Je pense \u00e0 la conception d\u2019un caf\u00e9, ou un restaurant ou m\u00eame une salle de classe o\u00f9 l\u2019on veut que les gens s\u2019assoient d\u2019une certaine fa\u00e7on et cohabitent d\u2019une certaine mani\u00e8re. Je pense qu\u2019il est important d\u2019utiliser diff\u00e9rentes m\u00e9thodes, tout comme les autres psychologues le font. Nous sommes capables d\u2019int\u00e9grer une vari\u00e9t\u00e9 de m\u00e9thodes combin\u00e9es dans notre travail. Nous utilisons l\u2019observation naturaliste pour observer et voir comment les gens se d\u00e9placent et se comportent dans un espace afin de prendre des d\u00e9cisions de conception \u00e0 partir de nos observations. Nous effectuons beaucoup de sondages et d\u2019entrevues et, \u00e0 partir de ceux-ci, nous pouvons aider les architectes et les concepteurs \u00e0 rendre les b\u00e2timents les plus humains possible. Si l\u2019objet du travail clinique et d\u2019autres types d\u2019intervention psychologique est d\u2019aider les gens \u00e0 se sentir bien, alors la psychologie de l\u2019environnement est tout \u00e0 fait en phase avec cela. Nous voulons que les b\u00e2timents soient con\u00e7us de mani\u00e8re \u00e0 aider les gens \u00e0 se sentir aussi bien, motiv\u00e9s, enthousiastes et en forme que possible. \u00bb Le Dr Zelenski jette \u00e9galement un pont entre les deux c\u00f4t\u00e9s de la psychologie de l\u2019environnement, et ce, de diff\u00e9rentes mani\u00e8res. La collaboration avec des groupes qui font d\u00e9j\u00e0 un travail environnemental lui permet de recueillir plus facilement des donn\u00e9es, et l\u2019analyse de ces donn\u00e9es permet \u00e0 ces groupes de fonctionner de mani\u00e8re plus efficace et efficiente. \u00ab J\u2019ai collabor\u00e9 avec un architecte, faisant ainsi le pont entre ces deux composantes de la psychologie de l\u2019environnement. Il \u00e9tait tr\u00e8s int\u00e9ress\u00e9 par la construction de b\u00e2timents qui donneraient envie aux gens de se comporter de mani\u00e8re \u00e9cologique. De m\u00eame, il ne s\u2019agit peut-\u00eatre pas seulement de l\u2019int\u00e9rieur du b\u00e2timent, mais aussi des espaces naturels proches du b\u00e2timent qui pourraient encourager ces comportements. Il s\u2019agit de poser une question plus nuanc\u00e9e sur les types de milieux naturels \u00e0 proximit\u00e9 qui pourraient aider les gens \u00e0 se sentir mieux, \u00e0 \u00eatre plus heureux et plus productifs. Il y a un petit organisme sans but lucratif qui fournit des trousses d\u2019analyse de l\u2019eau. Il les distribue aux gens, qui les utilisent pour tester la qualit\u00e9 de l\u2019eau \u00e0 proximit\u00e9; les gens t\u00e9l\u00e9chargent ensuite leurs donn\u00e9es dans un genre de base de donn\u00e9es participative qui permet de voir si le lac ou la rivi\u00e8re pr\u00e8s de chez eux est en bon ou en mauvais \u00e9tat, et comment cela \u00e9volue au fil du temps. Il serait difficile pour moi de monter une exp\u00e9rience dans laquelle je distribuerais des tas de trousses d\u2019analyse de l\u2019eau, mais je peux essayer de suivre les personnes qui le font d\u00e9j\u00e0 pour voir si cela change leur sentiment de connexion avec la nature, si cela les rend heureux et si cela leur donne envie de faire d\u2019autres choses bonnes pour l\u2019environnement que de simplement tester l\u2019eau. \u00bb Depuis la mise en place de mesures de confinement en raison de la pand\u00e9mie, nous entendons beaucoup de personnes dire qu\u2019elles appr\u00e9cient davantage la nature. C\u2019est un moyen s\u00fbr de sortir de chez soi. Si on ne peut pas aller dans un centre commercial bond\u00e9 ou \u00e0 un concert, on peut toujours aller dans un parc et se promener. Les gens voient la nature comme une source de bien-\u00eatre et un bon moyen de s\u2019adapter, et certaines \u00e9tudes indiquent que la nature est l\u2019une des choses les plus positives que les gens ont ressenties au cours des deux derni\u00e8res ann\u00e9es, o\u00f9 la distanciation physique \u00e9tait impos\u00e9e. Mais ce lien avec la nature, ainsi que la prise de conscience de la grave menace que repr\u00e9sente le changement climatique, cr\u00e9e \u00e0 certains \u00e9gards de nouveaux probl\u00e8mes. Selon le Dr Zelenski, \u00ab Beaucoup de gens parlent d\u2019\u00e9coanxi\u00e9t\u00e9 et le fait que les gens soient de plus en plus conscients des changements climatiques pourrait \u00eatre une arme \u00e0 double tranchant. Cela peut donc \u00eatre motivant \u2013 ce qui est un r\u00e9sultat positif, les gens voulant se comporter d\u2019une mani\u00e8re plus \u00e9cologique \u2013 mais certaines personnes pourraient \u00eatre boulevers\u00e9es ou inqui\u00e8tes \u00e0 tel point que cela cr\u00e9era de nouvelles formes de stress et d\u2019inqui\u00e9tude qui, chez elles, peuvent \u00eatre inadapt\u00e9es. \u00bb L\u2019un des moyens de lutter contre l\u2019\u00e9coanxi\u00e9t\u00e9, un nouveau mot \u00e0 la mode dans le domaine de la pr\u00e9servation de l\u2019environnement, consiste \u00e0 faire conna\u00eetre les psychologues de l\u2019environnement et \u00e0 solliciter leurs conseils. Cette sensibilisation accrue se ressent \u00e9galement dans la dimension architecturale, car les contributions des experts de ce domaine sont maintenant per\u00e7ues par beaucoup comme \u00e9tant inestimables. La Dre McCunn dit qu\u2019elle a vu ce changement directement. \u00ab Lorsque je rencontre des ing\u00e9nieurs, des architectes et des urbanistes, je constate qu\u2019ils sont davantage sensibili\u00e9s \u00e0 la psychologie de l\u2019environnement et qu\u2019ils sont tout \u00e0 fait dispos\u00e9s \u00e0 travailler avec nous. Lorsque je faisais ma ma\u00eetrise, j\u2019ai remarqu\u00e9 que tr\u00e8s peu de personnes occupant ces postes voulaient travailler avec un sp\u00e9cialiste en sciences sociales. Plusieurs d\u2019entre eux disaient qu\u2019ils faisaient ce genre de recherche accessoirement, et qu\u2019ils \u201csavaient d\u00e9j\u00e0 comment \u00e9tudier les gens\u201d. Aujourd\u2019hui, ils font appel \u00e0 moi car ils veulent int\u00e9grer cette dimension professionnelle \u00e0 leur activit\u00e9 ou \u00e0 leurs processus. La cognition spatiale, par exemple, est un sujet tr\u00e8s habituel en psychologie de l\u2019environnement. Je pense qu\u2019il est important de le mentionner car la population vieillit. Les psychologues de l\u2019environnement consultent souvent les concepteurs pour savoir comment aider les personnes atteintes de d\u00e9mence \u00e0 s\u2019orienter dans une maison de soins, par exemple. Nous pouvons les observer et les aider avec des pancartes et des symboles, et des moyens d\u2019int\u00e9grer leur psychologie dans la conception pour leur faciliter la vie. \u00bb \u00cates-vous d\u00e9j\u00e0 all\u00e9 dans un magasin o\u00f9 il y a, sur le sol, un motif tr\u00e8s simple qui se transforme un peu \u00e0 l\u2019approche des toilettes, et un peu plus pr\u00e8s de la caisse? Peut-\u00eatre y a-t-il des rampes d\u2019escalier de couleur vive le long des murs, et le si\u00e8ge des toilettes est-il d\u2019une couleur nettement diff\u00e9rente du reste des toilettes. Le magasin est bien \u00e9clair\u00e9, mais pas trop, car il y a peu de surfaces r\u00e9fl\u00e9chissantes et pas de miroirs. Un magasin qui ressemble \u00e0 \u00e7a a probablement \u00e9t\u00e9 con\u00e7u pour \u00eatre accessible aux personnes atteintes de d\u00e9mence, avec l\u2019aide de psychologues de l\u2019environnement. Les personnes atteintes de la maladie d\u2019Alzheimer et de diff\u00e9rents types de d\u00e9mence sont g\u00e9n\u00e9ralement suivies par une \u00e9quipe de soins, notamment par un neuroscientifique (voir le portrait de la neuropsychologie clinique pr\u00e9sent\u00e9 plus t\u00f4t ce mois-ci). De plus en plus, les psychologues de l\u2019environnement travaillent au sein d\u2019\u00e9quipes interdisciplinaires plus larges, et les neurosciences elles-m\u00eames prennent une place plus importante dans la discipline. La Dre McCunn dit qu\u2019elle le constate gr\u00e2ce aux articles propos\u00e9s au Journal of Environmental Psychology. \u00ab Il y a beaucoup d\u2019articles qui fusionnent les neurosciences et la psychologie de l\u2019environnement. Je fais aussi cela dans mon propre travail \u2013 j\u2019ai presque termin\u00e9 une deuxi\u00e8me ma\u00eetrise en neurosciences appliqu\u00e9es, simplement pour approfondir mes recherches dans le domaine des neurosciences environnementales. J\u2019aime chercher \u00e0 comprendre des concepts tels que \u201cque se passe-t-il dans le cerveau lorsque nous ressentons un attachement \u00e0 un lieu? Est-ce diff\u00e9rent de l\u2019attachement que l\u2019on ressent face \u00e0 une personne? Que se passe-t-il dans le cerveau lorsque nous rencontrons diff\u00e9rents contextes?\u201d Ce sont des questions importantes qui, je pense, sont de plus en plus populaires. \u00bb La psychologie de l\u2019environnement devenant une discipline de plus en plus demand\u00e9e, l\u2019expertise des personnes travaillant dans ce domaine est appliqu\u00e9e \u00e0 une vari\u00e9t\u00e9 de sujets sans cesse croissante. La Dre McCunn esp\u00e8re que cette tendance se poursuivra, afin que l\u2019ensemble des comp\u00e9tences de ses coll\u00e8gues puisse \u00eatre utilis\u00e9 pour aider \u00e0 r\u00e9soudre des probl\u00e8mes importants. \u00ab Je souhaite que la psychologie de l\u2019environnement fasse partie d\u2019un grand nombre d\u2019\u00e9quipes tr\u00e8s diverses. Bien s\u00fbr, les architectes et les urbanistes, mais aussi les cliniciens, les m\u00e9decins, les neuroscientifiques, etc. Je crois que nous sommes de bons partenaires et nous pouvons ajouter des facettes aux questions de recherche qui peuvent enrichir une r\u00e9ponse et la rendre plus compl\u00e8te. Il est tr\u00e8s difficile de tirer des conclusions \u00e0 partir de quelques variables seulement. La mobilisation des donn\u00e9es et de la mod\u00e9lisation dans le domaine de la psychologie de l\u2019environnement peut nous aider \u00e0 aider les autres \u00e0 obtenir des r\u00e9ponses plus fiables \u00e0 de vastes questions de soci\u00e9t\u00e9 sur ce qui pousse les gens \u00e0 agir et \u00e0 penser de telle ou telle mani\u00e8re. J\u2019aimerais voir la psychologie de l\u2019environnement mettre \u00e0 contribution son expertise dans toutes sortes de contextes et dans toutes sortes d\u2019\u00e9quipes. \u00bb Mais soyez rassur\u00e9 \u2013 si un psychologue de l\u2019environnement se retrouve chez vous, il ne jugera pas la disposition de votre argenterie ni l\u2019endroit o\u00f9 vous avez plac\u00e9 votre sauci\u00e8re, \u00e0 c\u00f4t\u00e9 du pot de Nutella. Du moins, pas plus que n\u2019importe qui d\u2019autre.","og:url":"https:\/\/cpa.ca\/fr\/psychology-month-profile-dr-lindsay-mccunn-and-dr-john-zelenski-environmental-psychology\/","og:image":"https:\/\/cpa.ca\/wp-content\/uploads\/2023\/05\/android-chrome-512x512-onwhite.png","og:image:secure_url":"https:\/\/cpa.ca\/wp-content\/uploads\/2023\/05\/android-chrome-512x512-onwhite.png","article:published_time":"2022-02-25T05:01:59+00:00","article:modified_time":"2022-05-05T17:54:48+00:00","article:publisher":"https:\/\/www.facebook.com\/CPA.SCP\/","twitter:card":"summary","twitter:site":"@CPA_SCP","twitter:title":"Profils du Mois de la psychologie : Dre Lindsay McCunn et Dr John Zelenski, Environmental Psychology - Canadian Psychological Association","twitter:description":"Dre Lindsay McCunn Dr. John Zelenski Dre Lindsay McCunn et Dr John Zelenski, Environmental Psychology La psychologie de l\u2019environnement compte deux branches principales. Nous avons parl\u00e9 \u00e0 la Dre Lindsay McCunn de la branche de la psychologie de l\u2019architecture (la conception de b\u00e2timents et de pi\u00e8ces pour le bien-\u00eatre des occupants) et au Dr John Zelenski, de la psychologie \u00e9cologique (qui s\u2019int\u00e9resse aux comportements \u00e9cologiquement durables par l\u2019interm\u00e9diaire de la connexion des gens \u00e0 la nature). \u00c0 propos de Dre Lindsay McCunn et Dr John Zelenski Psychologie de l\u2019environnement \u00ab Quand je dis que je ne vous juge pas, je pense que je veux vraiment dire \u201cpas plus que les autres.\u201d \u00bb. Je suis un peu nerveux \u00e0 l\u2019id\u00e9e que, pendant notre r\u00e9union Zoom, la Dre Lindsay McCunn et le Dr John Zelenski puissent juger mon arri\u00e8re-plan, d\u00e9cid\u00e9ment tr\u00e8s encombr\u00e9. Tous mes appareils \u00e9lectrom\u00e9nagers sont plac\u00e9s sur une tablette derri\u00e8re moi, ce qui donne l\u2019impression (exacte, il se trouve) que mon bureau \u00e0 domicile est un coin exigu pr\u00e8s de la cuisine. La Dre McCunn et le Dr Zelenski sont des psychologues de l\u2019environnement, c\u2019est-\u00e0-dire des sp\u00e9cialistes des espaces que nous occupons et de la mani\u00e8re dont nous interagissons avec eux. Le Dr Zelenski est plut\u00f4t gentil et honn\u00eate \u2013 en tant qu\u2019\u00eatres humains, nous percevons des indices subtils, \u00e0 partir des espaces de chacun, mais cela n\u2019est probablement pas propre aux psychologues de l\u2019environnement. Nous jugeons tous les arri\u00e8re-plans Zoom, ne serait-ce qu\u2019un peu. La Dre Lindsay McCunn est professeure de psychologie \u00e0 l\u2019Universit\u00e9 Vancouver Island. Elle est la pr\u00e9sidente de la Section de psychologie de l\u2019environnement de la SCP et la r\u00e9dactrice en chef adjointe du Journal of Environmental Psychology. Selon elle, les arri\u00e8re-plans Zoom des gens ou la fa\u00e7on dont ils am\u00e9nagent leurs jardins ou leurs espaces de vie sont sources de curiosit\u00e9 pour chacun d\u2019entre nous. \u00ab La fa\u00e7on dont les gens s\u2019expriment, organisent leur domicile et placent des objets importants est vraiment int\u00e9ressante. Sam Gosling a \u00e9crit un livre intitul\u00e9 Snoopologie; il s\u2019agit d\u2019une \u00e9tude portant sur la fa\u00e7on dont on peut d\u00e9duire la personnalit\u00e9 et la fa\u00e7on de penser des gens en fonction de la mani\u00e8re dont ils rangent leurs bibelots et leurs affaires dans leur maison et leur bureau. \u00bb La Dre McCunn se sp\u00e9cialise en psychologie de l\u2019environnement et d\u00e9crit ainsi sa sp\u00e9cialit\u00e9. \u00ab La psychologie de l\u2019environnement, c\u2019est l\u2019\u00e9tude des transactions entre les personnes et les lieux. Et j\u2019entends par l\u00e0 beaucoup de types d\u2019endroits \u2013 un caf\u00e9, un bureau, une \u00e9cole, un parc, un oc\u00e9an, une montagne. Nous \u00e9tudions les diff\u00e9rentes fa\u00e7ons dont les gens interagissent avec leur environnement. De la m\u00eame mani\u00e8re qu\u2019un psychologue social \u00e9tudie et analyse les relations et les interactions entre les individus et les autres, les psychologues de l\u2019environnement \u00e9tudient et analysent les relations entre les personnes et les lieux. Dans mes recherches, je m\u2019int\u00e9resse \u00e0 la fa\u00e7on dont les gens interagissent dans les collectivit\u00e9s et les milieux de travail, en particulier dans les h\u00f4pitaux, les \u00e9coles et les bureaux. \u00c0 ce titre, je me penche sur le personnel, principalement, et sur les personnes qui utilisent les environnements d\u2019une mani\u00e8re diff\u00e9rente de celle \u00e0 laquelle on pourrait s\u2019attendre, comme les \u00e9tudiants et les patients, les enseignants, etc. \u00bb. Le Dr John Zelenski est professeur au d\u00e9partement de psychologie de l\u2019Universit\u00e9 Carleton. Il est \u00e9galement un psychologue de l\u2019environnement, mais il se sp\u00e9cialise dans un domaine bien diff\u00e9rent de celui de la Dre McCunn. On pourrait dire que l\u2019un et l\u2019autre repr\u00e9sentent les deux principales branches de la psychologie de l\u2019environnement \u2013 la psychologie de l\u2019architecture (Dre McCunn) et la psychologie de l\u2019\u00e9cologie (Dr Zelenski). \u00ab En plus d\u2019\u00eatre un psychologue de l\u2019environnement, je me consid\u00e8re aussi comme un psychologue de la personnalit\u00e9 qui se r\u00e9clame de la psychologie positive. Je me suis beaucoup int\u00e9ress\u00e9 \u00e0 ce que nous appelons le rapport \u00e0 la nature, ou ce que d\u2019autres appellent \u201cla connexion avec la nature\u201d. Je parle ici des impressions subjectives des gens : font-ils partie de la nature ou la nature est-elle distincte d\u2019eux et n\u2019a pas grand-chose \u00e0 voir avec leur perception d\u2019eux-m\u00eames? Je me suis aussi beaucoup int\u00e9ress\u00e9 de fa\u00e7on g\u00e9n\u00e9rale par ce que j\u2019appelle un \u201cchemin heureux vers la durabilit\u00e9\u201d. C\u2019est l\u2019id\u00e9e que nous savons que la nature est capable de rendre les gens de bonne humeur. La nature est associ\u00e9e au bonheur, tant sur de longues p\u00e9riodes que sur le moment. Nous savons que les gens qui passent beaucoup de temps dans la nature et qui se sentent tr\u00e8s li\u00e9s \u00e0 la nature adoptent des comportements proenvironnement et \u00e9cologiquement durables. Au cours des derni\u00e8res ann\u00e9es, nous avons commenc\u00e9 \u00e0 penser que l\u2019inverse est peut-\u00eatre vrai aussi. Si l\u2019on peut amener les gens \u00e0 faire quelques petits gestes pour la nature, en adoptant des comportements \u00e9cologiquement durables, il serait possible de se servir de cela pour qu\u2019ils se sentent plus proches de la nature et plus heureux de pratiquer ces activit\u00e9s. Nous pensons que les actions en faveur de l\u2019environnement ne doivent pas n\u00e9cessairement \u00eatre on\u00e9reuses et que nous pouvons les associer \u00e0 des \u00e9motions positives. \u00bb Ce que \u00ab consacrer du temps dans la nature \u00bb signifie pour chaque personne est subjectif. Il s\u2019agit peut-\u00eatre de prendre un week-end pour faire de la randonn\u00e9e dans les collines, de passer une journ\u00e9e \u00e0 p\u00eacher sur la glace ou simplement d\u2019aller dans son jardin et s\u2019occuper de son potager de radis. Pour la Dre McCunn, cela a entra\u00een\u00e9 de grands changements depuis le d\u00e9but de la pand\u00e9mie de COVID-19. Elle nous parle par Zoom dans ce qui semble \u00eatre un chalet dans les bois. Depuis quelques ann\u00e9es, elle et sa famille vivaient dans le centre-ville de Nanaimo, en Colombie-Britannique, en face du service d\u2019ambulance, du service de police et de la caserne de pompiers. Les sir\u00e8nes ont augment\u00e9 consid\u00e9rablement lorsque la pand\u00e9mie a commenc\u00e9, leurs habitudes de sommeil ont commenc\u00e9 \u00e0 en \u00eatre affect\u00e9es et ils ont d\u00e9cid\u00e9 de louer un endroit \u00e0 la campagne. \u00ab Ce fut en quelque sorte une bonne \u00e9tude de cas en psychologie de l\u2019environnement, dans la mesure o\u00f9 nous pouvions r\u00e9aliser ce qui nous stimulait dans notre environnement familial, puis d\u00e9cider comment le modifier pour notre sant\u00e9 mentale. Nous avons donc pens\u00e9 \u00e0 d\u00e9m\u00e9nager dans un cadre naturel plus vaste o\u00f9 nous pourrions avoir un peu plus de contr\u00f4le sur les choses qui nous stimulent. Nous avons \u00e9t\u00e9 tr\u00e8s chanceux de pouvoir louer quelque chose \u00e0 la campagne. C\u2019\u00e9tait int\u00e9ressant, parce que j\u2019\u00e9tais tr\u00e8s attach\u00e9e \u00e0 la maison que nous poss\u00e9dions. L\u2019une des choses que nous \u00e9tudions, comme psychologues de l\u2019environnement, est le \u201csentiment d\u2019appartenance\u201d ou un sentiment d\u2019appartenance \u00e0 un lieu, un sentiment identitaire ou un sentiment de d\u00e9pendance. Au d\u00e9but de la pand\u00e9mie, j\u2019ai entendu beaucoup de questions sur la fa\u00e7on dont les gens faisaient face au sentiment de perte qu\u2019ils ressentaient depuis qu\u2019ils travaillaient \u00e0 domicile. Pas seulement un sentiment de perte en rapport avec des \u00e9l\u00e9ments sociaux, mais aussi une perte des moyens habituels par lesquels ils se rendaient \u00e0 leur lieu de travail. Peut-\u00eatre prenaient-ils le m\u00eame autobus tous les jours ou arr\u00eataient-ils au m\u00eame caf\u00e9 lorsqu\u2019ils se rendaient \u00e0 l\u2019\u00e9cole ou au travail. M\u00eame le caract\u00e8re physique de l\u2019environnement de bureau ou de la salle de classe elle-m\u00eame \u2013 cet environnement leur manquait. Je me suis donc demand\u00e9 comment je r\u00e9agirais lorsque je m\u2019\u00e9loignerais de mon environnement familier auquel je m\u2019\u00e9tais vraiment attach\u00e9. Je ne voulais pas me mettre dans une position o\u00f9 je perdrais mon lien avec mon cadre habituel, mais je me suis rapidement attach\u00e9e \u00e0 cet endroit et aux caract\u00e9ristiques naturelles qui l\u2019entourent. Ce fut une belle aventure d\u2019explorer la psychologie de l\u2019environnement de l\u2019int\u00e9rieur et dans ce contexte. \u00bb Se sentir proche de la nature, ce peut \u00eatre aussi simple que de pouvoir sortir et toucher \u00e0 un arbre, ou regarder par la fen\u00eatre une montagne ou une vari\u00e9t\u00e9 d\u2019esp\u00e8ces d\u2019oiseaux. Alors, comment cela peut-il se traduire par des comportements plus respectueux de l\u2019environnement, au moment o\u00f9 le changement climatique est devenu le probl\u00e8me le plus urgent de notre \u00e9poque? Le Dr Zelenski donne l\u2019exemple que voici. \u00ab Nous avons beaucoup de bonnes preuves circonstancielles et d\u2019\u00e9tudes de laboratoire, et nous essayons de les assembler. Quelques programmes ont \u00e9t\u00e9 prometteurs! Mon ancienne \u00e9tudiante, amie et collaboratrice, Lisa Nisbet, a collabor\u00e9 avec la Fondation David Suzuki pour relever le D\u00e9fi nature 30\u00d730. Ce d\u00e9fi consiste \u00e0 consacrer 30 minutes dans la nature chaque jour pendant 30 jours. Les personnes qui s\u2019inscrivent \u00e0 ce d\u00e9fi ont tendance \u00e0 \u00eatre plut\u00f4t \u00e9cologistes et d\u00e9j\u00e0 tr\u00e8s proches de la nature. Mais au cours de ce mois, cette connexion semble se d\u00e9velopper. Ce n\u2019est pas un essai contr\u00f4l\u00e9 randomis\u00e9, mais il semble que le fait de passer du temps dans la nature donne \u00e0 ces personnes le sentiment d\u2019\u00eatre plus proches, ce qui les incite \u00e0 adopter des comportements \u00e9cologiquement durables. \u00bb L\u2019\u00e9cologie est une division de la psychologie de l\u2019environnement (relativement) nouvelle, et elle a sans aucun doute pris beaucoup d\u2019ampleur au cours des 20 derni\u00e8res ann\u00e9es, les changements climatiques \u00e9tant rapidement devenus un sujet de premier plan pour beaucoup d\u2019entre nous. Le Dr Zelenski n\u2019est pas le seul \u00e0 avoir \u00e9volu\u00e9 dans cette direction. \u00ab L\u2019attention et l\u2019importance accord\u00e9es \u00e0 l\u2019aspect \u00e9cologique de la psychologie de l\u2019environnement semblent s\u2019\u00eatre accrues au cours des 10 ou 15 derni\u00e8res ann\u00e9es. Je suis venu \u00e0 la psychologie \u00e9cologique apr\u00e8s mon doctorat, par simple int\u00e9r\u00eat personnel, et j\u2019ai l\u2019impression d\u2019\u00eatre l\u2019un des millions de personnes qui ont suivi le mouvement, et ce, pour plusieurs raisons. Les gens semblent de plus en plus manifester des sympt\u00f4mes de d\u00e9pression, d\u2019anxi\u00e9t\u00e9, etc., et la nature semble offrir un r\u00e9pit agr\u00e9able. De plus, la prise de conscience relative aux changements climatiques ne cesse de cro\u00eetre, car nous en voyons de plus en plus les effets. Et les d\u00e9cideurs politiques souhaitent savoir ce que les sciences sociales peuvent apporter pour r\u00e9soudre ces probl\u00e8mes. \u00bb La dimension \u00e9cologique de la discipline a \u00e9man\u00e9 naturellement de la branche traditionnelle de la psychologie de l\u2019architecture, qui existe depuis les ann\u00e9es 1960. Selon la Dre McCunn, il existe quelques programmes d\u2019\u00e9tudes sup\u00e9rieures officiels en \u00ab psychologie de l\u2019environnement \u00bb au Canada, mais il y en a plus en Angleterre et aux \u00c9tats-Unis, aux Pays-Bas et en Am\u00e9rique du Sud. Donc, lorsqu\u2019elle dit aux gens qu\u2019elle est une \u00ab psychologue de l\u2019environnement \u00bb, ceux-ci savent souvent ce qu\u2019elle veut dire. \u00ab Certaines personnes, \u00e0 juste titre, divisent la dimension de la psychologie de l\u2019architecture et la dimension de la psychologie de l\u2019\u00e9cologie. Je le fais aussi si je veux expliquer aux gens ce que j\u2019\u00e9tudie, parce que je suis plut\u00f4t du c\u00f4t\u00e9 de l\u2019architecture. Je travaille avec des ing\u00e9nieurs, des gestionnaires d\u2019installations et des urbanistes, mais j\u2019ai aussi des coll\u00e8gues, comme John, qui s\u2019int\u00e9ressent au lien avec la nature et travaillent avec des personnes qui \u00e9tudient les attitudes et les comportements proenvironnement. L\u2019id\u00e9e de conservation de la nature est devenue tr\u00e8s populaire dans le domaine de la psychologie de l\u2019environnement, sans pour autant prendre le pas sur la dimension architecturale, qui s\u2019int\u00e9resse \u00e0 l\u2019infrastructure des immeubles, etc. En fait, la psychologie de l\u2019environnement a d\u00e9but\u00e9 dans le contexte de l\u2019architecture, mais elle s\u2019est largement \u00e9tendue \u00e0 son autre volet, qui consiste \u00e0 poser aux gens des questions sur leur conscience \u00e9cologique et leur rapport \u00e0 la nature. \u00bb Les deux branches vont de pair. Pensez \u00e0 la tendance \u00e0 construire des b\u00e2timents \u00ab verts \u00bb, avec du chauffage \u00e0 faible consommation d\u2019\u00e9nergie, des panneaux solaires, voire un jardin sur le toit. Selon la Dre McCunn, \u00ab Quand un ing\u00e9nieur me demande : \u201cdevrions-nous concevoir ce b\u00e2timent en tenant compte de la durabilit\u00e9\u201d, il veut en r\u00e9alit\u00e9 savoir \u2013 \u201cles gens vont-ils le remarquer? S\u2019en soucient-ils? Vont-ils apporter des changements \u00e0 leurs comportements \u00e0 l\u2019int\u00e9rieur (et \u00e0 l\u2019ext\u00e9rieur) de l\u2019immeuble pour cette raison?\u201d Je peux les aider \u00e0 \u00e9tudier la mani\u00e8re dont les gens se comportent, travaillent et fonctionnent dans des b\u00e2timents plus (ou moins) durables. J\u2019ai fait une \u00e9tude dans une \u00e9cole d\u2019\u00e9tudes sup\u00e9rieures qui a montr\u00e9 que le fait qu\u2019un immeuble de bureaux soit \u201cvert\u201d ou durable ne signifie pas n\u00e9cessairement que cela permettra de pr\u00e9dire une forte productivit\u00e9 ou une forte satisfaction. Il est important de garder un \u0153il critique sur ce que l\u2019on attend d\u2019une conception durable et sur ce que l\u2019on n\u2019attend pas. \u00bb Pensez \u00e0 des espaces dans lesquels vous vous \u00eates sentis imm\u00e9diatement \u00e0 l\u2019aise avec les personnes qui vous entouraient \u2013 et d\u2019autres o\u00f9 ce n\u2019\u00e9tait pas le cas. Il est possible que ce ne soit pas les personnes pr\u00e9sentes qui en soient la cause, mais la conception de l\u2019espace qui a rendu les interactions plus embarrassantes, ou qui a rendu cette pi\u00e8ce, ce b\u00e2timent ou ce wagon plus confortable. La Dre McClunn pr\u00e9cise. \u00ab Si l\u2019on veut qu\u2019un certain espace soit accueillant et confortable, on peut le concevoir pour qu\u2019un certain nombre de personnes puissent s\u2019y asseoir \u00e0 une certaine distance. Je pense \u00e0 la conception d\u2019un caf\u00e9, ou un restaurant ou m\u00eame une salle de classe o\u00f9 l\u2019on veut que les gens s\u2019assoient d\u2019une certaine fa\u00e7on et cohabitent d\u2019une certaine mani\u00e8re. Je pense qu\u2019il est important d\u2019utiliser diff\u00e9rentes m\u00e9thodes, tout comme les autres psychologues le font. Nous sommes capables d\u2019int\u00e9grer une vari\u00e9t\u00e9 de m\u00e9thodes combin\u00e9es dans notre travail. Nous utilisons l\u2019observation naturaliste pour observer et voir comment les gens se d\u00e9placent et se comportent dans un espace afin de prendre des d\u00e9cisions de conception \u00e0 partir de nos observations. Nous effectuons beaucoup de sondages et d\u2019entrevues et, \u00e0 partir de ceux-ci, nous pouvons aider les architectes et les concepteurs \u00e0 rendre les b\u00e2timents les plus humains possible. Si l\u2019objet du travail clinique et d\u2019autres types d\u2019intervention psychologique est d\u2019aider les gens \u00e0 se sentir bien, alors la psychologie de l\u2019environnement est tout \u00e0 fait en phase avec cela. Nous voulons que les b\u00e2timents soient con\u00e7us de mani\u00e8re \u00e0 aider les gens \u00e0 se sentir aussi bien, motiv\u00e9s, enthousiastes et en forme que possible. \u00bb Le Dr Zelenski jette \u00e9galement un pont entre les deux c\u00f4t\u00e9s de la psychologie de l\u2019environnement, et ce, de diff\u00e9rentes mani\u00e8res. La collaboration avec des groupes qui font d\u00e9j\u00e0 un travail environnemental lui permet de recueillir plus facilement des donn\u00e9es, et l\u2019analyse de ces donn\u00e9es permet \u00e0 ces groupes de fonctionner de mani\u00e8re plus efficace et efficiente. \u00ab J\u2019ai collabor\u00e9 avec un architecte, faisant ainsi le pont entre ces deux composantes de la psychologie de l\u2019environnement. Il \u00e9tait tr\u00e8s int\u00e9ress\u00e9 par la construction de b\u00e2timents qui donneraient envie aux gens de se comporter de mani\u00e8re \u00e9cologique. De m\u00eame, il ne s\u2019agit peut-\u00eatre pas seulement de l\u2019int\u00e9rieur du b\u00e2timent, mais aussi des espaces naturels proches du b\u00e2timent qui pourraient encourager ces comportements. Il s\u2019agit de poser une question plus nuanc\u00e9e sur les types de milieux naturels \u00e0 proximit\u00e9 qui pourraient aider les gens \u00e0 se sentir mieux, \u00e0 \u00eatre plus heureux et plus productifs. Il y a un petit organisme sans but lucratif qui fournit des trousses d\u2019analyse de l\u2019eau. Il les distribue aux gens, qui les utilisent pour tester la qualit\u00e9 de l\u2019eau \u00e0 proximit\u00e9; les gens t\u00e9l\u00e9chargent ensuite leurs donn\u00e9es dans un genre de base de donn\u00e9es participative qui permet de voir si le lac ou la rivi\u00e8re pr\u00e8s de chez eux est en bon ou en mauvais \u00e9tat, et comment cela \u00e9volue au fil du temps. Il serait difficile pour moi de monter une exp\u00e9rience dans laquelle je distribuerais des tas de trousses d\u2019analyse de l\u2019eau, mais je peux essayer de suivre les personnes qui le font d\u00e9j\u00e0 pour voir si cela change leur sentiment de connexion avec la nature, si cela les rend heureux et si cela leur donne envie de faire d\u2019autres choses bonnes pour l\u2019environnement que de simplement tester l\u2019eau. \u00bb Depuis la mise en place de mesures de confinement en raison de la pand\u00e9mie, nous entendons beaucoup de personnes dire qu\u2019elles appr\u00e9cient davantage la nature. C\u2019est un moyen s\u00fbr de sortir de chez soi. Si on ne peut pas aller dans un centre commercial bond\u00e9 ou \u00e0 un concert, on peut toujours aller dans un parc et se promener. Les gens voient la nature comme une source de bien-\u00eatre et un bon moyen de s\u2019adapter, et certaines \u00e9tudes indiquent que la nature est l\u2019une des choses les plus positives que les gens ont ressenties au cours des deux derni\u00e8res ann\u00e9es, o\u00f9 la distanciation physique \u00e9tait impos\u00e9e. Mais ce lien avec la nature, ainsi que la prise de conscience de la grave menace que repr\u00e9sente le changement climatique, cr\u00e9e \u00e0 certains \u00e9gards de nouveaux probl\u00e8mes. Selon le Dr Zelenski, \u00ab Beaucoup de gens parlent d\u2019\u00e9coanxi\u00e9t\u00e9 et le fait que les gens soient de plus en plus conscients des changements climatiques pourrait \u00eatre une arme \u00e0 double tranchant. Cela peut donc \u00eatre motivant \u2013 ce qui est un r\u00e9sultat positif, les gens voulant se comporter d\u2019une mani\u00e8re plus \u00e9cologique \u2013 mais certaines personnes pourraient \u00eatre boulevers\u00e9es ou inqui\u00e8tes \u00e0 tel point que cela cr\u00e9era de nouvelles formes de stress et d\u2019inqui\u00e9tude qui, chez elles, peuvent \u00eatre inadapt\u00e9es. \u00bb L\u2019un des moyens de lutter contre l\u2019\u00e9coanxi\u00e9t\u00e9, un nouveau mot \u00e0 la mode dans le domaine de la pr\u00e9servation de l\u2019environnement, consiste \u00e0 faire conna\u00eetre les psychologues de l\u2019environnement et \u00e0 solliciter leurs conseils. Cette sensibilisation accrue se ressent \u00e9galement dans la dimension architecturale, car les contributions des experts de ce domaine sont maintenant per\u00e7ues par beaucoup comme \u00e9tant inestimables. La Dre McCunn dit qu\u2019elle a vu ce changement directement. \u00ab Lorsque je rencontre des ing\u00e9nieurs, des architectes et des urbanistes, je constate qu\u2019ils sont davantage sensibili\u00e9s \u00e0 la psychologie de l\u2019environnement et qu\u2019ils sont tout \u00e0 fait dispos\u00e9s \u00e0 travailler avec nous. Lorsque je faisais ma ma\u00eetrise, j\u2019ai remarqu\u00e9 que tr\u00e8s peu de personnes occupant ces postes voulaient travailler avec un sp\u00e9cialiste en sciences sociales. Plusieurs d\u2019entre eux disaient qu\u2019ils faisaient ce genre de recherche accessoirement, et qu\u2019ils \u201csavaient d\u00e9j\u00e0 comment \u00e9tudier les gens\u201d. Aujourd\u2019hui, ils font appel \u00e0 moi car ils veulent int\u00e9grer cette dimension professionnelle \u00e0 leur activit\u00e9 ou \u00e0 leurs processus. La cognition spatiale, par exemple, est un sujet tr\u00e8s habituel en psychologie de l\u2019environnement. Je pense qu\u2019il est important de le mentionner car la population vieillit. Les psychologues de l\u2019environnement consultent souvent les concepteurs pour savoir comment aider les personnes atteintes de d\u00e9mence \u00e0 s\u2019orienter dans une maison de soins, par exemple. Nous pouvons les observer et les aider avec des pancartes et des symboles, et des moyens d\u2019int\u00e9grer leur psychologie dans la conception pour leur faciliter la vie. \u00bb \u00cates-vous d\u00e9j\u00e0 all\u00e9 dans un magasin o\u00f9 il y a, sur le sol, un motif tr\u00e8s simple qui se transforme un peu \u00e0 l\u2019approche des toilettes, et un peu plus pr\u00e8s de la caisse? Peut-\u00eatre y a-t-il des rampes d\u2019escalier de couleur vive le long des murs, et le si\u00e8ge des toilettes est-il d\u2019une couleur nettement diff\u00e9rente du reste des toilettes. Le magasin est bien \u00e9clair\u00e9, mais pas trop, car il y a peu de surfaces r\u00e9fl\u00e9chissantes et pas de miroirs. Un magasin qui ressemble \u00e0 \u00e7a a probablement \u00e9t\u00e9 con\u00e7u pour \u00eatre accessible aux personnes atteintes de d\u00e9mence, avec l\u2019aide de psychologues de l\u2019environnement. Les personnes atteintes de la maladie d\u2019Alzheimer et de diff\u00e9rents types de d\u00e9mence sont g\u00e9n\u00e9ralement suivies par une \u00e9quipe de soins, notamment par un neuroscientifique (voir le portrait de la neuropsychologie clinique pr\u00e9sent\u00e9 plus t\u00f4t ce mois-ci). De plus en plus, les psychologues de l\u2019environnement travaillent au sein d\u2019\u00e9quipes interdisciplinaires plus larges, et les neurosciences elles-m\u00eames prennent une place plus importante dans la discipline. La Dre McCunn dit qu\u2019elle le constate gr\u00e2ce aux articles propos\u00e9s au Journal of Environmental Psychology. \u00ab Il y a beaucoup d\u2019articles qui fusionnent les neurosciences et la psychologie de l\u2019environnement. Je fais aussi cela dans mon propre travail \u2013 j\u2019ai presque termin\u00e9 une deuxi\u00e8me ma\u00eetrise en neurosciences appliqu\u00e9es, simplement pour approfondir mes recherches dans le domaine des neurosciences environnementales. J\u2019aime chercher \u00e0 comprendre des concepts tels que \u201cque se passe-t-il dans le cerveau lorsque nous ressentons un attachement \u00e0 un lieu? Est-ce diff\u00e9rent de l\u2019attachement que l\u2019on ressent face \u00e0 une personne? Que se passe-t-il dans le cerveau lorsque nous rencontrons diff\u00e9rents contextes?\u201d Ce sont des questions importantes qui, je pense, sont de plus en plus populaires. \u00bb La psychologie de l\u2019environnement devenant une discipline de plus en plus demand\u00e9e, l\u2019expertise des personnes travaillant dans ce domaine est appliqu\u00e9e \u00e0 une vari\u00e9t\u00e9 de sujets sans cesse croissante. La Dre McCunn esp\u00e8re que cette tendance se poursuivra, afin que l\u2019ensemble des comp\u00e9tences de ses coll\u00e8gues puisse \u00eatre utilis\u00e9 pour aider \u00e0 r\u00e9soudre des probl\u00e8mes importants. \u00ab Je souhaite que la psychologie de l\u2019environnement fasse partie d\u2019un grand nombre d\u2019\u00e9quipes tr\u00e8s diverses. Bien s\u00fbr, les architectes et les urbanistes, mais aussi les cliniciens, les m\u00e9decins, les neuroscientifiques, etc. Je crois que nous sommes de bons partenaires et nous pouvons ajouter des facettes aux questions de recherche qui peuvent enrichir une r\u00e9ponse et la rendre plus compl\u00e8te. Il est tr\u00e8s difficile de tirer des conclusions \u00e0 partir de quelques variables seulement. La mobilisation des donn\u00e9es et de la mod\u00e9lisation dans le domaine de la psychologie de l\u2019environnement peut nous aider \u00e0 aider les autres \u00e0 obtenir des r\u00e9ponses plus fiables \u00e0 de vastes questions de soci\u00e9t\u00e9 sur ce qui pousse les gens \u00e0 agir et \u00e0 penser de telle ou telle mani\u00e8re. J\u2019aimerais voir la psychologie de l\u2019environnement mettre \u00e0 contribution son expertise dans toutes sortes de contextes et dans toutes sortes d\u2019\u00e9quipes. \u00bb Mais soyez rassur\u00e9 \u2013 si un psychologue de l\u2019environnement se retrouve chez vous, il ne jugera pas la disposition de votre argenterie ni l\u2019endroit o\u00f9 vous avez plac\u00e9 votre sauci\u00e8re, \u00e0 c\u00f4t\u00e9 du pot de Nutella. Du moins, pas plus que n\u2019importe qui d\u2019autre.","twitter:creator":"@CPA_SCP","twitter:image":"https:\/\/cpa.ca\/wp-content\/uploads\/2023\/05\/android-chrome-512x512-onwhite.png"},"aioseo_meta_data":{"post_id":"28033","title":"#post_title #separator_sa #site_title","description":"#post_excerpt","keywords":[],"keyphrases":{"focus":{"keyphrase":"","score":0,"analysis":{"keyphraseInTitle":{"score":0,"maxScore":9,"error":1}}},"additional":[]},"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":"","og_custom_url":null,"og_article_section":null,"og_article_tags":[],"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[],"defaultGraph":"Article","defaultPostTypeGraph":""},"schema_type":"default","schema_type_options":"{\"article\":{\"articleType\":\"BlogPosting\"},\"course\":{\"name\":\"\",\"description\":\"\",\"provider\":\"\"},\"faq\":{\"pages\":[]},\"product\":{\"reviews\":[]},\"recipe\":{\"ingredients\":[],\"instructions\":[],\"keywords\":[]},\"software\":{\"reviews\":[],\"operatingSystems\":[]},\"webPage\":{\"webPageType\":\"WebPage\"}}","pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":"-1","robots_max_videopreview":"-1","robots_max_imagepreview":"large","priority":null,"frequency":"default","local_seo":null,"breadcrumb_settings":null,"limit_modified_date":false,"ai":null,"created":"2022-02-23 14:50:02","updated":"2025-06-27 00:23:12","seo_analyzer_scan_date":null},"publishpress_future_action":{"enabled":false,"date":"2026-08-25 22:17:17","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/cpa.ca\/fr\/wp-json\/wp\/v2\/posts\/28033","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cpa.ca\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/cpa.ca\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/cpa.ca\/fr\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/cpa.ca\/fr\/wp-json\/wp\/v2\/comments?post=28033"}],"version-history":[{"count":6,"href":"https:\/\/cpa.ca\/fr\/wp-json\/wp\/v2\/posts\/28033\/revisions"}],"predecessor-version":[{"id":28450,"href":"https:\/\/cpa.ca\/fr\/wp-json\/wp\/v2\/posts\/28033\/revisions\/28450"}],"wp:attachment":[{"href":"https:\/\/cpa.ca\/fr\/wp-json\/wp\/v2\/media?parent=28033"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/cpa.ca\/fr\/wp-json\/wp\/v2\/categories?post=28033"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/cpa.ca\/fr\/wp-json\/wp\/v2\/tags?post=28033"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}